{"id":40906,"date":"2016-01-21T11:03:22","date_gmt":"2016-01-21T11:03:22","guid":{"rendered":"http:\/\/www.ccdrc.pt\/?p=40906"},"modified":"2023-10-26T13:34:10","modified_gmt":"2023-10-26T13:34:10","slug":"acordao-949-2015-do-tribunal-constitucional-e-acep-celebrado-entre-o-municipio-de-e-o-stal-eficacia","status":"publish","type":"post","link":"https:\/\/www.ccdrc.pt\/pt\/acordao-949-2015-do-tribunal-constitucional-e-acep-celebrado-entre-o-municipio-de-e-o-stal-eficacia\/","title":{"rendered":"Ac\u00f3rd\u00e3o 949\/2015 do Tribunal Constitucional e ACEP celebrado entre o munic\u00edpio de &#8230; e o STAL; efic\u00e1cia."},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1288px;margin-left: calc(-0% \/ 2 );margin-right: calc(-0% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:0%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:0%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:0%;--awb-spacing-left-medium:0%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:0%;--awb-spacing-left-small:0%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><div class=\"searchbox\">\n<div class=\"value\">Data:&nbsp;&nbsp;<strong>quinta, 21 janeiro 2016<\/strong><\/div>\n<div class=\"value\">N\u00famero:&nbsp;<strong>DSAJAL 21\/16<\/strong><\/div>\n<div class=\"value\">Respons\u00e1veis:&nbsp;&nbsp;<strong>Ricardo Ant\u00f3nio Vieira Veiga Ferr\u00e3o<\/strong><\/div>\n<\/div>\n<div class=\"article_content\">\n<div class=\"fulltext\">\n<p>&nbsp;<\/p>\n<p>Solicita a Presidente da C\u00e2mara Municipal da &#8230;, por seu of\u00edcio de &#8230;, refer\u00eancia n.\u00ba 3928\/ano 2015, a emiss\u00e3o de parecer sobre a<\/p>\n<p>\u2026 viabilidade de proceder ao pagamento, aos trabalhadores do Munic\u00edpio, do montante correspondente a uma hora nos dias em que efetivamente prestaram servi\u00e7o entre 09\/12\/2014 e 15\/11\/2015, retirando todas as aus\u00eancias (faltas e f\u00e9rias), conforme entendimento veiculado no Parecer Jur\u00eddico que se anexa.<br \/>\nSolicita-se ainda, se dignem pronunciar-se sobre a aplicabilidade de tal direito respetivamente aos chefes de divis\u00e3o, aos eleitos locais e aos secret\u00e1rios dos gabinetes de apoio aos referidos eleitos.<br \/>\nA acompanhar o oficio, uma informa\u00e7\u00e3o subscrita pela Chefe de Divis\u00e3o de Desenvolvimento Organizacional da C\u00e2mara Municipal bem como um conjunto de documenta\u00e7\u00e3o v\u00e1ria, nela citada, atinente \u00e0 outorga de um acordo colectivo de empregador p\u00fablico entre a edilidade e sindicato representativo de trabalhadores do munic\u00edpio. Porque a quest\u00e3o ora em causa se encontra explanada na informa\u00e7\u00e3o, transcreve-se a mesma:<br \/>\nRelativamente \u00e0 informa\u00e7\u00e3o solicitada por V. Ex.\u00aa no que concerne \u00e0 possibilidade legal de proceder ao pagamento do montante correspondente a uma hora di\u00e1ria aos trabalhadores desta C\u00e2mara Municipal, por for\u00e7a do ACEP- Acordo Coletivo de Empregador P\u00fablico, celebrado em 20\/11\/2014, entre esta Autarquia e o STAL &#8211; Sindicato Nacional dos Trabalhadores da Administra\u00e7\u00e3o Local e Regional, Empresas P\u00fablicas, Concession\u00e1rias e Afins, conjugado com a declara\u00e7\u00e3o de inconstitucionalidade \u00ednsita no Ac\u00f3rd\u00e3o n.\u00ba 494\/2015<sup>1<\/sup>&nbsp;do Tribunal Constitucional, publicado na 2\u00aa S\u00e9rie do Di\u00e1rio da Republica, n\u00ba 220, de 10 de novembro de 2014, informa-se o seguinte:<br \/>\nNo passado dia 7 de outubro, o Tribunal Constitucional declarou inconstitucionais as &#8220;normas que conferem aos membros do Governo respons\u00e1veis pelas \u00e1reas das finan\u00e7as e da administra\u00e7\u00e3o p\u00fablica legitimidade para celebrar e assinar acordos coletivos de empregador p\u00fablico, no \u00e2mbito da administra\u00e7\u00e3o aut\u00e1rquica<sup>3<\/sup>&nbsp;(&#8230;) por viola\u00e7\u00e3o do princ\u00edpio da autonomia local, consagrado no artigo 6.\u00ba, n.\u00ba 1, da Constitui\u00e7\u00e3o&#8221;.<br \/>\nEsta decis\u00e3o, que se soma a outras dos Tribunais Administrativos veio, em definitivo, dar raz\u00e3o \u00e0 oposi\u00e7\u00e3o que as autarquias, os seus trabalhadores e respetivas associa\u00e7\u00f5es sindicais vinham travando contra a inger\u00eancia do Governo na autonomia das autarquias locais. Ao longo destes dois anos, muitas autarquias, trabalhadores e sindicatos resistiram \u00e1 inaceit\u00e1vel press\u00e3o do governo para que, em troca das trinta e cinco horas, fossem introduzidos bancos de horas e regimes de adaptabilidade.<br \/>\nO Munic\u00edpio de &#8230; assumiu, desde a primeira hora, o seu papel na defesa das trinta e cinco horas semanais como direito dos seus trabalhadores e da autonomia do Poder Local.<br \/>\nNo entanto, mesmo suspeitando da inconstitucionalidade da norma que foi objeto de controlo sucessivo pelo Tribunal Constitucional, a que se reporta o supramencionado Ac\u00f3rd\u00e3o, esta autarquia sempre acatou e cumpriu escrupulosamente os ditames legais, como de resto era sua obriga\u00e7\u00e3o.<br \/>\nAssim antes de celebrar o ACEP- Acordo Coletivo de Empregador P\u00fablico solicitou, oportunamente, a compar\u00eancia do Senhor Secret\u00e1rio de Estado da Administra\u00e7\u00e3o Publica nesta autarquia para efeitos da assinatura do ACEP ou a indica\u00e7\u00e3o de uma data alternativa que melhor lhe conviesse em termos de agenda tendo-lhe sido remetido inclusivamente, a minuta de tal documento para efeitos de aprecia\u00e7\u00e3o e apresenta\u00e7\u00e3o de eventuais altera\u00e7\u00f5es que considerassem pertinentes.<br \/>\nContudo, Suas Excel\u00eancias n\u00e3o compareceram, n\u00e3o se fizeram representar, nem t\u00e3o pouco enviaram qualquer sugest\u00e3o de altera\u00e7\u00e3o, optando por se remeterem ao sil\u00eancio (DOC.1).<br \/>\nFoi ent\u00e3o celebrado o ACEP entre as entidades que compareceram na data previamente agendada para a sua assinatura (Presidente da C\u00e2mara e STAL) e de imediato remetido tal documento ao Senhor Secret\u00e1rio de Estado das Finan\u00e7as e Administra\u00e7\u00e3o P\u00fablica para os efeitos previstos no n.\u00ba 6 do Art.\u00ba 364.\u00ba do Anexo \u00e0 Lei 35\/2014, de 26 de junho, o mesmo \u00e9 dizer, para efeitos da sua assinatura, uma vez que n\u00e3o se verificou a necessidade de introduzir qualquer altera\u00e7\u00e3o formal ou substancial. Solicit\u00e1mos ainda o seu dep\u00f3sito na DGAEP, em cumprimento do estipulado no art.\u00ba 368.\u00ba do Anexo \u00e0 Lei no 35\/2014, de 20 de junho, para que esta o remetesse para publica\u00e7\u00e3o, ou em alternativa, se assim o entendessem, a sua devolu\u00e7\u00e3o depois de devidamente assinado para que os servi\u00e7os desta autarquia promovessem o seu dep\u00f3sito na DGAEP e esta a sua publica\u00e7\u00e3o (DOC.2).<br \/>\nDecorridos alguns meses, mais concretamente em 02 de mar\u00e7o do ano em curso, fomos surpreendidos por um of\u00edcio da Secretaria de Estado da Administra\u00e7\u00e3o P\u00fablica com um teor algo ins\u00f3lito, uma vez que, vinha completamente a destempo, exigir, sob pena de n\u00e3o o assinarem, que o ACEP contemplasse, um conjunto de fatores de pondera\u00e7\u00e3o, criados em abstrato e completamente desarrazoados face \u00e0 realidade dos servi\u00e7os desta autarquia (DOC.3).<br \/>\nAs entidades signat\u00e1rias de tal Acordo n\u00e3o aceitaram, nem poderiam aceitar, as condi\u00e7\u00f5es impostas pelo Senhor Secret\u00e1rio de Estado uma vez que, para al\u00e9m de extempor\u00e2neas, eram inaceit\u00e1veis e totalmente antag\u00f3nicas \u00e0 realidade dos servi\u00e7os da c\u00e2mara Municipal de &#8230; e arrostavam os princ\u00edpios democr\u00e1ticos que, na opini\u00e3o da autarquia, deveriam presidir \u00e0 celebra\u00e7\u00e3o do ACEP. Dessa posi\u00e7\u00e3o deram conhecimento imediato ao Senhor Secret\u00e1rio de Estado.<br \/>\nDepois disso a Secretaria de Estado remeteu-se ao sil\u00eancio e nada mais fez, nem disse.<br \/>\nQuando o Tribunal Constitucional proferiu o Ac\u00f3rd\u00e3o em refer\u00eancia, esta autarquia solicitou de imediato (19\/10\/20015) ao senhor secret\u00e1rio de Estado que, como imperativo de justi\u00e7a e por forma de sustar os danos causados aos trabalhadores desta autarquia, sem mais delongas e mesmo antes da publica\u00e7\u00e3o em Di\u00e1rio da Rep\u00fablica do supra referido Ac\u00f3rd\u00e3o do Tribunal Constitucional, procede-se ao reenvio do dito ACEP \u00e0 Dire\u00e7\u00e3o Geral do Emprego e Administra\u00e7\u00e3o P\u00fablica para efeitos de dep\u00f3sito e promo\u00e7\u00e3o da respetiva publica\u00e7\u00e3o na 2.\u00aa S\u00e9rie do Di\u00e1rio da Republica.<br \/>\nFoi ainda solicitado ao Senhor Secret\u00e1rio de Estado que, caso assim n\u00e3o o entendesse procedesse, sem mais protela\u00e7\u00e3o, \u00e0 devolu\u00e7\u00e3o do mencionado ACEP \u00e0 c\u00e2mara Municipal para que esta promovesse o seu dep\u00f3sito e respetiva publica\u00e7\u00e3o, agora em obedi\u00eancia e por imposi\u00e7\u00e3o do Ac\u00f3rd\u00e3o do Tribunal Constitucional supra referido, a qual enquanto \u201cpessoa de bem&#8221; poderia e deveria, expurgar de imediato de tal processo, os obst\u00e1culos que inevitavelmente acabariam por sucumbir aquando da publica\u00e7\u00e3o de tal Ac\u00f3rd\u00e3o do Tribunal constitucional. (DOC.4)<br \/>\nOra, o Senhor Secret\u00e1rio de Estado, mais uma vez nada fez e esperou pela publica\u00e7\u00e3o do Ac\u00f3rd\u00e3o do Tribunal Constitucional (em 22\/10\/2015) para devolver o dito ACEP \u00e0 C\u00e2mara Municipal de &#8230; (DOC.5), que posteriormente o remeteu \u00e0 DGAEP para dep\u00f3sito e publica\u00e7\u00e3o.<br \/>\nTal publica\u00e7\u00e3o veio finalmente a acontecer em 10 de novembro de 2015, quase um ano depois da sua celebra\u00e7\u00e3o que, repita-se, aconteceu em 20 de novembro de 2014, conforme consta da dita publica\u00e7\u00e3o.<br \/>\nAcontece que, logo ap\u00f3s a entrada em vigor do AGEP em apre\u00e7o (16\/11\/2015) muitos trabalhadores e sindicato subscritor do ACEP vieram solicitar o pagamento de uma hora referente aos dias em que trabalharam oito horas, no per\u00edodo que mediou entre a assinatura do ACEP e a sua entrada em vigor, isto \u00e9, entre 20\/11\/2014 e 16\/11\/2015.<br \/>\nA quest\u00e3o jur\u00eddica subjacente \u00e0 situa\u00e7\u00e3o concreta colocada a V.\u00aa Ex.\u00aa traduz-se na pr\u00e1tica, em saber se os efeitos da declara\u00e7\u00e3o de inconstitucionalidade com for\u00e7a obrigat\u00f3ria geral expressa no Ac\u00f3rd\u00e3o do Tribunal Constitucional n.\u00ba 949\/2015, publicado na 2.\u00aa S\u00e9rie do Di\u00e1rio da Republica n.\u00ba 207 de 22 de outubro de 2015, poder\u00e3o fazer retroagir a data de entrada em vigor do AGEP-Acordo Coletivo de Empregador P\u00fablico.<br \/>\nOra, com este ac\u00f3rd\u00e3o o \u201cTribunal Constitucional declara a inconstitucionalidade com for\u00e7a obrigat\u00f3ria geral, das normas que conferem aos membros do Governo respons\u00e1veis pelas \u00e1reas das finan\u00e7as e da administra\u00e7\u00e3o p\u00fablica legitimidade para celebrar e assinar acordos coletivos de empregador p\u00fabico, no \u00e2mbito da administra\u00e7\u00e3o aut\u00e1rquica, resultantes do artigo 364.\u00ba, n.\u00ba 3, al\u00ednea b), e do n.\u00ba 6, do da Lei Geral do Trabalho em Fun\u00e7\u00f5es P\u00fablicas, aprovada em anexo \u00e0 Lei 35\/2014, de 20 de junho, por viola\u00e7\u00e3o do princ\u00edpio da autonomia local, consagrado no artigo 6.\u00ba, n.\u00ba 7, da Constitui\u00e7\u00e3o.\u201d<br \/>\nA declara\u00e7\u00e3o de inconstitucionalidade com for\u00e7a obrigat\u00f3ria geral, no que se refere a normas constantes de diplomas j\u00e1 em vigor &#8211; como \u00e9 o caso, pois a Lei Geral do Trabalho em Fun\u00e7\u00f5es P\u00fablicas (LTFP), aprovada em anexo \u00e0 Lei 3512014, de 20 de junho, entrou em vigor em 01\/08\/2014 &#8211; produz efeitos desde a entrada em vigor da norma declarada inconstitucional ou ilegal e determina a reposi\u00e7\u00e3o das normas que eventualmente hajam sido revogadas por aquela declara\u00e7\u00e3o.<br \/>\nDestarte, a declara\u00e7\u00e3o de inconstitucionalidade dos referidos dispositivos legais produz efeitos ex tunc, isto \u00e9, a norma deixou de existir no ordenamento jur\u00eddico e n\u00e3o produz efeitos \u2013 inconstitucionalidade origin\u00e1ria \u2013 desde a sua entrada em vigor em 01\/08\/2014.<br \/>\nNestes termos e reportando-nos ao caso concreto, o ACEP celebrado a 20\/11\/2014 previa no n.\u00ba 1 da sua cl\u00e1usula 2.\u00aa o seguinte (e passamos a citar): &#8220;entra em vigor cinco dias ap\u00f3s a sua publica\u00e7\u00e3o na 2.\u00aa s\u00e9rie do Di\u00e1rio da Rep\u00fablica e vigora pelo prazo de dois anos\u201d. A esta luz, explica-se pois a insist\u00eancia desta autarquia para que os membros do Governo assinassem e procedessem ao dep\u00f3sito do referido ACEP na DGAEP, em conformidade com o disposto no Artigo 368\u00ba da LTFP, para que esta promovesse a respetiva publica\u00e7\u00e3o. Mas os membros do governo n\u00e3o assinaram, n\u00e3o devolveram nem promoveram a publica\u00e7\u00e3o do ACEP (apesar da versada prem\u00eancia por parte da autarquia, como supra demonstrado).<br \/>\nConsidera-se pois que para que se alcance efetivamente o efeito &#8220;for\u00e7a obrigat\u00f3ria geral\u201d, exarado no Ac\u00f3rd\u00e3o do Tribunal Constitucional supra referido, teremos que proceder \u00e0 reconstitui\u00e7\u00e3o da situa\u00e7\u00e3o de facto, expurgando do procedimento que envolveu a celebra\u00e7\u00e3o do ACEP, as normas que conferiam aos membros do Governo respons\u00e1veis pelas \u00e1reas das finan\u00e7as e da administra\u00e7\u00e3o p\u00fablica legitimidade para celebrar e assinar acordos coletivos de empregador p\u00fablico, no \u00e2mbito da administra\u00e7\u00e3o aut\u00e1rquica, agora declaradas inconstitucionais &#8211; artigo 364.\u00ba n.\u00ba 3, al. b) e do n.\u00ba 6 da Lei Geral do Trabalho em Fun\u00e7\u00f5es P\u00fablicas, aprovada em anexo \u00e0 Lei 35\/2014, de 20 de junho. Deste modo seremos reconduzidos ao dia 20 de novembro de 2014 (data da assinatura do ACEP) e nesse sentido remeter\u00edamos tal documento, n\u00e3o aos membros do Governo, mas sim \u00e0 DGAEP para efeitos de dep\u00f3sito e consequente publica\u00e7\u00e3o (em conformidade com o disposto no Artigo 368\u00ba da LTFP).<br \/>\nPor conseguinte e aventando que a DGAEP tivesse promovido a publica\u00e7\u00e3o do ACEP com a mesma dilig\u00eancia, ent\u00e3o o mesmo teria sido publicado a 03\/12\/2014 (dezasseis dias depois do envio do ACEP pela c\u00e2mara Municipal \u00e0 DGAEP para promo\u00e7\u00e3o da publica\u00e7\u00e3o na 2.\u00aa S\u00e9rie do Di\u00e1rio da Rep\u00fablica) e entraria em vigor no dia 09\/12\/2014 (cinco dias ap\u00f3s a publica\u00e7\u00e3o). Isto, repita se, tendo por base o mesmo hiato de tempo que decorreu entre o envio do ACEP pela C\u00e2mara Municipal \u00e0 DGAEP (em 26\/10\/2015 &#8211; DOC. 6) e a respetiva publica\u00e7\u00e3o (em 10\/11\/2015) \u2013 dezasseis dias \u2013 se a estes acrescentarmos os cinco dias ap\u00f3s a data da publica\u00e7\u00e3o previstos no ACEP, temos que o mesmo entrou em vigor, como \u00e9 sabido, no pret\u00e9rito dia 16\/11\/2015.<br \/>\nTendo em conta o excurso verifica-se que os trabalhadores desta autarquia, no per\u00edodo que decorreu entre 09\/12\/2014 e 15\/11\/2015, prestaram ao Munic\u00edpio de &#8230; nos dias em que efetivamente trabalharam (retirando faltas e f\u00e9rias), mais uma hora de trabalho di\u00e1rio do que aquele que lhes seria exig\u00edvel, e por isso t\u00eam direito a ser ressarcidos dessa hora de trabalho por for\u00e7a da decis\u00e3o do Tribunal Constitucional proferida no seu douto Ac\u00f3rd\u00e3o n\u00ba 94912015, com efeitos ex tunc.<br \/>\nObviamente que o Munic\u00edpio de &#8230;, na pessoa da Senhora Presidente da C\u00e2mara, envidou todos os esfor\u00e7os para que o ACEP tivesse sido publicado com a maior brevidade ap\u00f3s a sua assinatura em 20\/11\/2014, conforme se demonstra peros correspond\u00eancia enviada ao senhor Secret\u00e1rio de Estado das Finan\u00e7as e da Administra\u00e7\u00e3o p\u00fabrica, mas sem qualquer \u00eaxito face a conduta demonstrada por aquele representante do Governo.<br \/>\nMas, tamb\u00e9m \u00e9 certo, que o benefici\u00e1rio do trabalho \u201cindevido\u201d foi o Munic\u00edpio de &#8230; e \u00e9 este que, em primeira linha deveria responder perante os trabalhadores&#8217; sem preju\u00edzo de usar dos mecanismos legais ao seu dispor para demandar a eventual responsabilidade do Estado Portugu\u00eas neste processo.<br \/>\nMais se informa que em termos or\u00e7amentais e no que tange \u00e0s restri\u00e7\u00f5es das despesas com pessoal, impostas pelo or\u00e7amento de Estado de 2015, conforme constada informa\u00e7\u00e3o do chefe de Divis\u00e3o Financeira que se anexa, e como de resto \u00e9 do conhecimento de V. Ex\u00aa. a C\u00e2mara Municipal de &#8230; pode proceder ao pagamento de tal despesa, sem colocar em causa as restri\u00e7\u00f5es decorrentes da Lei do Or\u00e7amento de Estado de 2015.<br \/>\nEm face do exposto e por forma a respeitar cabalmente a decis\u00e3o do Tribunal Constitucional parece-me, sem preju\u00edzo de melhor opini\u00e3o, que a senhora Presidente da C\u00e2mara Municipal poder\u00e1, como de resto \u00e9 sua vontade e por forma a ressarcir os trabalhadores dos danos sofridos, pagar aos seus trabalhadores o montante correspondente a uma hora nos dias em que efetivamente prestaram servi\u00e7o entre 09\/12\/2014 e 15\/11\/2015, retirando todas as aus\u00eancias (faltas e f\u00e9rias), conforme se apurou e consta do quadro anexo.<\/p>\n<p>APRECIANDO<br \/>\n1. DO PEDIDO<br \/>\nPretende a C\u00e2mara Municipal consulente saber da viabilidade \u2013 que se presume ser a viabilidade jur\u00eddica, ou seja, a sua admissibilidade legal ou legalidade \u2013 de proceder ao pagamento, aos trabalhadores do Munic\u00edpio, do montante correspondente a uma hora nos dias em que efetivamente prestaram servi\u00e7o entre 09\/12\/2014 \u2013 momento em que foi celebrado entre o munic\u00edpio e um sindicato um ACEP prevendo a redu\u00e7\u00e3o do per\u00edodo normal de trabalho de 40 para 35 horas \u2013 e 15\/11\/2015 \u2013 data considerada como de inicio de vig\u00eancia do ACEP, de acordo com o previsto no n.\u00ba 1 da sua cl\u00e1usula 2.\u00ba e, consequencialmente, do in\u00edcio da redu\u00e7\u00e3o hor\u00e1ria do per\u00edodo laboral nele prevista \u2013 retirando todas as aus\u00eancias (faltas e f\u00e9rias), apresentando como base fundante para essa vontade de pagamento o entendimento veiculado no Parecer Jur\u00eddico anexo ao peticionante of\u00edcio e transcrito supra.<br \/>\nEsse parecer jur\u00eddico, descontadas as considera\u00e7\u00f5es exorbitantes e os ju\u00edzos ajur\u00eddicos, descabidos num contexto de aprecia\u00e7\u00e3o jur\u00eddica e irrelevantes em sede de an\u00e1lise de direito, parte do detalhado e comentado relato do desenrolar do processo de celebra\u00e7\u00e3o do acordo em quest\u00e3o, para sustentar, \u00e0 face dele, que tendo o Ac\u00f3rd\u00e3o do Tribunal Constitucional n.\u00ba 494\/2015<sup>1<\/sup>&nbsp;declarado a inconstitucionalidade, com for\u00e7a obrigat\u00f3ria geral, das normas que conferem aos membros do Governo respons\u00e1veis pelas \u00e1reas das finan\u00e7as e da administra\u00e7\u00e3o p\u00fablica legitimidade para celebrar e assinar acordos coletivos de empregador p\u00fablico, no \u00e2mbito da administra\u00e7\u00e3o aut\u00e1rquica, normas essas que impediram o desenrolar dos normais tr\u00e2mites e subsequente in\u00edcio de vig\u00eancia do ACEP aquando da sua celebra\u00e7\u00e3o, por via da n\u00e3o interven\u00e7\u00e3o do referido membro do governo, vig\u00eancia essa que s\u00f3 veio a ter inicio, afastada que foi a necessidade legal dessa interven\u00e7\u00e3o (por via do antecitado aresto), ap\u00f3s o cumprimento dos tr\u00e2mites legalmente exigidos para o efeito, caberia ent\u00e3o ter lugar e ser paga aos trabalhadores a hora de trabalho di\u00e1rio a mais que eles ter\u00e3o prestado nesse per\u00edodo de inac\u00e7\u00e3o do ACEP, pois que se por via da efic\u00e1cia ex tunc da declara\u00e7\u00e3o de inconstitucionalidade com for\u00e7a obrigat\u00f3ria geral deveria ser reposta a situa\u00e7\u00e3o f\u00e1ctica laboral num ponto id\u00eantico ao que ocorreria se a interven\u00e7\u00e3o do membro do governo nunca tivesse sido prevista como necess\u00e1ria, o per\u00edodo normal de trabalho teria passado a ser de 35 horas desde o momento do inicio de vig\u00eancia do ACEP, momento esse que deveria ter sido aquele que agora se pode ficcionar, recorrendo como se tivesse ocorrido ent\u00e3o, ao per\u00edodo de tempo que agora foi necess\u00e1rio para, ap\u00f3s a declara\u00e7\u00e3o de inconstitucionalidade, dar cumprimento \u00e0s formalidades necess\u00e1rias, ainda em falta, para que o ACEP pudesse entrar finalmente em vigor.<br \/>\nMais pretende ainda a edilidade saber se, sendo (legalmente) admiss\u00edvel o que antes fica referido, ser\u00e1 tamb\u00e9m poss\u00edvel aplicar id\u00eantico regime e a mesma regalia aos chefes de divis\u00e3o, aos eleitos locais e aos secret\u00e1rios dos gabinetes de apoio aos referidos eleitos \u2013 o que \u00e9 por dizer fazer incluir no \u00e2mbito de aplica\u00e7\u00e3o subjectivo do referido ACEP os titulares de (alguns) cargos dirigentes das autarquias locais, os titulares do poder local e, bem assim, o pessoal de confian\u00e7a pessoal dos gabinetes de apoio.<\/p>\n<p>2. AN\u00c1LISE<br \/>\n2.1. BREVE NOTA SOBRE O QUADRO LEGAL<br \/>\n2.1.1. A Lei Geral do Trabalho em Fun\u00e7\u00f5es P\u00fablicas (LTFP), aprovada em anexo \u00e0 Lei n.\u00ba 35\/2014, de 20 de Junho, veio regula[r] o v\u00ednculo de trabalho em fun\u00e7\u00f5es p\u00fablicas<sup>2<\/sup>, aplicando-se n\u00e3o s\u00f3 \u00e0 administra\u00e7\u00e3o direta e indireta do Estado como tamb\u00e9m, com as necess\u00e1rias adapta\u00e7\u00f5es, designadamente no que respeita \u00e0s compet\u00eancias em mat\u00e9ria administrativa dos correspondentes \u00f3rg\u00e3os de governo pr\u00f3prio, aos servi\u00e7os da administra\u00e7\u00e3o regional e da administra\u00e7\u00e3o aut\u00e1rquica , para al\u00e9m de ser igualmente aplic\u00e1vel a outras entidades e organismos n\u00e3o t\u00edpica e substancialmente administrativos<sup>4<\/sup>. Ao mesmo tempo que aprovava a LTFP, a Lei n.\u00ba 35\/2014 revogava a legisla\u00e7\u00e3o anteriormente aplic\u00e1vel na mat\u00e9ria<sup>5<\/sup>.<br \/>\nExpressamente exclu\u00eddos do \u00e2mbito de aplica\u00e7\u00e3o da LTFP, e portanto fora do per\u00edmetro de aplicabilidade \u201cper si ipsum\u201d do seu regime legal<sup>6<\/sup>, ficam os gabinetes de apoio dos membros do Governo e dos titulares dos \u00f3rg\u00e3os referidos nos n.\u00bas 2 a 4 do artigo (\u2026) segundo<sup>7<\/sup>, as entidades p\u00fablicas empresariais<sup>8<\/sup>&nbsp;e as entidades administrativas independentes com fun\u00e7\u00f5es de regula\u00e7\u00e3o da atividade econ\u00f3mica dos setores privado, p\u00fablico e cooperativo e Banco de Portugal<sup>9<\/sup>&nbsp;.<br \/>\nAssim, de entre os titulares dos \u00f3rg\u00e3os referidos nos n.\u00bas 2 a 4 do artigo 2.\u00ba, cujos gabinetes de apoio \u2013 o que \u00e9 por dizer, cujos trabalhadores desses gabinetes, enquanto nessa qualidade \u2013 ficam exclu\u00eddos do \u00e2mbito de aplica\u00e7\u00e3o da LTFP, encontra-se a administra\u00e7\u00e3o aut\u00e1rquica.<br \/>\nPor outro lado, a LTFP veio estabelecer que o trabalho em fun\u00e7\u00f5es p\u00fablicas pode ser prestado mediante v\u00ednculo de emprego p\u00fablico \u2013 ou seja, mediante o v\u00ednculo pelo qual uma pessoa singular presta a sua atividade a um empregador p\u00fablico, de forma subordinada e mediante remunera\u00e7\u00e3o, nas modalidades de contrato de trabalho em fun\u00e7\u00f5es p\u00fablicas, nomea\u00e7\u00e3o ou comiss\u00e3o de servi\u00e7o<sup>10<\/sup>&nbsp;\u2013 ou contrato de presta\u00e7\u00e3o de servi\u00e7o, nos termos da presente lei<sup>11<\/sup>.<br \/>\n2.1.2. Para al\u00e9m da lei (e dos usos<sup>12<\/sup>, nas condi\u00e7\u00f5es nela fixadas<sup>13<\/sup>), constituem fontes<sup>14<\/sup>&nbsp;(de direito) aut\u00f3nomas ou convencionais<sup>15<\/sup>, espec\u00edficas do contrato de trabalho em fun\u00e7\u00f5es p\u00fablicas, os instrumentos de regulamenta\u00e7\u00e3o colectiva de trabalho<sup>16<\/sup>&nbsp;(IRCT), de entre os quais se encontra o acordo colectivo de empregador p\u00fablico (ACEP)<sup>17<\/sup>, considerado como uma das modalidades de acordo colectivo de trabalho (ao lado do acordo colectivo de carreira) e definido pela lei como a conven\u00e7\u00e3o coletiva aplic\u00e1vel no \u00e2mbito do \u00f3rg\u00e3o ou servi\u00e7o onde o trabalhador exer\u00e7a fun\u00e7\u00f5es<sup>18<\/sup>.<br \/>\nAinda que os IRCT se situem no mesmo patamar de vig\u00eancia, ou seja, inexista uma hierarquia entre eles, certo \u00e9, por\u00e9m, que por via das rela\u00e7\u00f5es de subsidiariedade ou preced\u00eancia entre estes instrumentos, a lei estabelece algumas limita\u00e7\u00f5es quanto \u00e0s mat\u00e9rias sobre as quais pode incidir a sua regula\u00e7\u00e3o, por via do que os acordos colectivos de empregador p\u00fablico apenas pode[m] regular as mat\u00e9rias relativas a seguran\u00e7a e sa\u00fade no trabalho e dura\u00e7\u00e3o e organiza\u00e7\u00e3o do tempo de trabalho, excluindo as respeitantes a suplementos remunerat\u00f3rios sempre que inexista acordo coletivo de carreira ou, caso ele exista, a\u00ed n\u00e3o sejam indicadas as mat\u00e9rias que podem ser reguladas pelos acordos coletivos de empregador p\u00fablico<sup>19<\/sup>.<br \/>\nA celebra\u00e7\u00e3o de um acordo colectivo de trabalho, m\u00e1xime, de um acordo colectivo de empregador p\u00fablico, pressup\u00f5e o cumprimento de um conjunto de passos ou fases sucessivas, formais e procedimentalizadas, nas quais apenas podem participar e ter interven\u00e7\u00e3o as entidades \u00e0s quais a lei atribui legitimidade para o efeito.<br \/>\nAssim, no que toca \u00e0 celebra\u00e7\u00e3o de tais acordos, a LTFP estipula que t\u00eam legitimidade (conjunta) para o efeito, do \u201clado\u201d do empregador p\u00fablico, os membros do Governo respons\u00e1veis pelas \u00e1reas das finan\u00e7as e da Administra\u00e7\u00e3o P\u00fablica, o que superintenda no \u00f3rg\u00e3o ou servi\u00e7o e o empregador p\u00fablico nos termos do artigo 27.\u00ba<sup>20<\/sup>&nbsp;&#8211; ou seja, neste \u00faltimo caso e quanto \u00e0 administra\u00e7\u00e3o aut\u00e1rquica, o presidente da c\u00e2mara municipal, nos munic\u00edpios e a junta de freguesia, nas freguesias<sup>21<\/sup>. Ora, foi precisamente esta legitimidade e capacidade\/poder de interven\u00e7\u00e3o conjunta de membros do governo \u2013 rectius, dos membros do Governo respons\u00e1veis pelas \u00e1reas das finan\u00e7as e da Administra\u00e7\u00e3o P\u00fablica \u2013 na celebra\u00e7\u00e3o e assinatura de acordos colectivos de empregador p\u00fablico no \u00e2mbito das autarquias locais que o Tribunal Constitucional veio declarar inconstitucional, com for\u00e7a obrigat\u00f3ria geral, pelo seu Ac\u00f3rd\u00e3o n.\u00ba 494\/2015, afirmando ao mesmo tempo que essa compet\u00eancia cabe unicamente \u00e0s autarquias locais<sup>22<\/sup>.<br \/>\nContudo, n\u00e3o basta a assinatura do ACEP pelas respectivas partes intervenientes para que o acordo entre imediatamente em vigor. A lei exige ainda a pr\u00e1tica de um conjunto de procedimentos que se pode dizer fazerem parte de uma fase integrativa de efic\u00e1cia e de publicita\u00e7\u00e3o.<br \/>\nAssim, o ACEP carece de ser entregue na DGAEP, para efeitos de dep\u00f3sito (administrativo)<sup>23<\/sup>, nos cinco dias posteriores \u00e0 sua assinatura, dep\u00f3sito esse que fica dependente da pr\u00e9via verifica\u00e7\u00e3o (pela entidade deposit\u00e1ria) do cumprimento dos requisitos elencados no n.\u00ba 4 do artigo 368.\u00ba da LCFP<sup>24<\/sup>. O dep\u00f3sito do ACEP considera-se efectuado se n\u00e3o for fundamentadamente recusado nos 15 dias seguintes \u00e0 data da sua recep\u00e7\u00e3o<sup>25<\/sup>.<br \/>\nPara que o ACEP possa entrar finalmente em vigor, \u00e9 ainda necess\u00e1ria a sua publica\u00e7\u00e3o em Di\u00e1rio da Rep\u00fablica<sup>26<\/sup>, passando a vigorar nos mesmo termos que a lei<sup>27<\/sup>, ou seja, na data nele fixada ou, na falta de tal indica\u00e7\u00e3o, de acordo com a regra supletiva do n.\u00ba 2 do artigo 2.\u00ba da Lei n.\u00ba 74\/98<sup>28<\/sup>.<br \/>\n2.2. O HISTORIAL DO ACEP<br \/>\nDos elementos e documenta\u00e7\u00e3o enviada a quando do pedido de parecer, pode-se extrair que o ACEP de que ora se cuida \u00e9 um dos que foi assinado por um sindicado e uma autarquia local sem interven\u00e7\u00e3o dos membros do Governo respons\u00e1veis pelas \u00e1reas das finan\u00e7as e da Administra\u00e7\u00e3o P\u00fablica, ao arrepio do determinado na al\u00ednea b) do n.\u00ba 3 do artigo 364.\u00ba da LTFP.<br \/>\nAli\u00e1s, tendo-se, ent\u00e3o, suscitado d\u00favidas sobre se deveria\/poderia haver, ou n\u00e3o, lugar \u00e0 interven\u00e7\u00e3o dos referidos membros do governo, na celebra\u00e7\u00e3o e outorga desses ACEP, foi solicitado pelo Governo ao Conselho Consultivo da Procuradoria Geral da Rep\u00fablica a emiss\u00e3o de parecer dilucidando essa quest\u00e3o.<br \/>\nO parecer ent\u00e3o emitido, o Parecer PGR n.\u00ba 9\/2014<sup>29<\/sup>, veiculava o entendimento de que, n\u00e3o obstante durante todo o processo de celebra\u00e7\u00e3o de[sse] acordo coletivo de trabalho, est\u00e1[r] vedada aos membros do Governo referidos a faculdade de dar ordens ou emitir diretivas \u00e0 entidade aut\u00e1rquica por for\u00e7a da autonomia de que esta goza, nos termos da Constitui\u00e7\u00e3o e da lei, tal processo (\u2026.) apela a uma atua\u00e7\u00e3o conjunta e articulada destas entidades durante todas as fases da sua negocia\u00e7\u00e3o.<br \/>\nE prossegue o mesmo Parecer: a legitimidade para a celebra\u00e7\u00e3o de acordos coletivos de trabalho, na modalidade de acordos coletivos de entidade empregadora p\u00fablica, aplic\u00e1veis aos trabalhadores das autarquias locais (\u2026), pertence, pela entidade empregadora, em conjunto, \u00e0s autarquias locais, enquanto entidades empregadoras p\u00fablicas, e aos membros do Governo respons\u00e1veis pelas \u00e1reas das finan\u00e7as e da Administra\u00e7\u00e3o P\u00fablica, como determina o artigo 347.\u00ba, n.\u00ba 3, al\u00ednea b), do RCTFP, (\u2026) solu\u00e7\u00e3o normativa [que] n\u00e3o viola o direito de contrata\u00e7\u00e3o coletiva, nem ofende o princ\u00edpio da autonomia local, consagrados, respetivamente, nos artigos 56.\u00ba, n.\u00ba 3, e 6.\u00ba, n.\u00ba 1, da Constitui\u00e7\u00e3o da Rep\u00fablica.<br \/>\nAssim esclarecidas as d\u00favidas colocadas ao Conselho Consultivo da Procuradoria Geral da Rep\u00fablica<sup>30<\/sup>, a doutrina veiculada no referido Parecer, devidamente homologado, passou a constituir o entendimento a observar e a seguir pelo Secret\u00e1rio de Estado da Administra\u00e7\u00e3o P\u00fablica e servi\u00e7os da administra\u00e7\u00e3o, como n\u00e3o podia deixar de ser<sup>31<\/sup>.<br \/>\nN\u00e3o obstante a publicidade dada ao Parecer e ao sentido de quanto nele era sustentado, a C\u00e2mara Municipal consulente prosseguiu no processo de celebra\u00e7\u00e3o do acordo, oficiando ao Secret\u00e1rio de Estado da Administra\u00e7\u00e3o P\u00fablica e ao Secret\u00e1rio de Estado das Finan\u00e7as instando-os<sup>32&nbsp;<\/sup>a estarem presentes na assinatura do referido ACEP, na aus\u00eancia dos quais o assinou conjuntamente com o sindicato.<br \/>\nAp\u00f3s a outorga com o sindicato, a c\u00e2mara municipal enviou o ACEP para assinatura, aos Secret\u00e1rios de Estado da Administra\u00e7\u00e3o P\u00fablica e das Finan\u00e7as<sup>33<\/sup>, nunca tendo este merecido assinatura governamental e acabando devolvido \u00e0 C\u00e2mara Municipal ap\u00f3s a publica\u00e7\u00e3o em Di\u00e1rio da Rep\u00fablica do Ac\u00f3rd\u00e3o do Tribunal Constitucional j\u00e1 referido, que veio declarar a inconstitucionalidade, com for\u00e7a obrigat\u00f3ria geral, das normas que conferem aos membros do Governo respons\u00e1veis pelas \u00e1reas das finan\u00e7as e da administra\u00e7\u00e3o p\u00fablica legitimidade para celebrar e assinar acordos coletivos de empregador p\u00fablico, no \u00e2mbito da administra\u00e7\u00e3o aut\u00e1rquica<sup>34<\/sup>.<br \/>\n2.3. A VIG\u00caNCIA E APLICABILIDADE DO ACEP<br \/>\n2.3.1. Face a quanto fica anteriormente referido relativamente \u00e0s exig\u00eancias legais para que um ACEP se possa considerar plenamente vigente e aplic\u00e1vel, \u00e9 de concluir que, de acordo com as exig\u00eancias legais da LTFP no que toca a requisitos formais de efic\u00e1cia e a publicita\u00e7\u00e3o, ele ver\u00e1 o seu in\u00edcio de vig\u00eancia<sup>35<\/sup>&nbsp;\u2013 ou seja poder\u00e1 come\u00e7ar a produzir os efeitos nele previstos \u2013 unicamente ap\u00f3s publica\u00e7\u00e3o do seu texto em Di\u00e1rio da Rep\u00fablica, efectuado que tenha sido o seu pr\u00e9vio dep\u00f3sito na DGAEP.<br \/>\nNo caso ora em apre\u00e7o, o ACEP em quest\u00e3o foi depositado na DGAEP em 26 de Outubro de 2015<sup>36<\/sup>, tendo sido publicado no Di\u00e1rio da Rep\u00fablica em 10 de Novembro seguinte<sup>37<\/sup>, pelo que entrou em vigor, de acordo com o previsto no n.\u00ba 1 da sua cl\u00e1usula 2.\u00aa, cinco dias ap\u00f3s a sua publica\u00e7\u00e3o.<br \/>\nAntes desse momento n\u00e3o se pode dizer que tenha existido, em caso algum, um ACEP juridicamente v\u00e1lido e eficaz, condi\u00e7\u00e3o da sua aplicabilidade e produ\u00e7\u00e3o de efeitos, designada e especialmente, em mat\u00e9ria de redu\u00e7\u00e3o hor\u00e1ria do per\u00edodo normal de trabalho<sup>38<\/sup>.<br \/>\nPortanto, se \u00e0 luz da LTFP, s\u00e3o ainda previstas e necess\u00e1rias formalidades essenciais posteriores \u00e0 assinatura de um ACEP para que este se possa considerar juridicamente v\u00e1lido e eficaz, tal significa, ent\u00e3o, que ele nunca poder\u00e1 produzir quaisquer efeitos antes do cumprimento dessas formalidades e, menos ainda, nunca poder\u00e1 ser ficcionado o cumprimento retrotra\u00eddo dessas formalidades para assim retrotrair (igualmente de forma fict\u00edcia) o momento de inicio de vig\u00eancia do ACEP, retroagindo a sua produ\u00e7\u00e3o de efeitos, e por via disso, obtendo-se consequ\u00eancias laborais completamente pret\u00e9ritas, ou seja, efeitos e consequ\u00eancias considerados como tendo in\u00edcio de produ\u00e7\u00e3o num momento p\u00f3stumo e produzidos a partir de ent\u00e3o, durante um per\u00edodo a ele subsequente, mas j\u00e1 totalmente decorrido (futuro passado) quando essas formalidades tiveram lugar, mesmo que se pretenda este efeito como consequ\u00eancia necess\u00e1ria resultante dos efeitos da nulidade normativa<sup>39<\/sup>&nbsp;(de que resulta a efic\u00e1cia retroactiva da declara\u00e7\u00e3o de inconstitucionalidade) \u00ednsita na declara\u00e7\u00e3o de inconstitucionalidade da norma que definia a legitimidade para a celebra\u00e7\u00e3o e outorga do ACEP.<br \/>\nCabe, ali\u00e1s, sublinhar que em mat\u00e9ria de efic\u00e1cia temporal dos instrumentos de regulamenta\u00e7\u00e3o colectiva, a pr\u00f3pria LTFP disp\u00f5e que o[s] instrumento[s] de regulamenta\u00e7\u00e3o coletiva de trabalho (\u2026) n\u00e3o pode[m] conferir efic\u00e1cia retroativa a qualquer cl\u00e1usula que n\u00e3o seja de natureza pecuni\u00e1ria<sup>40<\/sup>, ou seja, apenas podem dispor para futuro, excepto quanto \u00e0 referida ressalva.<br \/>\n2.3.2. Na verdade, se aquilo a que se alude no pedido de parecer \u00e9 a uma retroac\u00e7\u00e3o (consequencial) do in\u00edcio de vig\u00eancia e dos efeitos do ACEP por via dos efeitos (retroactivos) inerentes \u00e0 declara\u00e7\u00e3o de inconstitucionalidade (com for\u00e7a obrigat\u00f3ria geral) da norma que previa a interven\u00e7\u00e3o de um membro do governo na outorga e assinatura do acordo, h\u00e1 que dizer que isso n\u00e3o ocorre no caso vertente \u2013 e que, portanto, a pretensa retroactividade dos efeitos jur\u00eddicos do ACEP n\u00e3o se verifica nem \u00e9, sequer, admiss\u00edvel.<br \/>\nNa verdade, as normas apreciadas pelo Tribunal Constitucional e declaradas inconstitucionais, e apenas quanto \u00e0 administra\u00e7\u00e3o aut\u00e1rquica, foram as do artigo 364.\u00ba, n.\u00ba 3, al\u00ednea b), e n.\u00ba 6, da Lei Geral do Trabalho em Fun\u00e7\u00f5es P\u00fablicas, por nelas ser conferida aos membros do Governo respons\u00e1veis pelas \u00e1reas das finan\u00e7as e da administra\u00e7\u00e3o p\u00fablica legitimidade para celebrar e assinar acordos coletivos de empregador p\u00fablico, no \u00e2mbito da administra\u00e7\u00e3o aut\u00e1rquica.<br \/>\nOra, tal inconstitucionalidade n\u00e3o s\u00f3 n\u00e3o se comunica \u00e0s demais normas da LTFP que regulam os procedimentos tendentes \u00e0 entrada em vigor de um ACEP, designadamente o dep\u00f3sito e a publica\u00e7\u00e3o, que apresentam uma natureza formal mas constitutiva, ou seja, na aus\u00eancia das quais n\u00e3o se pode dizer que exista um ACEP juridicamente v\u00e1lido e vigente, como, por outro lado, tamb\u00e9m n\u00e3o legitima qualquer retrotrac\u00e7\u00e3o (dos efeitos) de tais formalidades, ficcionando-as como ocorridas no passado as praticadas no presente, ou seja, como se essas formalidades tivessem sido praticadas em momento pret\u00e9rito e da\u00ed e a partir de ent\u00e3o pudessem resultar efeitos jur\u00eddicos vinculativos e cogentes.<br \/>\nO efeito da (declara\u00e7\u00e3o de) inconstitucionalidade com for\u00e7a obrigat\u00f3ria geral das normas em quest\u00e3o apenas significa e implica que foi eliminada ab ovo uma disposi\u00e7\u00e3o da lei relativa \u00e0 legitimidade e compet\u00eancia para a celebra\u00e7\u00e3o de ACEP<sup>41<\/sup>&nbsp;nas autarquias locais &#8211; mas disso n\u00e3o resulta a dispensa da pr\u00e1tica das subsequentes formalidades previstas na LTFP, sendo que essas formalidades se assumem como essenciais para que se possa ter in\u00edcio a produ\u00e7\u00e3o de efeitos jur\u00eddicos do ACEP, ou seja, para que se d\u00ea o seu in\u00edcio de vig\u00eancia.<br \/>\nAt\u00e9 \u00e0 declara\u00e7\u00e3o de inconstitucionalidade com for\u00e7a obrigat\u00f3ria geral das normas referidas n\u00e3o era legalmente admiss\u00edvel e juridicamente v\u00e1lido um ACEP que desrespeitasse as exig\u00eancias e condi\u00e7\u00f5es previstas na lei em mat\u00e9ria de legitimidade para a sua outorga. Portanto, um acordo em que n\u00e3o tivesse havido interven\u00e7\u00e3o todas as entidades referidas no artigo 364.\u00ba, n.\u00ba 3, al\u00ednea b), e n.\u00ba 6, da LTFP, era irregular face \u00e0 lei vigente at\u00e9 esse momento<sup>42<\/sup>.<br \/>\nPode-se considerar, por\u00e9m, que o efeito retroactivo (ab ovo) da declara\u00e7\u00e3o de inconstitucionalidade, previsto no artigo 282.\u00ba, n.\u00ba 1, da Constitui\u00e7\u00e3o, sanou o v\u00edcio (de ilegalidade, por viola\u00e7\u00e3o da lei) de que padecia o ACEP aqui em causa, fazendo com que a sua celebra\u00e7\u00e3o e assinatura passe a estar totalmente conforme com a lei e assim convalidando-o e tornando-o apto a prosseguir as demais formalidade legais.<br \/>\nPor\u00e9m, quanto \u00e0 repercuss\u00e3o dos efeitos da declara\u00e7\u00e3o de inconstitucionalidade com for\u00e7a obrigat\u00f3ria geral no ACEP em apre\u00e7o, eles esgotam-se aqui.<br \/>\nComo se viu antes, ap\u00f3s a celebra\u00e7\u00e3o e outorga do ACEP, segue-se ainda, de acordo com a LTFP, o dep\u00f3sito do mesmo na DGAEP e, ap\u00f3s este ser aceite, a publica\u00e7\u00e3o do texto do ACEP depositado em Di\u00e1rio da Rep\u00fablica.<br \/>\nComo tamb\u00e9m antes j\u00e1 se aludiu<sup>43<\/sup>, o dep\u00f3sito, mesmo que n\u00e3o consista num controle de conte\u00fado ou de subst\u00e2ncia do acordo, implica, ainda assim, um controlo formal sobre determinados requisitos legais, ficando dependente do seu comprimento ou observ\u00e2ncia. Ora, o primeiro desses requisitos no elenco legal<sup>44<\/sup>, \u00e9 o de que o ACEP seja celebrado por quem tenha capacidade para o efeito, norma que h\u00e1-de ser entendida no duplo sentido de que todos os intervenientes t\u00eam que ter capacidade para esse efeito e que todos os que tenham essa capacidade carecem de ter interven\u00e7\u00e3o na celebra\u00e7\u00e3o.<br \/>\nAssim sendo, n\u00e3o seria nunca poss\u00edvel \u00e0 Administra\u00e7\u00e3o \u2013 \u00e0 DGAEP, portanto \u2013 considerar o dep\u00f3sito efectuado antes da publica\u00e7\u00e3o em Di\u00e1rio da Rep\u00fablica do Ac\u00f3rd\u00e3o do Tribunal Constitucional n.\u00ba 494\/2015, pois que at\u00e9 ent\u00e3o o ACEP apresentava irregularidades que desrespeitavam os requisitos legais exigidos para o efeito.<br \/>\nS\u00f3 ap\u00f3s a sua publica\u00e7\u00e3o em Di\u00e1rio da Rep\u00fablica \u00e9 que o Ac\u00f3rd\u00e3o n.\u00ba 494\/2015 passou a produzir todos os seus efeitos<sup>45<\/sup>, permitindo que a partir da\u00ed o ACEP ora em apre\u00e7o passe a poder ser considerado como cumprindo todas as exig\u00eancias legais e, portanto, o seu dep\u00f3sito possa ser aceite e considerado efectuado.<br \/>\nEm consequ\u00eancia, como a publica\u00e7\u00e3o dos ACEP em Di\u00e1rio da Rep\u00fablica pressup\u00f5e o dep\u00f3sito v\u00e1lido<sup>46<\/sup>&nbsp;\u2013 pois que o texto do acordo a publicar tem que corresponder exactamente ao texto depositado \u2013 s\u00f3 ap\u00f3s este ter sido considerado efectuado \u00e9 que pode haver lugar a essa publica\u00e7\u00e3o.<br \/>\nE como a publica\u00e7\u00e3o em Di\u00e1rio da Rep\u00fablica \u00e9 pressuposto necess\u00e1rio essencial para que o ACEP entre em vigor, s\u00f3 haver\u00e1 ACEP v\u00e1lido e vigente ap\u00f3s a sua publica\u00e7\u00e3o, o que permitir\u00e1 o seu in\u00edcio de vig\u00eancia na data nele fixada ou, sendo omisso, de acordo com as regras supletivas aplic\u00e1veis para o efeito.<br \/>\nAssim, e em consequ\u00eancia, carece de qualquer fundamento jur\u00eddico-legal ou negocial, a apontada pretens\u00e3o de proceder ao pagamento, aos trabalhadores do Munic\u00edpio, do montante correspondente a uma hora<sup>47<\/sup>&nbsp;nos dias em que efetivamente prestaram servi\u00e7o entre 09\/12\/2014 e 15\/11\/2015, retirando todas as aus\u00eancias (faltas e f\u00e9rias), bem como de estender tal direito aos chefes de divis\u00e3o, aos eleitos locais e aos secret\u00e1rios dos gabinetes de apoio aos referidos eleitos<sup>48<\/sup>.<br \/>\n2.4. A PRETENDIDA EXTENS\u00c3O DE EFEITOS PARA AL\u00c9M DOS TRABALHADORES COM V\u00cdNCULO DE EMPREGO P\u00daBLICO<br \/>\nAcabou de ser dito que carece de qualquer fundamento jur\u00eddico, legal ou negocial, a pretens\u00e3o de proceder ao pagamento, aos trabalhadores do Munic\u00edpio, do montante correspondente a uma hora nos dias em que efetivamente prestaram servi\u00e7o entre 09\/12\/2014 e 15\/11\/2015, pelo que tratando-se da quest\u00e3o principal e de subst\u00e2ncia, um entendimento desfavor\u00e1vel sobre ela torna desnecess\u00e1ria a resposta \u00e0 quest\u00e3o colocada de forma subordinada, a saber, a da eventual aplicabilidade de tal direito respetivamente aos chefes de divis\u00e3o, aos eleitos locais e aos secret\u00e1rios dos gabinetes de apoio aos referidos eleitos.<br \/>\nAinda que assim seja, entende-se, n\u00e3o obstante, dever ser feita sobre ela uma breve nota.<br \/>\n2.4.1. Em primeiro lugar \u00e9 de referir que o \u00e2mbito subjectivo de aplica\u00e7\u00e3o do ACEP \u00e9 o nele definido, de acordo com o previsto na LTFP.<br \/>\nPor outro lado, sendo que a LTFP regula o v\u00ednculo de trabalho em fun\u00e7\u00f5es p\u00fablicas (artigo 1.\u00ba, n.\u00ba 1, da LTFP), que o trabalho em fun\u00e7\u00f5es p\u00fablicas pode ser prestado mediante v\u00ednculo de emprego p\u00fablico ou contrato de presta\u00e7\u00e3o de servi\u00e7o (artigo 6.\u00ba, n.\u00ba 1, da LTFP), que o v\u00ednculo de emprego p\u00fablico \u00e9 aquele pelo qual uma pessoa singular presta a sua atividade a um empregador p\u00fablico, de forma subordinada e mediante remunera\u00e7\u00e3o (artigo 6.\u00ba, n.\u00ba 2, da LTFP) nas modalidades de contrato de trabalho em fun\u00e7\u00f5es p\u00fablicas, nomea\u00e7\u00e3o ou comiss\u00e3o de servi\u00e7o (artigo 6.\u00ba, n.\u00ba 3, da LTFP), que o contrato de trabalho em fun\u00e7\u00f5es p\u00fablicas pode ser regulado por instrumento de regulamenta\u00e7\u00e3o coletiva de trabalho (artigo 13.\u00ba, n.\u00ba 1, da LTFP) no \u00e2mbito do direito de negocia\u00e7\u00e3o coletiva garantido aos trabalhadores com v\u00ednculo de emprego p\u00fablico (artigo 347.\u00ba, n.\u00ba 1, da LTFP), que um desses instrumentos \u00e9 o acordo coletivo de trabalho (artigo 13.\u00ba, n.\u00ba 3, da LTFP), o qual pode assumir a forma de acordo coletivo de empregador p\u00fablico (artigo 13.\u00ba, n.\u00ba 5, da LTFP) que consiste na conven\u00e7\u00e3o coletiva aplic\u00e1vel no \u00e2mbito do \u00f3rg\u00e3o ou servi\u00e7o onde o trabalhador exer\u00e7a fun\u00e7\u00f5es (artigo 13.\u00ba, n.\u00ba 7, da LTFP), ent\u00e3o n\u00e3o resta sen\u00e3o concluir que os eleitos locais, porque n\u00e3o s\u00e3o trabalhadores em fun\u00e7\u00f5es publicas, nem det\u00eam um v\u00ednculo da trabalho em fun\u00e7\u00f5es p\u00fablicas para com a autarquia, n\u00e3o caem, obviamente, no \u00e2mbito de aplica\u00e7\u00e3o da LTFP e portanto no \u00e2mbito de aplica\u00e7\u00e3o subjectivo do ACEP, pelo que nunca lhes poderia ser aplic\u00e1vel o seu regime, enquanto normativo disciplinador do trabalho em fun\u00e7\u00f5es p\u00fablicas.<br \/>\nNa verdade, os membros dos \u00f3rg\u00e3os deliberativos e executivos dos munic\u00edpios e das freguesias s\u00e3o considerados pela lei como eleitos locais, dotados de estatuto pr\u00f3prio como titulares do poder local, para cuja aprova\u00e7\u00e3o a Constitui\u00e7\u00e3o apenas confere compet\u00eancia \u00e0 Assembleia da Rep\u00fablica, lado a lado com a relativa aos titulares dos \u00f3rg\u00e3os de soberania (artigo 164.\u00ba, al. m) da Constitui\u00e7\u00e3o), cujos direitos se encontram elencados no artigo 5.\u00ba do Estatuto dos Eleitos Locais<sup>49<\/sup>, n\u00e3o existindo a\u00ed norma que preveja qualquer hor\u00e1rio de trabalho cuja ultrapassagem possa conferir direito a qualquer compensa\u00e7\u00e3o ou pagamento, designadamente a t\u00edtulo de trabalho extraordin\u00e1rio.<br \/>\nO v\u00ednculo jur\u00eddico que permite aos eleitos locais o exerc\u00edcio leg\u00edtimo das suas fun\u00e7\u00f5es n\u00e3o \u00e9, pois, um v\u00ednculo laboral, maxime, um v\u00ednculo assente numa rela\u00e7\u00e3o laboral baseada num contrato de trabalho, mas sim um v\u00ednculo pol\u00edtico, um mandato, de dura\u00e7\u00e3o previamente fixada e limitada<sup>50<\/sup>, assente no sufr\u00e1gio eleitoral<sup>51<\/sup>, e cujo exerc\u00edcio de fun\u00e7\u00f5es pressup\u00f5e a instala\u00e7\u00e3o do \u00f3rg\u00e3o para que hajam sido eleitos<sup>52<\/sup>|<sup>53<\/sup>.<br \/>\nTorna-se assim evidente que os eleitos locais encontram-se fora do \u00e2mbito de aplica\u00e7\u00e3o da LTFP e, por maioria de raz\u00e3o, do \u00e2mbito de aplica\u00e7\u00e3o dos ACEP nela previstos e celebrados no seu \u00e2mbito. Al\u00e9m disso, aludindo o pedido de parecer, genericamente, a \u201celeitos locais\u201d, sem precisar quais deles, parte-se da presun\u00e7\u00e3o de que estaria a querer referir-se apenas aos membros do \u00f3rg\u00e3o executivo municipal a c\u00e2mara municipal em regime de perman\u00eancia.<br \/>\n2.4.2. A LTFP ao mesmo tempo que define positivamente o seu \u00e2mbito de aplica\u00e7\u00e3o no seu artigo 1.\u00ba, f\u00e1-lo tamb\u00e9m de forma negativa, ao prever, de modo expresso, um conjunto de entidades \u00e0s quais ela se diz n\u00e3o aplic\u00e1vel \u2013 rectuis, um conjunto de entidades a cujos trabalhadores ela n\u00e3o \u00e9 aplic\u00e1vel, ficando assim estes fora do seu \u00e2mbito de aplica\u00e7\u00e3o subjectivo, pelo que a sua rela\u00e7\u00e3o laboral haver\u00e1 ser regulada por outros dipositivos legais.<br \/>\nAssim, no seu artigo 2.\u00ba, n.\u00ba 1, al. a), a LTFP coloca fora do seu \u00e2mbito de aplica\u00e7\u00e3o os gabinetes de apoio dos membros do Governo e dos titulares dos \u00f3rg\u00e3os referidos nos n.\u00bas 2 a 4 do artigo anterior<sup>54<\/sup>, ou seja, quanto a esta \u00faltima refer\u00eancia e para o que ora interessa, aos gabinetes de apoio dos titulares dos \u00f3rg\u00e3os da administra\u00e7\u00e3o aut\u00e1rquica, pelo que se lhes n\u00e3o aplica a disciplina da LTFP, designadamente em mat\u00e9ria de instrumentos de regulamenta\u00e7\u00e3o colectiva.<br \/>\nPor outro lado, estes gabinetes h\u00e3o-de ser aqueles a que se referem os artigos 42.\u00ba e 43.\u00ba do Regime Jur\u00eddico das Autarquias Locais (RJAL)<sup>55<\/sup>, seja, o gabinete de apoio \u00e0 presid\u00eancia<sup>56<\/sup>&nbsp;e o gabinete de apoio \u00e0 verea\u00e7\u00e3o<sup>57<\/sup>. Trata-se de gabinetes de confian\u00e7a pessoal<sup>58<\/sup>, com pessoal em regime de livre nomea\u00e7\u00e3o e exonera\u00e7\u00e3o, e que, obrigatoriamente, cessa fun\u00e7\u00f5es com o termo do mandato do nomeante<sup>59<\/sup>. Acresce que o pessoal destes gabinetes disp\u00f5e de um sistema remunerat\u00f3rio pr\u00f3prio<sup>60<\/sup>&nbsp;totalmente distinto do sistema remunerat\u00f3rio previsto no artigo 87.\u00ba da LTFP<sup>61<\/sup>, sendo-lhes ainda aplic\u00e1vel, com as devidas adapta\u00e7\u00f5es, o disposto no diploma que estabelece o regime jur\u00eddico a que est\u00e3o sujeitos os gabinetes dos membros do Governo no que respeita a designa\u00e7\u00e3o, fun\u00e7\u00f5es, regime de exclusividade, incompatibilidades, impedimentos, deveres e garantias<sup>62<\/sup>.<br \/>\nOra o Decreto-Lei n.\u00ba 11\/2012, de 20 de Janeiro, que presentemente estabelece a natureza, a composi\u00e7\u00e3o, a org\u00e2nica e o regime jur\u00eddico a que est\u00e3o sujeitos os gabinetes dos membros do Governo, diz que para al\u00e9m do chefe de gabinete, os restantes membros do gabinete pelo exerc\u00edcio das suas fun\u00e7\u00f5es em regime de disponibilidade permanente e isen\u00e7\u00e3o de hor\u00e1rio de trabalho, decorrente da natureza e das condi\u00e7\u00f5es de funcionamento espec\u00edficas dos gabinetes, (\u2026) t\u00eam um regime remunerat\u00f3rio pr\u00f3prio<sup>63<\/sup>. Mais se diz ainda nesse diploma que esse referido pessoal (\u2026) n\u00e3o fica sujeito aos limites m\u00e1ximos dos per\u00edodos normais de trabalho, n\u00e3o sendo devida qualquer remunera\u00e7\u00e3o a t\u00edtulo de trabalho extraordin\u00e1rio ou nocturno ou prestado em dias de descanso e feriados<sup>64<\/sup>.<br \/>\nDeste modo, e sendo que esse regime tamb\u00e9m lhes \u00e9 aplic\u00e1vel por via da j\u00e1 referida remiss\u00e3o do n.\u00ba 5 do artigo 43.\u00ba da RJAL, ent\u00e3o n\u00e3o resta sen\u00e3o concluir que ao pessoal que, nas c\u00e2maras municipais, presta servi\u00e7o no gabinete de apoio \u00e0 presid\u00eancia e no gabinete de apoio \u00e0 verea\u00e7\u00e3o n\u00e3o \u00e9 devida qualquer remunera\u00e7\u00e3o a t\u00edtulo de trabalho extraordin\u00e1rio ou nocturno ou prestado em dias de descanso e feriados pelo que, tamb\u00e9m n\u00e3o seria de abonar a esse pessoal o pagamento referido no pedido do presente parecer, caso ele fosse devido e pudesse ser pago, pois que em nenhum caso ele lhes seria devido.<br \/>\n2.4.3. Resta, por fim, abordar os chefes de divis\u00e3o. Quanto a estes h\u00e1 que referir que os mesmos integram o grupo de pessoal dirigente, sendo regidos por estatuto pr\u00f3prio<sup>65<\/sup>, aplic\u00e1vel, com as necess\u00e1rias adapta\u00e7\u00f5es, \u00e0 administra\u00e7\u00e3o local mediante decreto-lei<sup>66<\/sup>.<br \/>\nEsta especial regula\u00e7\u00e3o n\u00e3o afasta, por\u00e9m, o facto de o pessoal dirigente ser considerado como trabalhador em fun\u00e7\u00f5es p\u00fablicas, pois que para o exerc\u00edcio das suas fun\u00e7\u00f5es, que \u00e9 transit\u00f3rio, ou seja, tem uma dura\u00e7\u00e3o limitada na lei, ele encontra-se em regime de comiss\u00e3o de servi\u00e7o que \u00e9 uma das modalidade do v\u00ednculo de emprego p\u00fablico<sup>67<\/sup>, especificamente aquela que \u00e9 aplic\u00e1vel aos cargos dirigentes<sup>68<\/sup>.<br \/>\nPor seu lado, a Lei n.\u00ba 49\/2012, de 29 de Agosto, alterada pela Lei n.\u00ba 82-B\/2014, de 31 de Dezembro, que procede \u00e0 adapta\u00e7\u00e3o do EPD \u00e0 administra\u00e7\u00e3o local, diz aplic\u00e1vel<sup>69&nbsp;<\/sup>ao pessoal dirigente das c\u00e2maras municipais o estatuto do pessoal dirigente da administra\u00e7\u00e3o central com as adapta\u00e7\u00f5es nela previstas, excep\u00e7\u00e3o feita \u00e0 sua sec\u00e7\u00e3o III do cap\u00edtulo I relativo \u00e0s compet\u00eancias. Temos assim que, salvo quanto \u00e0s adapta\u00e7\u00f5es nele expressamente efectuadas, o quadro legal aplic\u00e1vel aos dirigentes das c\u00e2maras municipais \u00e9 o aplic\u00e1vel aos dirigentes da administra\u00e7\u00e3o central<sup>70<\/sup>.<br \/>\nOra, n\u00e3o se encontrando especialmente regulada na Lei n.\u00ba 49\/2012 a mat\u00e9ria relativa a hor\u00e1rio de trabalho do pessoal dirigente das c\u00e2maras municipais, n\u00e3o resta ent\u00e3o sen\u00e3o considerar que a esse pessoal dirigente \u00e9 integralmente aplic\u00e1vel a norma do artigo 13.\u00ba do EPD, na qual se diz que o pessoal dirigente est\u00e1 isento de hor\u00e1rio de trabalho, n\u00e3o lhe sendo, por isso, devida qualquer remunera\u00e7\u00e3o por trabalho prestado fora do per\u00edodo normal de trabalho.<br \/>\nOra, sendo assim, como \u00e9, n\u00e3o seria igualmente de abonar ao pessoal dirigente da c\u00e2mara municipal e concretamente a chefes de divis\u00e3o municipal, o pagamento referido no pedido do presente parecer, caso ele fosse devido e pudesse ser pago, pois que em nenhum caso ele lhes seria devido \u00e0 face da lei.<\/p>\n<p>&nbsp;<\/p>\n<p>CONCLUINDO<br \/>\na) Carece de qualquer fundamento jur\u00eddico-legal ou negocial, a pretens\u00e3o de se proceder ao pagamento, aos trabalhadores do Munic\u00edpio, do montante correspondente a uma hora nos dias em que efetivamente prestaram servi\u00e7o entre 09\/12\/2014 e 15\/11\/2015, retirando todas as aus\u00eancias (faltas e f\u00e9rias), pois que tal n\u00e3o pode ser extra\u00eddo consequencialmente (como efeito) da declara\u00e7\u00e3o de inconstitucionalidade com for\u00e7a obrigat\u00f3ria geral, constante do Ac\u00f3rd\u00e3o do Tribunal Constitucional n.\u00ba 494\/2015, das normas que conferem aos membros do Governo respons\u00e1veis pelas \u00e1reas das finan\u00e7as e da administra\u00e7\u00e3o p\u00fablica legitimidade para celebrar e assinar acordos coletivos de empregador p\u00fablico, no \u00e2mbito da administra\u00e7\u00e3o aut\u00e1rquica, resultantes do artigo 364.\u00ba, n.\u00ba 3, al\u00ednea b), e do n.\u00ba 6, da Lei Geral do Trabalho em Fun\u00e7\u00f5es P\u00fablicas, aprovada em anexo \u00e0 Lei n.\u00ba 35\/2014, de 20 de junho, por viola\u00e7\u00e3o do princ\u00edpio da autonomia local, consagrado no artigo 6.\u00ba, n.\u00ba 1, da Constitui\u00e7\u00e3o.<br \/>\nb) O ACEP em causa, celebrado na plena vig\u00eancia da lei e contra as suas determina\u00e7\u00f5es em mat\u00e9ria de entidades outorgantes que nele deveriam ter interven\u00e7\u00e3o, nunca poderia, por isso, ser considerado como depositado, e, consequencialmente, ser publicado, para que entrasse em vigor na data nele prevista, enquanto se mantivesse essa desconformidade com o requisito legal.<br \/>\nc) A decis\u00e3o do Tribunal Constitucional ao declarar inconstitucionais as normas que continham a previs\u00e3o normativa que o ACEP desrespeitava, convalidou-o, tornando-o conforme \u00e0 lei.<br \/>\nd) Contudo, n\u00e3o basta a sua regular outorga (ou a regularidade superveniente da sua outorga) para que um ACEP entre em vigor \u2013 pois que a lei (LTFP) exige ainda o cumprimento de um conjunto de outras posteriores formalidades para que essa vig\u00eancia possa ter inicio.<br \/>\ne) Ap\u00f3s a sua assinatura, o ACEP carece de ser entregue na DGAEP, para efeitos de dep\u00f3sito que se considera efectuado se n\u00e3o for fundamentadamente recusado nos 15 dias seguintes \u00e0 data da sua recep\u00e7\u00e3o; efectuado este, \u00e9 ainda necess\u00e1ria a publica\u00e7\u00e3o do ACEP em Di\u00e1rio da Rep\u00fablica, em face da qual entrar\u00e1 em vigor nos mesmo termos da lei, ou seja, na data nele fixada ou, na falta de tal indica\u00e7\u00e3o, cinco dias ap\u00f3s a sua publica\u00e7\u00e3o.<br \/>\nf) Dos efeitos da declara\u00e7\u00e3o de inconstitucionalidade com for\u00e7a obrigat\u00f3ria geral relativamente \u00e0 norma sobre legitimidade para a outorga de ACEP n\u00e3o \u00e9 poss\u00edvel extrair a consequ\u00eancia ou o efeito de poder ser ficcionado que o dep\u00f3sito e publica\u00e7\u00e3o desse ACEP hajam sido efectuados em data anterior \u00e0quela em que efectivamente ocorreram e que, por isso, ele haveria de produzir efeitos a partir de um momento determinado por uma fic\u00e7\u00e3o que consistiria em recorrer ao lapso de tempo que foi agora necess\u00e1rio para proceder ao seu dep\u00f3sito e publica\u00e7\u00e3o, para o ficcionar como ocorrido imediatamente a seguir \u00e0 data da assinatura do ACEP, e produzindo efeitos a partir de ent\u00e3o, em especial em mat\u00e9ria de redu\u00e7\u00e3o da dura\u00e7\u00e3o do per\u00edodo normal de trabalho.<br \/>\ng) A publica\u00e7\u00e3o dos ACEP em Di\u00e1rio da Rep\u00fablica pressup\u00f5e o dep\u00f3sito v\u00e1lido e s\u00f3 ap\u00f3s este ter sido considerado efectuado \u00e9 que pode haver lugar a essa publica\u00e7\u00e3o, a qual constitui pressuposto necess\u00e1rio essencial para que o ACEP entre em vigor na data nele fixada ou de acordo com as regras supletivas aplic\u00e1veis \u2013 pelo que sendo actos objectivos e \u201cmateriais\u201d, n\u00e3o \u00e9 poss\u00edvel ficcionar a sua pr\u00e1tica ou consider\u00e1-los praticados em momento anterior \u00e0quele em que efectivamente o foram.<br \/>\nh) Assim sendo, carece de qualquer fundamento jur\u00eddico-legal ou negocial, a pretens\u00e3o de proceder ao pagamento, aos trabalhadores do Munic\u00edpio, do montante correspondente a uma hora nos dias em que efetivamente prestaram servi\u00e7o entre 09\/12\/2014 e 15\/11\/2015, retirando todas as aus\u00eancias (faltas e f\u00e9rias), bem como de estender tal direito aos chefes de divis\u00e3o, aos eleitos locais e aos secret\u00e1rios dos gabinetes de apoio aos referidos eleitos.<br \/>\ni) Contudo, na hip\u00f3tese de tal poder ser admiss\u00edvel, que n\u00e3o \u00e9, certo \u00e9 que essa regalia nunca poderia ser estendida aos chefes de divis\u00e3o, aos eleitos locais e aos secret\u00e1rios dos gabinetes de apoio aos referidos eleitos.<br \/>\n1) N\u00e3o poderia ser estendida aos chefes de divis\u00e3o pois que ainda que estes sejam trabalhadores em fun\u00e7\u00f5es p\u00fablicas, eles encontra-se sujeitos ao disposto no Estatuto do Pessoal Dirigente da Administra\u00e7\u00e3o P\u00fablica, por for\u00e7a do disposto na Lei n.\u00ba 49\/2012, de 29 de Agosto, que adapta o EPD \u00e0 administra\u00e7\u00e3o local, sendo-lhe por isso integralmente aplic\u00e1vel a norma do artigo 13.\u00ba do EPD, que estabelece que o pessoal dirigente est\u00e1 isento de hor\u00e1rio de trabalho, n\u00e3o lhe sendo, por isso, devida qualquer remunera\u00e7\u00e3o por trabalho prestado fora do per\u00edodo normal de trabalho.<br \/>\n2) N\u00e3o poderia ser estendido aos membros da c\u00e2mara municipal (em regime de perman\u00eancia) porque estes s\u00e3o considerados pela lei como eleitos locais, dotados de estatuto pr\u00f3prio como titulares do poder local, cujos direitos se encontram elencados no Estatuto dos Eleitos Locais, n\u00e3o existindo a\u00ed norma que preveja qualquer hor\u00e1rio de trabalho cuja ultrapassagem possa conferir direito a qualquer compensa\u00e7\u00e3o ou pagamento, designadamente a t\u00edtulo de trabalho extraordin\u00e1rio, para al\u00e9m de que o v\u00ednculo jur\u00eddico que legitima aos eleitos locais o exerc\u00edcio das suas fun\u00e7\u00f5es n\u00e3o \u00e9 um v\u00ednculo laboral, maxime, um v\u00ednculo assente numa rela\u00e7\u00e3o laboral baseada num contrato de trabalho, mas sim um v\u00ednculo pol\u00edtico, um mandato, assente no sufr\u00e1gio eleitoral, pelo que a LTFP e, da\u00ed, o ACEP n\u00e3o lhes seja aplic\u00e1vel.<br \/>\n3) Por fim n\u00e3o poderia igualmente ser estendido aos secret\u00e1rios dos gabinetes de apoio aos referidos eleitos, n\u00e3o s\u00f3 porque estes gabinetes se encontram fora do \u00e2mbito de aplica\u00e7\u00e3o da LTFP e, por tal, dos instrumentos de regulamenta\u00e7\u00e3o colectiva nela previstos, como tamb\u00e9m porque o pessoal destes gabinetes n\u00e3o se encontra sujeito aos limites m\u00e1ximos dos per\u00edodos normais de trabalho, pelo que n\u00e3o lhes \u00e9 devida qualquer remunera\u00e7\u00e3o a t\u00edtulo de trabalho extraordin\u00e1rio ou nocturno ou prestado em dias de descanso e feriados, conforme se disp\u00f5e no artigo 13.\u00ba, n.\u00ba 3, do Decreto-Lei n.\u00ba 11\/2012, aplic\u00e1vel ex vi da remiss\u00e3o que para ele faz o artigo 43.\u00ba, n.\u00ba 5, do RJAL.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Salvo semper meliori judicio<\/p>\n<p>&nbsp;<\/p>\n<p>Ricardo da Veiga Ferr\u00e3o<br \/>\n(Jurista. T\u00e9cnico Superior)<\/p>\n<p>1. O Ac\u00f3rd\u00e3o do Tribunal Constitucional n.\u00ba 494\/2015, devidamente rectificado, encontra-se publicado junto \u00e0 Declara\u00e7\u00e3o de Retifica\u00e7\u00e3o n.\u00ba 47-A\/2015, no Di\u00e1rio da Rep\u00fablica, 1.\u00aa s\u00e9rie, n.\u00ba 207, 1.\u00ba suplemento, de 22 de Outubro de 2015.<\/p>\n<p>2. Artigo 1.\u00ba, n.\u00ba 1, da LTFP.<\/p>\n<p>3. Artigo 1.\u00ba, n.\u00ba 2, da LTFP.<\/p>\n<p>4. Artigo 1.\u00ba, n.\u00bas 3 e 4, da LTFP.<\/p>\n<p>5. Artigo 42.\u00ba da Lei n.\u00ba 35\/2014, de 20 de Julho.<br \/>\nPorque a LTFP veio disciplinar, de forma unit\u00e1ria e num s\u00f3 diploma legal, o regime de v\u00ednculos laborais e da presta\u00e7\u00e3o de trabalho na administra\u00e7\u00e3o p\u00fablica, substituindo e coligindo num \u00fanico diploma a disciplina da mat\u00e9ria at\u00e9 ent\u00e3o vigente, que se encontrava dispersa por v\u00e1rios diplomas, a Lei 35\/2014 revogou a legisla\u00e7\u00e3o sobre o regime de trabalho na fun\u00e7\u00e3o p\u00fablicas vigente at\u00e9 ent\u00e3o, designadamente a Lei n.\u00ba 12-A\/2008, de 27 de Fevereiro (LVCR), com excep\u00e7\u00e3o das suas normas transit\u00f3rias (artigos 88.\u00ba a 115.\u00ba) e a Lei n.\u00ba 59\/2008, de 11 de Setembro (RCTFP).<br \/>\nContudo isso n\u00e3o significou de forma nenhuma, qualquer radical altera\u00e7\u00e3o pela nova lei, das op\u00e7\u00f5es, sentido e solu\u00e7\u00f5es contidos nos diplomas seus antecedentes. Pelo contr\u00e1rio, a LTFP, para al\u00e9m de algumas novidades, recebeu e incorporou a quase totalidade das solu\u00e7\u00f5es, e mesmo das pr\u00f3prias normas, da anterior legisla\u00e7\u00e3o.<\/p>\n<p>6. O que n\u00e3o significa, contudo, que a LTFP lhes n\u00e3o possa ser ainda aplic\u00e1vel, mas, neste caso, apenas por via de remiss\u00e3o legal operada por norma aplic\u00e1vel a esses especiais regimes, que venha cometer \u00e0 LTFP a regula\u00e7\u00e3o de determinados aspectos ou mat\u00e9rias. \u00c9 o caso, por exemplo, da aplicabilidade aos trabalhadores das entidades reguladoras, n\u00e3o obstante se encontrarem sujeitos ao regime do contrato individual de trabalho, [d]os requisitos e [d]as limita\u00e7\u00f5es decorrentes da prossecu\u00e7\u00e3o do interesse p\u00fablico, nomeadamente os respeitantes a acumula\u00e7\u00f5es e incompatibilidades legalmente estabelecidos para os trabalhadores em fun\u00e7\u00f5es p\u00fablicas (artigo 32.\u00ba, n.\u00ba 1 e 4, da Lei-Quadro das Entidades Administrativas Independentes com Fun\u00e7\u00f5es de Regula\u00e7\u00e3o da Atividade Econ\u00f3mica, referida infra, na nota 9).<\/p>\n<p>7. Os \u00f3rg\u00e3os cujos gabinetes de apoio aos respectivos titulares se encontram exclu\u00eddos do \u00e2mbito de aplica\u00e7\u00e3o da LTFP s\u00e3o os gabinetes de apoio aos membros dos governos regionais e dos \u00f3rg\u00e3os da administra\u00e7\u00e3o aut\u00e1rquica (artigo 1.\u00ba, n.\u00ba 2, da LTFP), do Presidente da Rep\u00fablica, dos tribunais e do Minist\u00e9rio P\u00fablico e respetivos \u00f3rg\u00e3os de gest\u00e3o e de outros \u00f3rg\u00e3os independentes (artigo 1.\u00ba, n.\u00ba 3, da LTFP) bem como da Assembleia da Rep\u00fablica (artigo 1.\u00ba, n.\u00ba 4, da LTFP).<\/p>\n<p>8. As Entidades P\u00fablicas Empresariais encontram-se previstas e reguladas no Regime Jur\u00eddico do Sector P\u00fablico Empresarial, constante do Decreto-Lei n.\u00ba 133\/2013, de 3 de Outubro, alterado pela Lei n.\u00ba 75-A\/2014, de 30 de Setembro.<br \/>\nDe acordo com o artigo 56.\u00ba deste referido diploma, as entidades p\u00fablicas empresariais s\u00e3o definidas como pessoas coletivas de direito p\u00fablico, com natureza empresarial, criadas pelo Estado para prossecu\u00e7\u00e3o dos seus fins, as quais se regem pelas disposi\u00e7\u00f5es do (&#8230;) [seu] cap\u00edtulo IV e, subsidiariamente, pelas restantes normas do (\u2026) [mesmo] decreto-lei.<br \/>\nNos termos do artigo 57.\u00ba, n.\u00ba 1, do mesmo diploma, as entidades p\u00fablicas empresariais s\u00e3o criadas por decreto-lei, o qual aprova tamb\u00e9m os respetivos estatutos.<\/p>\n<p>9. As Entidades Administrativas Independentes com Fun\u00e7\u00f5es de Regula\u00e7\u00e3o da Atividade Econ\u00f3mica encontram-se disciplinadas pela Lei-quadro das entidades administrativas independentes com fun\u00e7\u00f5es de regula\u00e7\u00e3o da atividade econ\u00f3mica dos setores privado, p\u00fablico e cooperativo, aprovada pela Lei n.\u00ba 67\/2013, de 28 de Agosto.<br \/>\nPor seu lado, o Banco de Portugal rege-se por Lei Org\u00e2nica pr\u00f3pria, aprovada pela Lei n.\u00ba 5\/98, de 31 de Janeiro, posteriormente alterada pelos Decreto-Lei n.\u00ba 118\/2001, de 17 de Abril, Decreto-Lei n.\u00ba 50\/2004, de 10 de Mar\u00e7o, Decreto-Lei n.\u00ba 39\/2007, de 20 de Fevereiro, Decreto-Lei n.\u00ba 31-A\/2012, de 10 de Fevereiro, Decreto-Lei n.\u00ba 142\/2013, de 18 de Outubro, Lei n.\u00ba 23-A\/2015, de 26 de Mar\u00e7o, e Lei n.\u00ba 39\/2015, de 25 de Maio.<\/p>\n<p>10. Artigo 6.\u00ba, n.\u00bas 2 e 3, da LTFP.<\/p>\n<p>11. Artigo 6.\u00ba, n.\u00ba 1, da LTFP.<\/p>\n<p>12. Sobre os usos laborais como fonte de direito do trabalho, vd. BERNARDO DA GAMA LOBO XAVIER, Manual de Direito do Trabalho, 2.\u00aa edi\u00e7\u00e3o revista e actualizada, 2014, p\u00e1g. 284.<\/p>\n<p>13. Artigo 13.\u00ba, n.\u00ba 2, da LTFP.<\/p>\n<p>14. Nesse sentido, LUIZ MENESES LEIT\u00c3O, Direito do Trabalho, 4.\u00aa edi\u00e7\u00e3o, 2014, p\u00e1g. 591 e BERNARDO DA GAMA LOBO XAVIER, Manual \u2026 cit., p\u00e1g. 271 e 275-276.<\/p>\n<p>15. Nesse sentido, MARIA DO ROS\u00c1RIO PALMA RAMALHO, Tratado de Direito do Trabalho, Parte III &#8211; Situa\u00e7\u00f5es Laborais Colectivas, 2.\u00ba edi\u00e7\u00e3o, 2015, p\u00e1g., 183 e nota 2 nessa p\u00e1gina.<\/p>\n<p>16. Artigo 13.\u00ba, n.\u00ba 3, da LTFP.<\/p>\n<p>17. Artigo 13.\u00ba, n.\u00ba 5, da LTFP.<\/p>\n<p>18. Artigo 13.\u00ba, n.\u00ba 7, da LTFP.<\/p>\n<p>19. Artigo 14.\u00ba, n.\u00ba 2 e n.\u00ba 1, da LTFP.<\/p>\n<p>20. Artigo 364.\u00ba, n.\u00ba 3, al. b), da LTFP. No caso dos servi\u00e7os municipalizados a lei prev\u00ea a interven\u00e7\u00e3o do respectivo presidente do conselho de administra\u00e7\u00e3o.<\/p>\n<p>21. Artigo 14.\u00ba, n.\u00ba 2 e n.\u00ba 1, da LTFP.<br \/>\nEsta \u00e9 j\u00e1 a solu\u00e7\u00e3o que o Decreto-Lei n.\u00ba 209\/2009, de 3 de Setembro, veio estabelecer no n.\u00ba 2 do seu artigo 2.\u00ba, ainda na vig\u00eancia da Lei n.\u00ba 12-A\/2008 (LVCR) e da Lei n.\u00ba 59\/2008 (RCTFP), as quais eram omissas quanto a este aspecto.<\/p>\n<p>22. A legitimidade de interven\u00e7\u00e3o conjunta dos membros do Governo respons\u00e1veis pelas \u00e1reas das finan\u00e7as e da Administra\u00e7\u00e3o P\u00fablica na celebra\u00e7\u00e3o e assinatura de acordos colectivos de entidade empregadora p\u00fablica no \u00e2mbito das autarquias locais, n\u00e3o constitui qualquer inova\u00e7\u00e3o ou novidade trazida pela LTFP, ao arrepio do que antes se dispunha.<br \/>\nNa verdade, o artigo 347.\u00ba, n.\u00ba 3, al. b), do RCTFP, j\u00e1 dispunha que t\u00eam legitimidade para celebrar acordos colectivos de entidade empregadora p\u00fablica (\u2026) pela entidade empregadora p\u00fablica, os membros do Governo respons\u00e1veis pelas \u00e1reas das finan\u00e7as e da Administra\u00e7\u00e3o P\u00fablica e o que superintenda no \u00f3rg\u00e3o ou servi\u00e7o, bem como a pr\u00f3pria entidade empregadora p\u00fablica. E o n.\u00ba 6 do mesmo artigo dispunha igualmente que os acordos colectivos de trabalho s\u00e3o assinados pelos representantes das associa\u00e7\u00f5es sindicais determinadas nos termos dos n\u00fameros anteriores, bem como pelos membros do Governo e entidade referidos naqueles n\u00fameros, ou respectivos representantes.<br \/>\nAs autarquias locais, como entidades empregadoras p\u00fablicas, intervinham representadas nos termos do n.\u00ba 2 do artigo 2.\u00ba do Decreto-Lei n.\u00ba 209\/2009.<\/p>\n<p>23. Cfr. MARIA DO ROS\u00c1RIO PALMA RAMALHO, Tratado \u2026 cit., p\u00e1g., 251.<\/p>\n<p>24. Cfr. ANT\u00d3NIO MONTEIRO FERNANDES, Direito do Trabalho, 14.\u00aa edi\u00e7\u00e3o, 2009, p\u00e1g. 797 (edi\u00e7\u00e3o aced\u00edvel e consultada; por\u00e9m, existe j\u00e1 a 17.\u00ba edi\u00e7\u00e3o, 2014).<br \/>\nDiz este autor a respeito do dep\u00f3sito dos ACT, \u00e0 luz da lei laboral: O dep\u00f3sito consiste na recep\u00e7\u00e3o e registo, pelo Minist\u00e9rio do Trabalho, do texto do acordo, assinado pelas partes. Esse acto est\u00e1 subordinado a pressupostos legais indicados no artigo 494.\u00ba [do C\u00f3digo do Trabalho]. Embora n\u00e3o possa dizer-se que as conven\u00e7\u00f5es colectivas est\u00e3o globalmente sujeitas a um controlo administrativo do seu conte\u00fado, esse controlo existe todavia em rela\u00e7\u00e3o a aspectos individualizados, pela via da (eventual) recusa do dep\u00f3sito e, por conseguinte, da n\u00e3o publica\u00e7\u00e3o do texto acordado, que determina a sua inefic\u00e1cia enquanto instrumento de regulamenta\u00e7\u00e3o colectiva de trabalho (ob. cit. p\u00e1g. 797-798).<br \/>\nDiz ainda o mesmo autor, a respeito do dep\u00f3sito das conven\u00e7\u00f5es colectivas de trabalho: Define a lei certos elementos identificativos de cada CCT que, por isso, nela devem figurar obrigatoriamente: a designa\u00e7\u00e3o das entidades celebrantes, o nome e qualidade em que interv\u00eam os representantes das entidades celebrantes, a \u00e1rea e \u00e2mbito de aplica\u00e7\u00e3o, a data da celebra\u00e7\u00e3o, a identifica\u00e7\u00e3o da conven\u00e7\u00e3o alterada, o prazo de vig\u00eancia acordado (art. 492.\u00ba\/1). Sem eles, n\u00e3o \u00e9 poss\u00edvel, ou pode suscitar d\u00favidas s\u00e9rias, a determina\u00e7\u00e3o do campo de aplica\u00e7\u00e3o da conven\u00e7\u00e3o no tempo e no espa\u00e7o. Da\u00ed que a sua omiss\u00e3o seja considerada um obst\u00e1culo \u00e0 pr\u00f3pria efic\u00e1cia do clausulado, estando sujeita a controlo administrativo: o dep\u00f3sito da CCT no Minist\u00e9rio do Trabalho, sem o qual n\u00e3o h\u00e1 publica\u00e7\u00e3o (nem, por conseguinte, entrada em vigor), pode ser recusado na falta de qualquer das referidas indica\u00e7\u00f5es (art. 494.\u00ba\/4-c)) (ob. cit. p\u00e1g. 113) [sublinhados nossos].<\/p>\n<p>25. Artigo 368.\u00ba, n.\u00bas 5 e 6, da LTFP.<br \/>\nA possibilidade de recusa do dep\u00f3sito revela que h\u00e1, por conseguinte, um controlo administrativo da legalidade formal da conven\u00e7\u00e3o. Cfr. ANT\u00d3NIO MONTEIRO FERNANDES, Direito do Trabalho, cit., p\u00e1g. 798, nota 1. Tamb\u00e9m MARIA DO ROS\u00c1RIO PALMA RAMALHO, Tratado\u2026 cit., pag. 251, refere que actualmente o dep\u00f3sito tem em vista o objectivo de viabilizar o controlo administrativo da regularidade formal da conven\u00e7\u00e3o colectiva.<\/p>\n<p>26. Artigo 356.\u00ba, n.\u00ba 1, da LTFP.<br \/>\nNo \u00e2mbito do direito do trabalho (rela\u00e7\u00f5es laborais privadas) \u00e9 exigida, paralelamente, a publicita\u00e7\u00e3o dos instrumentos de regulamenta\u00e7\u00e3o colectiva, mas atrav\u00e9s da sua publica\u00e7\u00e3o no Boletim do Trabalho e Emprego, s\u00f3 ap\u00f3s o que entram em vigor nos termos da lei, conforme disposto no artigo 519.\u00ba do C\u00f3digo do Trabalho.<\/p>\n<p>27. Quer isto dizer que o ACEP entra em vigor em termos id\u00eanticos aos que ocorrem com a entrada em vigor das normas legais. Quanto a estas, diz o C\u00f3digo Civil (artigo 5.\u00ba) que elas s\u00f3 se tornam obrigat\u00f3rias depois de publicadas no jornal oficial e que entre a publica\u00e7\u00e3o e o in\u00edcio da sua vig\u00eancia decorrer\u00e1 o tempo (vacatio legis) que a pr\u00f3pria lei estabele\u00e7a ou, na falta dessa fixa\u00e7\u00e3o, o que for determinado em legisla\u00e7\u00e3o especial. Nesse sentido, disp\u00f5e-se no artigo 2.\u00ba da Lei n.\u00ba 74\/98, de 11 de Novembro, que os atos legislativos e os outros atos de conte\u00fado gen\u00e9rico entram em vigor no dia neles fixado, n\u00e3o podendo, em caso algum, o in\u00edcio da vig\u00eancia verificar-se no pr\u00f3prio dia da publica\u00e7\u00e3o (n.\u00ba 1) e que na falta de fixa\u00e7\u00e3o do dia, os diplomas referidos no n\u00famero anterior entram em vigor, em todo o territ\u00f3rio nacional e no estrangeiro, no quinto dia ap\u00f3s a publica\u00e7\u00e3o (n.\u00ba 2). Estas s\u00e3o, assim, as regras aplic\u00e1veis aos ACEP, quanto ao seu in\u00edcio de vig\u00eancia.<\/p>\n<p>28. Lei n.\u00ba 74\/98, de 11 de Novembro &#8211; Publica\u00e7\u00e3o, identifica\u00e7\u00e3o e formul\u00e1rio dos diplomas &#8211; alterada pela Lei n.\u00ba 2\/2005, de 24 de Janeiro, Lei n.\u00ba 26\/2006, de 30 de Junho, Lei n.\u00ba 42\/2007, de 24 de Agosto e Lei n.\u00ba 43\/2014, de 11 de Julho.<\/p>\n<p>29. O referido parecer foi homologado por despacho de 26 de Setembro de 2014 do Secret\u00e1rio de Estado da Administra\u00e7\u00e3o P\u00fablica, sendo publicado no Di\u00e1rio da Rep\u00fablica, 2\u00aa s\u00e9rie, n.\u00ba 192, de 6 de Outubro de 2014.<\/p>\n<p>30. Diz-se no introito do Parecer PGR n.\u00ba 9\/2014: Por se terem \u00absuscitado d\u00favidas em mat\u00e9ria de legitimidade para a celebra\u00e7\u00e3o de acordos coletivos de empregador p\u00fablico no caso espec\u00edfico das autarquias locais\u00bb o Secret\u00e1rio de Estado da Administra\u00e7\u00e3o P\u00fablica entendeu colocar ao Conselho Consultivo da PGR as duas seguintes quest\u00f5es para que sobre elas fosse emitido parecer:<br \/>\n1 &#8211; A norma que regulamenta a legitimidade para celebrar acordos coletivos de entidade empregadora p\u00fablica, por parte desta, constante da al\u00ednea b) do n.\u00ba 3 do artigo 347.\u00ba da Lei n.\u00ba 59\/2008, de 11 de setembro, no que diz respeito \u00e0s autarquias locais, pode ser lida, numa interpreta\u00e7\u00e3o conforme \u00e0 Constitui\u00e7\u00e3o, no sentido de implicar que o acordo seja subscrito tamb\u00e9m pelo membro do Governo respons\u00e1vel pela \u00e1rea das finan\u00e7as e da Administra\u00e7\u00e3o P\u00fablica ou deve ser lida com as necess\u00e1rias adapta\u00e7\u00f5es e o acordo deve ser subscrito apenas pela entidade empregadora p\u00fablica aut\u00e1rquica? No caso de o acordo dever ser subscrito pelo membro do Governo respons\u00e1vel pela \u00e1rea das finan\u00e7as e da Administra\u00e7\u00e3o P\u00fablica que poderes em concreto lhe competem na negocia\u00e7\u00e3o desses acordos?<br \/>\n2 &#8211; A interven\u00e7\u00e3o da Administra\u00e7\u00e3o Central nos acordos coletivos de trabalho na administra\u00e7\u00e3o aut\u00e1rquica restringe-se, para al\u00e9m da tutela inspetiva, \u00e0s normas que regulam o dep\u00f3sito previstas nos artigos 356.\u00ba a 358.\u00ba da Lei n.\u00ba 59\/2008, de 11 de setembro?<\/p>\n<p>31. Disp\u00f5e-se no artigo 42.\u00ba, n.\u00ba 1, do Estatuto do Minist\u00e9rio P\u00fablico (Lei n.\u00ba 47\/86, de 15 de Outubro) que quando homologados pelas entidades que os tenham solicitado ou a cujo sector respeite o assunto apreciado, os pareceres do Conselho Consultivo sobre disposi\u00e7\u00f5es de ordem gen\u00e9rica s\u00e3o publicados na 2.\u00aa s\u00e9rie do Di\u00e1rio da Rep\u00fablica para valerem como interpreta\u00e7\u00e3o oficial, perante os respectivos servi\u00e7os, das mat\u00e9rias que se destinam a esclarecer.<\/p>\n<p>32. Of\u00edcios (registados) de 6\/11\/2014. N\u00e3o deixa de ser curiosa e significativa a manifesta diferen\u00e7a de tom entre os of\u00edcios dirigidos aos Secret\u00e1rios de Estado da Administra\u00e7\u00e3o P\u00fablica e das Finan\u00e7as e o que foi dirigido ao sindicato (da mesma data).<\/p>\n<p>33. Como resulta do oficio da c\u00e2mara municipal de 21\/11\/2014.<\/p>\n<p>34. De referir que nesse \u00ednterim, o Secret\u00e1rio de Estado da Administra\u00e7\u00e3o Publica, na sequ\u00eancia da referida remessa para assinatura do ACEP j\u00e1 outorgado pela c\u00e2mara municipal e sindicato, enviou a esta (em 24\/2\/2015) of\u00edcio acompanhado de documento (gen\u00e9rico e geral) contendo um conjunto de fatores a ponderar nas propostas de redu\u00e7\u00e3o do limite m\u00e1ximo do per\u00edodo normal de trabalho (pnt) previsto no art.\u00ba 105.\u00ba da LTFP (8h\/dia, 40h\/semana), \u00e0 luz do que se conclu\u00eda no Parecer da PGR n.\u00ba 9\/2014 de que o processo destinado \u00e0 celebra\u00e7\u00e3o de um acordo coletivo em que, nos termos do disposto no artigo 347.\u00ba, n.\u00ba 3, al\u00ednea b), do RCTFP, t\u00eam necessariamente de intervir, do lado da entidade empregadora p\u00fablica, os membros do Governo respons\u00e1veis pelas \u00e1reas das finan\u00e7as e da Administra\u00e7\u00e3o P\u00fablica e uma autarquia, enquanto entidade empregadora p\u00fablica, apela a uma atua\u00e7\u00e3o conjunta e articulada destas entidades durante todas as fases da sua negocia\u00e7\u00e3o.<br \/>\nTr\u00eas meses depois da sua recep\u00e7\u00e3o (em 8\/6\/2015), esse of\u00edcio mereceu, por parte da C\u00e2mara Municipal uma resposta r\u00edspida, algo deslocada, que n\u00e3o mereceu nenhuma outra resposta do governo at\u00e9 \u00e0 publica\u00e7\u00e3o em Di\u00e1rio da Rep\u00fablica do citado aresto do Tribunal Constitucional, n\u00e3o obstante, entretanto, mas j\u00e1 ap\u00f3s o conhecimento p\u00fablico dessa decis\u00e3o, a c\u00e2mara municipal ter envido novo of\u00edcio, no mesmo tom, a solicitar ao Secret\u00e1rio de Estado da Administra\u00e7\u00e3o P\u00fablica a devolu\u00e7\u00e3o do ACEP.<\/p>\n<p>35. Como se viu, supra, o in\u00edcio de vig\u00eancia d\u00e1-se de acordo com o que seja previsto no ACEP ou, no sil\u00eancio deste, de acordo com o que se encontra previsto para a vig\u00eancia da lei.<\/p>\n<p>36. Como consta do exemplar consult\u00e1vel no site da DGAEP, em http:\/\/www.dgaep.gov.pt\/index.cfm?OBJID=91f17207-d63e-4f78-a525-4e8140f46f49&amp;ID=1884, o ACEP em quest\u00e3o foi depositado em 26 de outubro de 2015, ao abrigo do artigo 368.\u00ba da Lei n.\u00ba 35\/2014, de 20 de junho, sob o n.\u00ba 123\/ 2015, a fls. 50 do Livro n.\u00ba 1.<br \/>\nSobre o dep\u00f3sito de conven\u00e7\u00f5es colectivas, diz MARIA DO ROS\u00c1RIO PALMA RAMALHO, Tratado\u2026 cit., pag. 250: Uma conven\u00e7\u00e3o colectiva n\u00e3o depositada n\u00e3o pode valer como instrumento de regulamenta\u00e7\u00e3o colectiva de trabalho em sentido pr\u00f3prio, porque a opera\u00e7\u00e3o de dep\u00f3sito condiciona a entrada em vigor da conven\u00e7\u00e3o. Caso n\u00e3o seja depositada, a conven\u00e7\u00e3o ser\u00e1 um instrumento de regulamenta\u00e7\u00e3o colectiva de trabalho at\u00edpica, com valor puramente negocial.<\/p>\n<p>37. Di\u00e1rio da Rep\u00fablica, 2.\u00aa s\u00e9rie, n.\u00ba 220, de 10 de Novembro de 2015, pags. 32506-32509.<\/p>\n<p>38. Vd. o referido na nota 24 supra.<\/p>\n<p>39. Nesse sentido, JOAQUIM GOMES CANOTILHO e VITAL MOREIRA, Constitui\u00e7\u00e3o da Rep\u00fablica Portuguesa Anotada, vol. II, 4.\u00aa edi\u00e7\u00e3o, reimpress\u00e3o, 2014, anota\u00e7\u00e3o ao art.\u00ba 282.\u00ba, pag. 975.<\/p>\n<p>40. Artigo 355.\u00ba, n.\u00ba 2, al. c), da LTFP.<\/p>\n<p>41. Estar-se-\u00e1 aqui perante aquilo que a doutrina italiana classifica como de senten\u00e7a redutiva, na vers\u00e3o de inconstitucionalidade parcial com redu\u00e7\u00e3o do texto.<br \/>\nSobre os efeitos da declara\u00e7\u00e3o de inconstitucionalidade com for\u00e7a obrigat\u00f3ria geral, vd. RICARDO BRANCO, O efeito aditivo da declara\u00e7\u00e3o de inconstitucionalidade com for\u00e7a obrigat\u00f3ria geral, 2009, p\u00e1g. 67 e seg..<\/p>\n<p>42. Da\u00ed resultava que nunca seria admitido o seu dep\u00f3sito, por n\u00e3o se encontrar verificado o requisito constante da al. a) do n.\u00ba 4 do artigo 368.\u00ba da LTFP.<\/p>\n<p>43. Vd. supra, p\u00e1gs. 11-12 e notas 24 e 25.<\/p>\n<p>44. Artigo 368.\u00ba, n.\u00ba 4, al. a), da LTFP.<\/p>\n<p>45. Para que as decis\u00f5es do Tribunal Constitucional sejam obrigat\u00f3rias para todas as entidades p\u00fablicas e privadas e prevale\u00e7am sobre as dos restantes tribunais e de quaisquer outras autoridades (artigo 2.\u00ba da Lei n.\u00ba 28\/82, de 15 de Novembro \u2013 Organiza\u00e7\u00e3o, Funcionamento e Processo do Tribunal Constitucional \u2013 alterada pela Lei n.\u00ba 143\/85, de 26 de Novembro, Lei n.\u00ba 85\/89, de 7 de Setembro, Lei n.\u00ba 88\/95, de 1 de Setembro, Lei n.\u00ba 13-A\/98, de 26 de Fevereiro, Lei Org\u00e2nica n.\u00ba 1\/2011, de 30 de Novembro, Lei Org\u00e2nica n.\u00ba 5\/2015, de 10 de Abril e Lei Org\u00e2nica n.\u00ba 11\/2015, de 28 de Agosto), maxime, os ac\u00f3rd\u00e3os prolatados em sede de fiscaliza\u00e7\u00e3o sucessiva abstracta da constitucionalidade, necess\u00e1rio se torna que estes sejam objecto de publica\u00e7\u00e3o na 1\u00aa s\u00e9rie do Di\u00e1rio da Rep\u00fablica (artigo 3.\u00ba, n.\u00ba 1, al. a), da Lei n.\u00ba 28\/82, e artigo 3.\u00ba, n.\u00ba 2, al. h), da Lei n.\u00ba 74\/98), pois que, nos termos do artigo 1.\u00ba, n.\u00ba 1, da Lei n.\u00ba 74\/98 a efic\u00e1cia jur\u00eddica dos actos que nela s\u00e3o referidos encontra-se dependente da sua publica\u00e7\u00e3o no Di\u00e1rio da Rep\u00fablica.<\/p>\n<p>46. Vd. nota 24, supra.<\/p>\n<p>47. Quer o pedido de parecer quer a informa\u00e7\u00e3o n\u00e3o referem a que t\u00edtulo nem qual o valor por que deveria ser paga essa hora de trabalho \u201ca mais\u201d prestada no per\u00edodo em quest\u00e3o.<br \/>\nO facto de ser dito que eram exclu\u00eddos do pagamento as horas (rectius, a hora di\u00e1ria \u201ca mais\u201d) correspondentes aos per\u00edodos de f\u00e9rias e faltas, d\u00e1 ideia que estaria subjacente a ideia de que essas horas constituiriam trabalho extraordin\u00e1rio.<br \/>\nPor\u00e9m, para que o pagamento do trabalho extraordin\u00e1rio possa ser exig\u00edvel, necess\u00e1rio se torna que ele tenha sido pr\u00e9via e expressamente autorizado (artigo 162.\u00ba, n.\u00ba 5, da LTFP) ou que se verifique uma das situa\u00e7\u00f5es que permitem a dispensa dessa autoriza\u00e7\u00e3o (artigo 162.\u00ba, n.\u00ba 6, da LTFP) &#8211; o que n\u00e3o ser\u00e1 o caso na situa\u00e7\u00e3o em apre\u00e7o. Por outro lado tamb\u00e9m n\u00e3o resulta claro como se calcularia o valor da hora de trabalho pelo qual haveriam de ser remuneradas as horas em causa.<\/p>\n<p>48. Por isso n\u00e3o se descortina raz\u00e3o para que possa ter sido veiculado como constituindo entendimento legal e juridicamente v\u00e1lido, primeiro, que os ACEP se encontram em vigor, desde as respectivas datas de assinatura nos termos da lei \u2013 porque a lei (maxime, a LTFP) em local algum prev\u00ea ou estatui um tal efeito \u2013 e, em seguida, que os ACEP assinados sem a participa\u00e7\u00e3o do secret\u00e1rio de Estado da Administra\u00e7\u00e3o P\u00fablica encontram-se em vigor desde a data em que o dep\u00f3sito deveria ter ocorrido, ou seja, 15 dias \u00fateis ap\u00f3s o seu envio para a DGAEP \u2013 porque em nenhum local a lei prev\u00ea e admite tal fic\u00e7\u00e3o, para al\u00e9m de que, de todo o modo, ocorresse quando ocorresse o dep\u00f3sito, seria ainda necess\u00e1ria a publica\u00e7\u00e3o do ACEP em Di\u00e1rio da Rep\u00fablica para que este pudesse entrar em vigor, como se prev\u00ea na lei e nele mesmo \u2013 pelo que a conclus\u00e3o tirada do antes afirmado, de que todos os empregadores p\u00fablicos que assinaram ACEP com o STAL, e que continuaram a praticar 40 horas semanais e 8 horas di\u00e1rias, ter\u00e3o que ressarcir os trabalhadores em 5 horas de trabalho extraordin\u00e1rio semanal, desde a assinatura do acordo, e at\u00e9 \u00e0 sua efectiva entrada em vigor, carece, obviamente, de qualquer fundamento jur\u00eddico-legal.<\/p>\n<p>49. Lei n.\u00ba 29\/87, de 30 de Junho, alterada pela Lei n.\u00ba 97\/89, de 15 de Dezembro, Lei n.\u00ba 1\/91, de 10 de Janeiro, Lei n.\u00ba 11\/91, de 17 de Maio, Lei n.\u00ba 11\/96, de 18 de Abril, Lei n.\u00ba 127\/97, de 11 de Dezembro, Lei n.\u00ba 50\/99, de 24 de Junho, Lei n.\u00ba 86\/2001, de 10 de Agosto, Lei n.\u00ba 22\/2004, de 17 de Junho, Lei n.\u00ba 52-A\/2005, de 10 de Outubro, e Lei n.\u00ba 53-F\/2006, de 29 de Dezembro.<\/p>\n<p>50. Artigo 220.\u00ba, n.\u00ba 1 da Lei Eleitoral dos \u00d3rg\u00e3os das Autarquias Locais (LEOAL), aprovada pela Lei Org\u00e2nica n.\u00ba 1\/2001, de 14 de Agosto, rectificada pela Declara\u00e7\u00e3o de Rectifica\u00e7\u00e3o n.\u00ba 20-A\/2001, de 12 de Outubro, e alterada pela Lei Org\u00e2nica n.\u00ba 5-A\/2001, de 26 de Novembro; Lei Org\u00e2nica n.\u00ba 3\/2005, de 29 de Agosto, Lei Org\u00e2nica n.\u00ba 3\/2010, de 15 de Dezembro, Lei Org\u00e2nica n.\u00ba 1\/2011, de 30 de Novembro, e Lei n.\u00ba 72-A\/2015, de 23 de Julho.<\/p>\n<p>51. A Constitui\u00e7\u00e3o prev\u00ea a exist\u00eancia, nas autarquias locais, de dois \u00f3rg\u00e3os &#8211; uma assembleia eleita dotada de poderes deliberativos e um \u00f3rg\u00e3o executivo colegial perante ela respons\u00e1vel (artigo 239.\u00ba, n.\u00ba 1, da CRP) \u2013\u00ac para os quais estabelece desde logo a elei\u00e7\u00e3o como modo de designa\u00e7\u00e3o dos respectivos titulares \u2013 a assembleia \u00e9 eleita por sufr\u00e1gio universal, directo e secreto dos cidad\u00e3os recenseados na \u00e1rea da respectiva autarquia (artigo 239.\u00ba, n.\u00ba 2, da CRP) e o \u00f3rg\u00e3o executivo colegial \u00e9 constitu\u00eddo por um n\u00famero adequado de membros, sendo designado presidente o primeiro candidato da lista mais votada para a assembleia ou para o executivo, de acordo com a solu\u00e7\u00e3o adoptada na lei, a qual regular\u00e1 tamb\u00e9m o processo eleitoral (artigo 239.\u00ba, n.\u00ba 3, da CRP).<br \/>\nE assim, o artigo 1.\u00ba da LEOAL afirma que esta regula a elei\u00e7\u00e3o de titulares para os \u00f3rg\u00e3os das autarquias locais.<\/p>\n<p>52. Artigo 225.\u00ba da LEOAL.<\/p>\n<p>53. De referir tamb\u00e9m que quer a Lei n.\u00ba 64\/93, de 26 de Agosto, que estabelece o Regime jur\u00eddico de incompatibilidades e impedimentos dos titulares de cargos pol\u00edticos e altos cargos p\u00fablicos, quer a a Lei n.\u00ba 4\/83, de 2 de Abril, sobre Controle p\u00fablico da riqueza de titulares de cargos pol\u00edticos, ambas com posteriores altera\u00e7\u00f5es, consideram os presidentes e vereadores as c\u00e2maras municipais como titulares de cargos pol\u00edticos.<\/p>\n<p>54. Dizem os n\u00fameros em quest\u00e3o do artigo 1.\u00ba da LTFP:<br \/>\n2 &#8211; A presente lei \u00e9 aplic\u00e1vel \u00e0 administra\u00e7\u00e3o direta e indireta do Estado e, com as necess\u00e1rias adapta\u00e7\u00f5es, designadamente no que respeita \u00e0s compet\u00eancias em mat\u00e9ria administrativa dos correspondentes \u00f3rg\u00e3os de governo pr\u00f3prio, aos servi\u00e7os da administra\u00e7\u00e3o regional e da administra\u00e7\u00e3o aut\u00e1rquica.<br \/>\n3 &#8211; A presente lei \u00e9 tamb\u00e9m aplic\u00e1vel, com as adapta\u00e7\u00f5es impostas pela observ\u00e2ncia das correspondentes compet\u00eancias, aos \u00f3rg\u00e3os e servi\u00e7os de apoio do Presidente da Rep\u00fablica, dos tribunais e do Minist\u00e9rio P\u00fablico e respetivos \u00f3rg\u00e3os de gest\u00e3o e outros \u00f3rg\u00e3os independentes.<br \/>\n4 &#8211; Sem preju\u00edzo de regimes especiais e com as adapta\u00e7\u00f5es impostas pela observ\u00e2ncia das correspondentes compet\u00eancias, a presente lei \u00e9 ainda aplic\u00e1vel aos \u00f3rg\u00e3os e servi\u00e7os de apoio \u00e0 Assembleia da Rep\u00fablica.<\/p>\n<p>55. O Regime Jur\u00eddico das Autarquias Locais (RJAL) foi aprovado em anexo \u00e0 Lei n.\u00ba 75\/2013, de 12 de Setembro, rectificada pelas Declara\u00e7\u00f5es de Retifica\u00e7\u00e3o n.\u00ba 46-C\/2013, de 01 de Novembro, e n.\u00ba 50 A\/2013, de 11 de Novembro e alterada pela Lei n.\u00ba 25\/2015, de 30 de Mar\u00e7o e Lei n.\u00ba 69\/2015, de 16 de Julho.<\/p>\n<p>56. Artigo 42.\u00ba, n.\u00ba 1, do RJAL.<\/p>\n<p>57. Artigo 42.\u00ba, n.\u00bas 2 e 3, do RJAL.<\/p>\n<p>58. Artigo 43.\u00ba, n.\u00ba 4, do RJAL.<\/p>\n<p>59. Artigo 43.\u00ba, n.\u00ba 4, do RJAL.<\/p>\n<p>60. Artigo 43.\u00ba, n.\u00bas 1, 2 e 3, do RJAL.<\/p>\n<p>61. Do que resulta que tamb\u00e9m n\u00e3o lhes \u00e9 aplic\u00e1vel a tabela remunerat\u00f3ria \u00fanica dos trabalhadores que exercem fun\u00e7\u00f5es p\u00fablicas, constante da Portaria n.\u00ba 1553-C\/2008, de 31 de Dezembro.<\/p>\n<p>62. Artigo 43.\u00ba, n.\u00ba 5, do RJAL.<\/p>\n<p>63. Artigo 13.\u00ba, n.\u00ba 2, do Decreto-Lei n.\u00ba 11\/2012.<\/p>\n<p>64. Artigo 13.\u00ba, n.\u00ba 3, do Decreto-Lei n.\u00ba 11\/2012.<\/p>\n<p>65. O artigo 5.\u00ba, al. d), da LTFP, remete para diploma pr\u00f3prio [a defini\u00e7\u00e3o d]os estatutos do pessoal dirigente da Administra\u00e7\u00e3o Publica (EPD). \u00c9 esse diploma a Lei n.\u00ba 2\/2004, de 15 de Janeiro, com as altera\u00e7\u00f5es da Lei n.\u00ba 51\/2005, de 30 de Agosto, Lei n.\u00ba 64-A\/2008, de 31 de Dezembro, Lei n.\u00ba 3-B\/2010, de 28 de Abril, Lei n.\u00ba 64\/2011, de 22 de Dezembro, Lei n.\u00ba 68\/2013, de 29 de Agosto, Lei n.\u00ba 128\/2015, de 3 de Setembro.<\/p>\n<p>66. Artigo 1.\u00ba, n.\u00ba 4, do EPD.<\/p>\n<p>67. Artigo 6.\u00ba, n.\u00ba 3, al. c), da LTFP.<\/p>\n<p>68. Artigo 9.\u00ba, n.\u00ba 1, al. a), da LTFP.<\/p>\n<p>69. Artigo 2.\u00ba, n.\u00ba 1, da Lei n.\u00ba 49\/2012.<\/p>\n<p>70. Esta aplicabilidade \u00e9, tamb\u00e9m ela, uma decorr\u00eancia do princ\u00edpio da aplicabilidade aos funcion\u00e1rios da administra\u00e7\u00e3o local do regime dos funcion\u00e1rios do Estado, previsto no artigo 243.\u00ba, n.\u00ba 2 da Constitui\u00e7\u00e3o.<\/p>\n<\/div>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_eb_attr":"","inline_featured_image":false,"iawp_total_views":22,"footnotes":""},"categories":[357],"tags":[187],"class_list":["post-40906","post","type-post","status-publish","format-standard","hentry","category-pareceres-ate-2017","tag-text-layout"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ccdrc.pt\/pt\/wp-json\/wp\/v2\/posts\/40906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ccdrc.pt\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ccdrc.pt\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ccdrc.pt\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ccdrc.pt\/pt\/wp-json\/wp\/v2\/comments?post=40906"}],"version-history":[{"count":1,"href":"https:\/\/www.ccdrc.pt\/pt\/wp-json\/wp\/v2\/posts\/40906\/revisions"}],"predecessor-version":[{"id":40907,"href":"https:\/\/www.ccdrc.pt\/pt\/wp-json\/wp\/v2\/posts\/40906\/revisions\/40907"}],"wp:attachment":[{"href":"https:\/\/www.ccdrc.pt\/pt\/wp-json\/wp\/v2\/media?parent=40906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ccdrc.pt\/pt\/wp-json\/wp\/v2\/categories?post=40906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ccdrc.pt\/pt\/wp-json\/wp\/v2\/tags?post=40906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}