{"id":41407,"date":"2023-10-25T11:25:31","date_gmt":"2023-10-25T11:25:31","guid":{"rendered":"http:\/\/www.ccdrc.pt\/?p=41407"},"modified":"2023-10-26T13:32:20","modified_gmt":"2023-10-26T13:32:20","slug":"servicos-municipalizados-contrato-de-fornecimento-de-agua-falta-de-pagamento-execucao-fiscal-recusa-de-ligacao-por-existencia-de-dividas","status":"publish","type":"post","link":"https:\/\/www.ccdrc.pt\/en\/servicos-municipalizados-contrato-de-fornecimento-de-agua-falta-de-pagamento-execucao-fiscal-recusa-de-ligacao-por-existencia-de-dividas\/","title":{"rendered":"Servi\u00e7os Municipalizados. Contrato de fornecimento de \u00e1gua. Falta de pagamento. Execu\u00e7\u00e3o fiscal. Recusa de liga\u00e7\u00e3o por exist\u00eancia de d\u00edvidas."},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1288px;margin-left: calc(-0% \/ 2 );margin-right: calc(-0% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:0%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:0%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:0%;--awb-spacing-left-medium:0%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:0%;--awb-spacing-left-small:0%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><div class=\"searchbox\">\n<div class=\"value\">Data:&nbsp;&nbsp;<strong>ter\u00e7a, 23 maio 2006<\/strong><\/div>\n<div class=\"value\">N\u00famero:&nbsp;<strong>140\/2006<\/strong><\/div>\n<div class=\"value\">Respons\u00e1veis:&nbsp;&nbsp;<strong>Ricardo da Veiga Ferr\u00e3o<\/strong><\/div>\n<\/div>\n<div class=\"article_content\">\n<div class=\"fulltext\">\n<p align=\"justify\">Solicitam os Servi\u00e7os Municipalizados, a emiss\u00e3o de parecer sobre as quest\u00f5es que seguidamente se transcrevem:<\/p>\n<div align=\"justify\">&nbsp;<\/div>\n<p align=\"justify\">Os SMAS de t\u00eam vindo a confrontar-se com um n\u00famero cada vez mais elevado de facturas n\u00e3o atempadamente liquidadas.<br \/>\nTal situa\u00e7\u00e3o tem motivado, ap\u00f3s aviso pr\u00e9vio, a interrup\u00e7\u00e3o do fornecimento de \u00e1gua.<br \/>\nMas quanto \u00e0 cobran\u00e7a das d\u00edvidas tem-se suscitado a quest\u00e3o de saber se o procedimento correcto a seguir \u00e9 o de extrair certid\u00e3o de d\u00edvida para efeitos de execu\u00e7\u00e3o fiscal pela C\u00e2mara Municipal, ou se tais d\u00edvidas t\u00eam de ser exigidas judicialmente.<br \/>\nAcresce que em muitas situa\u00e7\u00f5es os contratos de fornecimento de \u00e1gua s\u00e3o celebrados com determinado inquilino que sai do local e n\u00e3o paga aos SMAS, sendo que o senhorio celebra novo contrato com outro inquilino.<br \/>\nPoder\u00e3o os SMAS recusar legalmente o fornecimento de \u00e1gua ao novo inquilino, at\u00e9 que seja resolvido o contrato existente?<br \/>\nE isto com o fundamento da liga\u00e7\u00e3o ser a mesma \u00e0 rede p\u00fablica?<br \/>\nE poder\u00e3o faz\u00ea-lo se tal estiver previsto expressamente no regulamento de fornecimento de \u00e1gua?<\/p>\n<p align=\"justify\">I<\/p>\n<ol>\n<li>\n<div align=\"justify\">O abastecimento p\u00fablico de \u00e1gua \u00e9 considerado pela lei como um servi\u00e7o p\u00fablico essencial, estando por isso sujeito a um especial regime de garantias para os seus utentes(1).A lei(2) estabelece, desde logo, que os sistemas p\u00fablicos de distribui\u00e7\u00e3o de \u00e1gua p\u00fablica e predial devem ser geridos por uma \u201centidade gestora\u201d que \u00e9 a respons\u00e1vel pela sua concep\u00e7\u00e3o, constru\u00e7\u00e3o e explora\u00e7\u00e3o.A responsabilidade da gest\u00e3o dos sistemas p\u00fablicos de distribui\u00e7\u00e3o de \u00e1gua cabe, nos termos da lei, ao Estado, aos munic\u00edpios e \u00e0s associa\u00e7\u00f5es de munic\u00edpios, podendo contudo ser tamb\u00e9m atribu\u00edda a outras entidades em regime de concess\u00e3o(3).<\/div>\n<\/li>\n<li>\n<div align=\"justify\">Temos assim que a distribui\u00e7\u00e3o p\u00fablica e predial de \u00e1gua est\u00e1 cometida, em primeira linha, por raz\u00e3o da sua natureza, ao Estado e aos munic\u00edpios e\/ou suas associa\u00e7\u00f5es.Por\u00e9m \u00e9 poss\u00edvel que essas actividades sejam \u201ccometidas\u201d ou \u201ctransferidas\u201d para outras entidades, de car\u00e1cter societ\u00e1rio ou empresarial, integrando o sector p\u00fablico empresarial \u2013 as empresas p\u00fablicas municipais ou intermunicipais \u2013 ou o sector privado \u2013 aqui atrav\u00e9s de contratos de concess\u00e3o.<\/div>\n<\/li>\n<li>\n<div align=\"justify\">Nos casos em que os munic\u00edpios persistam em, eles mesmos, assegurar aquela gest\u00e3o, podem faz\u00ea-lo atrav\u00e9s de entidades pr\u00f3prias, resultantes da municipaliza\u00e7\u00e3o (ou empresarializa\u00e7\u00e3o) dos competentes servi\u00e7os, a fim de levar a cabo a explora\u00e7\u00e3o industrial(4) dos servi\u00e7os prestados, criando-se ent\u00e3o os designados servi\u00e7os municipalizados.Na realidade, os servi\u00e7os municipalizados s\u00e3o verdadeiras empresas p\u00fablicas municipais que, n\u00e3o tendo personalidade jur\u00eddica, est\u00e3o integradas na pessoa colectiva munic\u00edpio; ali\u00e1s a legisla\u00e7\u00e3o vigente n\u00e3o os considera empresas p\u00fablicas para todos os efeitos(5).<\/div>\n<\/li>\n<li>\n<div align=\"justify\">\u00c9 sabido \u2013 ao menos de experi\u00eancia pr\u00f3pria \u2013 que o abastecimento de \u00e1gua n\u00e3o \u00e9, nem pode ser, gratuito, ao menos porque s\u00f3 o abastecimento em si mesmo gera encargos, a ser satisfeitos pelos benefici\u00e1rios do servi\u00e7o.Por\u00e9m, nos tempos que correm os recursos h\u00eddricos \u2013 at\u00e9 hoje sempre considerados um bem inesgot\u00e1vel (e, tamb\u00e9m por isso, de algum modo um bem \u201cn\u00e3o econ\u00f3mico\u201d), s\u00e3o cada vez mais um bem escasso e por tal, transformam-se agora num verdadeiro (e precioso) \u201cbem econ\u00f3mico\u201d, com maior valor a cada dia que passa.<\/div>\n<ol>\n<li>\n<div align=\"justify\">O C\u00f3digo Administrativo determinava j\u00e1, \u00e0 sua \u00e9poca, que pela presta\u00e7\u00e3o dos servi\u00e7os de fornecimento de \u00e1gua domicili\u00e1ria deveriam ser fixadas tarifas(6).<\/div>\n<\/li>\n<li>\n<div align=\"justify\">Actualmente, a Lei das Finan\u00e7as Locais elenca de entre as receitas dos munic\u00edpios o produto da cobran\u00e7a de taxas, tarifas e pre\u00e7os resultantes da presta\u00e7\u00e3o de servi\u00e7os pelo munic\u00edpio(7), sendo que as tarifas e pre\u00e7os a cobrar respeitam \u2026 \u00e0s actividades de explora\u00e7\u00e3o de sistemas p\u00fablicos de \u2026 distribui\u00e7\u00e3o de \u00e1gua(8).Estas tarifas e pre\u00e7os \u2013 devidas pela presta\u00e7\u00e3o de servi\u00e7os pelos servi\u00e7os municipais ou municipalizados e a ser pagas pelos utentes \u2013 s\u00e3o fixadas pela C\u00e2mara Municipal(9) e n\u00e3o devem, em princ\u00edpio ser inferiores aos custos directa e indirectamente suportados com o fornecimento dos bens e com a presta\u00e7\u00e3o do servi\u00e7os(10).<\/div>\n<\/li>\n<\/ol>\n<\/li>\n<li>\n<div align=\"justify\">Qual a natureza jur\u00eddica destas tarifas, previstas no artigo 20\u00ba da Lei da Finan\u00e7as Locais?<br \/>\nDever\u00e3o ser consideradas como se de verdadeiros pre\u00e7os se tratassem? Ou ser\u00e3o antes taxas?N\u00e3o sendo quest\u00e3o pac\u00edfica na generalidade da doutrina, pode contudo sustentar-se que as tarifas descritas nesse normativo integram o conceito de taxa lato sensu.Assim essas tarifas, entendidas no sentido de pre\u00e7os p\u00fablicos(11), s\u00e3o taxas lato sensu devidas pela presta\u00e7\u00e3o de servi\u00e7os p\u00fablicos \u2013 assim preenchendo um dos pressupostos do n\u00ba 2 do artigo 4\u00ba da Lei Geral Tribut\u00e1ria para a cria\u00e7\u00e3o de taxas: a presta\u00e7\u00e3o concreta de um servi\u00e7o p\u00fablico.<br \/>\nO que distingue as taxas stricto sensu das tarifas \u00e9 que estas \u00faltimas, por um lado, correspondem a bens e servi\u00e7os que n\u00e3o s\u00e3o por ess\u00eancia da titularidade do Estado, de acordo com a concep\u00e7\u00e3o pol\u00edtica dominante numa determinada sociedade, e, por outro lado, serem suscept\u00edveis de avalia\u00e7\u00e3o em termos de mercado, de modo que o seu montante n\u00e3o \u00e9 independente do crit\u00e9rio objectivo por que se rege a forma\u00e7\u00e3o dos correspondentes pre\u00e7os. Pelo que as tarifas se apresentam como taxas em que entre elas e as correspondentes contrapresta\u00e7\u00f5es espec\u00edficas se verifica n\u00e3o s\u00f3 uma equival\u00eancia jur\u00eddica, como \u00e9 caracter\u00edstica de todas as taxas, mas tamb\u00e9m uma equival\u00eancia econ\u00f3mica(12).\u00c9 precisamente esta equival\u00eancia econ\u00f3mica que se encontra reflectida na acima referida norma da Lei das Finan\u00e7as Locais que determina que as tarifas n\u00e3o devem, em princ\u00edpio ser inferiores aos custos directa e indirectamente suportados com o fornecimento dos bens e com a presta\u00e7\u00e3o do servi\u00e7os, o que as aproxima do conceito de pre\u00e7o.Por\u00e9m, j\u00e1 se afastam do conceito de pre\u00e7o e se aproximam do de taxas no que toca \u00e0 sua fixa\u00e7\u00e3o, que n\u00e3o resulta de um \u201cacordo de vontades\u201d mas sim de um acto de autoridade, como resulta do disposto na al\u00ednea j) do n\u00ba 1 do artigo 64\u00ba da Lei n\u00ba 169\/99 e tamb\u00e9m do n\u00ba 3 do artigo 20\u00ba da LFL(13).<\/div>\n<\/li>\n<li>\n<div align=\"justify\">Ora sendo considerada taxa lato sensu \u2013 e por isso, uma receita (de natureza) tribut\u00e1ria \u2013 qual o processo a seguir para a cobran\u00e7a coerciva destas tarifas?<\/div>\n<ol>\n<li>\n<div align=\"justify\">&nbsp;No que se refere \u00e0s tarifas cobradas pelos Servi\u00e7os Municipalizados pelo fornecimento p\u00fablico de \u00e1gua domicili\u00e1ria, tratando-se, como j\u00e1 se viu, de receitas de natureza tribut\u00e1ria, cabe aos competentes \u00f3rg\u00e3os executivos a cobran\u00e7a coerciva dessas d\u00edvidas, aplicando-se para o efeito o C\u00f3digo do Procedimento e Processo Tribut\u00e1rio. \u00c9 o que disp\u00f5e o n\u00ba 4 do artigo 30\u00ba da LFL(14).A este prop\u00f3sito h\u00e1 que referir ainda que o Decreto-Lei n\u00ba 433\/99, de 26 de Outubro, que aprovou o C\u00f3digo de Procedimento e Processo Tribut\u00e1rio, determina que as compet\u00eancias atribu\u00eddas no c\u00f3digo aprovado pelo presente diploma a \u00f3rg\u00e3os perif\u00e9ricos locais ser\u00e3o exercidas, nos termos da lei, em caso de tributos administrados por autarquias locais, pela respectiva autarquia(15). Ora esses \u00abservi\u00e7os perif\u00e9ricos locais\u00bb constituem precisamente os \u00ab\u00f3rg\u00e3os da execu\u00e7\u00e3o fiscal\u00bb pelos quais deve \u00ablegalmente correr a execu\u00e7\u00e3o\u00bb, como disp\u00f5e o artigo 149\u00ba do CPPT.<\/div>\n<\/li>\n<li>\n<div align=\"justify\">Resposta diferente merecer\u00e1, por\u00e9m, a situa\u00e7\u00e3o em que sejam empresas municipais as respons\u00e1veis por tais fornecimentos.Neste caso, por for\u00e7a do disposto no n\u00ba 1 do artigo 39\u00ba da Lei n\u00ba 58\/99 de 18 de Agosto(16) (e tamb\u00e9m por via do n\u00ba 2 do artigo 18\u00ba do Decreto-Lei n\u00ba 558\/99, de 17 de Dezembro(17), aplic\u00e1vel ex vi do artigo 5\u00ba do mesmo diploma) caber\u00e1 aos tribunais comuns a cobran\u00e7a coerciva das d\u00edvidas provenientes dos seus fornecimentos(18).<\/div>\n<\/li>\n<li>\n<div align=\"justify\">Temos assim que, constituindo-se como d\u00edvida de natureza tribut\u00e1ria a que resulta do n\u00e3o pagamento, em tempo, aos Servi\u00e7os Municipalizados das tarifas devidas pelo fornecimento publico de \u00e1gua ao domicilio, cabe aos \u00f3rg\u00e3os executivos municipais competentes(19) proceder a essa execu\u00e7\u00e3o, nos termos definidos no CPPT.<\/div>\n<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<p align=\"justify\">&nbsp;<\/p>\n<p align=\"justify\">II<\/p>\n<ol>\n<li>\n<div align=\"justify\">No que toca \u00e0 utiliza\u00e7\u00e3o de \u201coutras formas\u201d \u201cinjuntivas\u201d ou \u201cde press\u00e3o\u201d para levar ao pagamento dos montantes em d\u00edvida, tal n\u00e3o \u00e9, de todo, poss\u00edvel, por juridicamente inadmiss\u00edvel.Na verdade n\u00e3o \u00e9 juridicamente admiss\u00edvel negar o fornecimento de \u00e1gua a um mun\u00edcipe com a justifica\u00e7\u00e3o de que o anterior ocupante do mesmo local n\u00e3o pagou as suas contas da \u00e1gua(20) e\/ou condicionar esse fornecimento ao pr\u00e9vio pagamento das quantias em d\u00edvida.Ainda que essa possibilidade esteja prevista em regulamento \u201cdevidamente\u201d aprovado, isso n\u00e3o a transforma numa actua\u00e7\u00e3o \u201clegal\u201d \u2013 torna, sim, o regulamente, nessa parte, \u201cilegal\u201d.<br \/>\nDesde logo, porque est\u00e1 em causa o fornecimento de um \u201cbem essencial \u00e0 vida\u201d e nesse sentido, a Constitui\u00e7\u00e3o assegura um conjunto de direitos que visam a protec\u00e7\u00e3o de uma vida com as necess\u00e1rias condi\u00e7\u00f5es humanas, de sa\u00fade e de qualidade ambiental (artigos 64\u00ba, 65\u00ba e 66\u00ba), para a efectiva\u00e7\u00e3o dos quais o acesso ao fornecimento de \u00e1gua \u00e9 essencial. N\u00e3o pode, assim, o acesso ao consumo da \u00e1gua e \u00e0s condi\u00e7\u00f5es ambientais e de qualidade de vida por ela proporcionadas estar sujeita a uma pura l\u00f3gica de protec\u00e7\u00e3o empresarial, orientada por meios de press\u00e3o sobre os consumidores que ultrapassem a exigibilidade do estrito cumprimento dos seus contratos(21).Porque se est\u00e1 perante uma rela\u00e7\u00e3o \u201ccontratual\u201d, ali\u00e1s como disp\u00f5e o n\u00ba 1 do artigo 18\u00ba do Decreto-Lei n\u00ba 207\/94 \u2013 ao menos quanto a este aspecto \u2013 n\u00e3o \u00e9 poss\u00edvel fazer reverter sobre terceiros, absolutamente estranhos a ela, os efeitos dessa rela\u00e7\u00e3o, designadamente os que se referem \u00e0s consequ\u00eancias do seu incumprimento.<\/div>\n<\/li>\n<li>\n<div align=\"justify\">Uma solu\u00e7\u00e3o t\u00e9cnica \u2013 que n\u00e3o jur\u00eddica \u2013 ser\u00e1 a de tentar adoptar, sempre que poss\u00edvel \u2013 tamb\u00e9m n\u00e3o pode constituir solu\u00e7\u00e3o \u201cimposta\u201d \u2013 a adop\u00e7\u00e3o do pagamento atrav\u00e9s de \u201cd\u00e9bito directo em conta\u201d. \u00c9 eficaz&#8230; desde que a conta banc\u00e1ria v\u00e1 tendo provis\u00e3o&#8230;.<\/div>\n<\/li>\n<\/ol>\n<p align=\"justify\">&nbsp;<\/p>\n<p align=\"justify\">III<\/p>\n<ol>\n<li>\n<div align=\"justify\">Pode-se assim concluir que, por se tratar de \u201creceitas de natureza tribut\u00e1ria\u201d, o pagamento coercivo das tarifas em d\u00e9bito, cobradas pelos servi\u00e7os municipalizados pelo fornecimento p\u00fablico domicili\u00e1rio de \u00e1gua, deve ser efectuado em sede de execu\u00e7\u00e3o fiscal, pelos competentes servi\u00e7os da c\u00e2mara municipal.<\/div>\n<\/li>\n<li>\n<div align=\"justify\">N\u00e3o \u00e9 juridicamente admiss\u00edvel, quer por se estar perante uma rela\u00e7\u00e3o sinalagm\u00e1tica, quer por se tratar de um fornecimento (ali\u00e1s monopol\u00edstico) de um bem essencial \u00e0 vida(22), condicionar o fornecimento de \u00e1gua a determinado local ao pr\u00e9vio pagamento de todas as d\u00edvidas que existam relativas a anteriores fornecimentos de \u00e1gua a esse mesmo local por for\u00e7a de contratos titulados por terceiras pessoas, ainda que essa possibilidade ou mecanismo se encontre prevista em regulamento.<\/div>\n<\/li>\n<\/ol>\n<blockquote>\n<ul>\n<li>\n<div align=\"justify\">(1) A Lei n\u00ba 23\/96, de 26 de Julho, veio estabelecer alguns \u00abmecanismos destinados a proteger o utente de servi\u00e7os p\u00fablicos essenciais\u00bb, sendo que um destes \u00e9 o servi\u00e7o de fornecimento de \u00e1gua [al\u00ednea a) do n\u00ba 2 do artigo 1\u00ba].<\/div>\n<\/li>\n<li>\n<div align=\"justify\">(2) Decreto-Lei n\u00ba 207\/94, de 8 de Agosto, artigo 1\u00ba e n\u00ba 1 do artigo 3\u00ba.<\/div>\n<\/li>\n<li>\n<div align=\"justify\">(3) N\u00ba 2 do artigo 3\u00ba do Decreto-Lei n\u00ba 207\/94.<\/div>\n<\/li>\n<li>\n<div align=\"justify\">(4) No dizer do artigo 164\u00ba do C\u00f3digo Administrativo.<\/div>\n<\/li>\n<li>\n<div align=\"justify\">(5) Cfr. FREITAS DO AMARAL, Curso de Direito Administrativo, 2\u00aa edi\u00e7\u00e3o, pag. 500 e seg. e tamb\u00e9m pag. 358 e seg.<\/div>\n<\/li>\n<li>\n<div align=\"justify\">(6) \u00c9 do seguinte teor o corpo do artigo 165\u00ba do C\u00f3digo Administrativo: os servi\u00e7os municipalizados visar\u00e3o a satisfazer necessidades colectivas da popula\u00e7\u00e3o do concelho que a iniciativa privada n\u00e3o proveja de modo completo e dever\u00e3o fixar as tarifas de modo a cobrir os gastos de explora\u00e7\u00e3o e de administra\u00e7\u00e3o, bem como a permitir a constitui\u00e7\u00e3o das reservas necess\u00e1rias.<\/div>\n<\/li>\n<li>\n<div align=\"justify\">(7) Al\u00ednea d) do artigo 16\u00ba da LFL.<\/div>\n<\/li>\n<li>\n<div align=\"justify\">(8) Artigo 20\u00ba e al\u00ednea a) do n\u00ba 1 do mesmo artigo da LFL.<\/div>\n<\/li>\n<li>\n<div align=\"justify\">(9) Como disp\u00f5e o artigo 64\u00ba, n\u00ba 1, al\u00ednea j) da Lei n\u00ba 169\/99, de 18 de Setembro, Lei das atribui\u00e7\u00f5es, compet\u00eancias e funcionamento dos \u00f3rg\u00e3os dos munic\u00edpios e freguesias.<\/div>\n<\/li>\n<li>\n<div align=\"justify\">(10) Assim o n\u00ba 3 do artigo 20 da LFL.<\/div>\n<\/li>\n<li>\n<div align=\"justify\">(11) JOS\u00c9 CASALTA NABAIS, O regime das finan\u00e7as locais em Portugal, BFDC, vol LXXX (2004), pag. 40.<\/div>\n<\/li>\n<li>\n<div align=\"justify\">(12) JOS\u00c9 CASALTA NABAIS, op cit., pag. 40-41.<\/div>\n<\/li>\n<li>\n<div align=\"justify\">(13) Cfr. ALFREDO JOS\u00c9 DE SOUSA, JOS\u00c9 DA SILVA PAIX\u00c3O, C\u00f3digo do Procedimento e Processo Tribut\u00e1rio, Comentado e Anotado, 2000, pag. 363.<\/div>\n<\/li>\n<li>\n<div align=\"justify\">(14) Entendimento tamb\u00e9m partilhado por ALFREDO JOS\u00c9 DE SOUSA, JOS\u00c9 DA SILVA PAIX\u00c3O, op. cit, pag. 363.<\/div>\n<\/li>\n<li>\n<div align=\"justify\">(15)Artigo 7\u00ba, n\u00ba 1.<\/div>\n<\/li>\n<li>\n<div align=\"justify\">(16) Lei das Empresas P\u00fablicas Municipais, Intermunicipais e Regionais<\/div>\n<\/li>\n<li>\n<div align=\"justify\">(17) Regime jur\u00eddico do sector empresarial do Estado e das bases gerais do estatuto das empresas p\u00fablicas do Estado.<\/div>\n<\/li>\n<li>\n<div align=\"justify\">(18) Cfr. ALFREDO JOS\u00c9 DE SOUSA, JOS\u00c9 DA SILVA PAIX\u00c3O, op. cit, pag. 363-364.<\/div>\n<\/li>\n<li>\n<div align=\"justify\">(19) Sobre a quest\u00e3o da manuten\u00e7\u00e3o pelas autarquias locais, ou mais precisamente pelas c\u00e2maras municipais, dos poderes de execu\u00e7\u00e3o fiscal para a cobran\u00e7a de d\u00edvidas vd. JOS\u00c9 CASALTA NABAIS, Execu\u00e7\u00f5es Fiscais. Respons\u00e1veis pelos Servi\u00e7os. Participa\u00e7\u00e3o nas custas. (parecer), in O Municipal, n\u00ba 269, Junho 2003, pag 10-16, e J. L. SALDANHA SANCHES e ANDR\u00c9 SALGADO DE MATOS, A compet\u00eancia da C\u00e2mara Municipal para a designa\u00e7\u00e3o do respons\u00e1vel pelo servi\u00e7o de execu\u00e7\u00f5es fiscais, in Fiscalidade, Revista de Direito e Gest\u00e3o Fiscal, n\u00ba 22, Abril-Junho 2005, pags 139-151.<\/div>\n<\/li>\n<li>\n<div align=\"justify\">(20) Ali\u00e1s o Tribunal Constitucional, no seu Ac\u00f3rd\u00e3o n\u00ba 685\/2004 veio declarar inconstitucional uma norma regulamentar que permitia \u00e0 EPAL suspender o fornecimento de \u00e1gua em diferente local daquele relativamente ao qual se registava a d\u00edvida, ainda que o consumidor fosse o mesmo.<\/div>\n<\/li>\n<li>\n<div align=\"justify\">Ac\u00f3rd\u00e3o consult\u00e1vel em http:\/\/www.tribunalconstitucional.pt\/tc\/acordaos\/20040685.html.<\/div>\n<\/li>\n<li>\n<div align=\"justify\">(21) Ac\u00f3rd\u00e3o n\u00ba 685\/2004, do Tribunal Constitucional, citada na nota anterior<\/div>\n<\/li>\n<li>\n<div align=\"justify\">(22) Como considera o Ac\u00f3rd\u00e3o do Tribunal Constitucional, citado na nota 21.<\/div>\n<\/li>\n<\/ul>\n<\/blockquote>\n<\/div>\n<\/div>\n<div class=\"icons\">&nbsp;<\/div>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_eb_attr":"","inline_featured_image":false,"iawp_total_views":100,"footnotes":""},"categories":[357],"tags":[187],"class_list":["post-41407","post","type-post","status-publish","format-standard","hentry","category-pareceres-ate-2017","tag-text-layout"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/posts\/41407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/comments?post=41407"}],"version-history":[{"count":1,"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/posts\/41407\/revisions"}],"predecessor-version":[{"id":41408,"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/posts\/41407\/revisions\/41408"}],"wp:attachment":[{"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/media?parent=41407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/categories?post=41407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/tags?post=41407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}