{"id":34229,"date":"2017-01-12T14:03:58","date_gmt":"2017-01-12T14:03:58","guid":{"rendered":""},"modified":"2023-10-26T13:32:20","modified_gmt":"2023-10-26T13:32:20","slug":"34229","status":"publish","type":"post","link":"https:\/\/www.ccdrc.pt\/en\/34229\/","title":{"rendered":"RJUE; Pr\u00e9dio; Unidade Predial; Certid\u00e3o Conservat\u00f3ria Registo Predial; Artigo Matricial"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1288px;margin-left: calc(-0% \/ 2 );margin-right: calc(-0% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:0%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:0%;--awb-width-medium:100%;--awb-spacing-right-medium:0%;--awb-spacing-left-medium:0%;--awb-width-small:100%;--awb-spacing-right-small:0%;--awb-spacing-left-small:0%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><div class=\"searchbox\">\n<div class=\"value\">Data:&nbsp;&nbsp;<strong>quinta, 12 janeiro 2017<\/strong><\/div>\n<div class=\"value\">N\u00famero:&nbsp;<strong>DAJ 6\/17<\/strong><\/div>\n<div class=\"value\">Respons\u00e1veis:&nbsp;&nbsp;<strong>Ant\u00f3nio Ramos<\/strong><\/div>\n<\/div>\n<div class=\"article_content\">\n<div class=\"fulltext\">\n<p>&nbsp;<\/p>\n<p>A C\u00e2mara Municipal de \u2026, em seu of\u00edcio \u2026, de 20.12.2016, solicita parecer jur\u00eddico que esclare\u00e7a como decidir no caso que se segue.<\/p>\n<p>&nbsp;<\/p>\n<p>Um mun\u00edcipe, num seu terreno que constitui&nbsp;uma mesma unidade predial, onde existe j\u00e1 uma moradia, pretende legalizar uma outra edifica\u00e7\u00e3o, um armaz\u00e9m, sendo que os dois edif\u00edcios est\u00e3o inseridos em diferentes matrizes urbanas, de acordo com as respetivas cadernetas prediais.<\/p>\n<p>Para melhor avalia\u00e7\u00e3o do pretendido, junta o munic\u00edpio uma Certid\u00e3o Permanente, com a descri\u00e7\u00e3o do pr\u00e9dio, retirado do respetivo registo predial, bem como duas cadernetas prediais urbanas: uma referente a \u201c<em>pr\u00e9dio destinado a armaz\u00e9m<\/em>\u201d e outro a \u201c<em>pr\u00e9dio para habita\u00e7\u00e3o<\/em>\u201d.<\/p>\n<p>Pergunta o munic\u00edpio, em suma, se a pretens\u00e3o n\u00e3o violar\u00e1 o disposto no artigo 19\u00ba, n\u00ba3, do Regulamento do seu Plano Diretor Municipal, que tem a seguinte reda\u00e7\u00e3o:<\/p>\n<p>\u201c<em>Os lotes de terreno, resultante de uma opera\u00e7\u00e3o de loteamento, e&nbsp;os pr\u00e9dios correspondentes&nbsp;a&nbsp;uma s\u00f3 unidade cadastral&nbsp;apta para a edifica\u00e7\u00e3o, nos termos do n\u00famero anterior, dever\u00e3o contemplar&nbsp;um s\u00f3 edif\u00edcio, destinado aos usos habitacional, comercial, de servi\u00e7os ou industrial,&nbsp;excluindo anexos&nbsp;destinados a apoio \u00e0 edifica\u00e7\u00e3o principal e depend\u00eancias agr\u00edcolas<\/em>\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Quanto a esta norma, devemos come\u00e7ar por lembrar que a&nbsp;identifica\u00e7\u00e3o cadastral&nbsp;n\u00e3o cobre ainda todo o territ\u00f3rio nacional, o que motivou o Governo \u2013 atrav\u00e9s da RCM n.\u00ba 45\/2006 &#8211; a implementar o&nbsp;Sistema Nacional de Explora\u00e7\u00e3o e Gest\u00e3o de Informa\u00e7\u00e3o Cadastral&nbsp;(Sinergic), que tem como principal objetivo viabilizar a exist\u00eancia de cadastro predial em Portugal.<\/p>\n<p>&nbsp;<\/p>\n<p>Neste \u00e2mbito, por RCM n\u00ba 92\/2009, foi decidido autorizar a realiza\u00e7\u00e3o da despesa com a aquisi\u00e7\u00e3o de servi\u00e7os de execu\u00e7\u00e3o do cadastro predial em alguns munic\u00edpios do pa\u00eds, entre os quais Oliveira do Hospital e Seia, na \u00e1rea desta CCDR-Centro, n\u00e3o se incluindo, no entanto, o munic\u00edpio de Miranda do Corvo.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;Face ao exposto, n\u00e3o se poder\u00e1 ainda mencionar a exist\u00eancia de cadastro em Miranda do Corvo, pelo que a refer\u00eancia a \u201c<em>unidade cadastral<\/em>\u201d, no citado artigo do PDM, dever-se-\u00e1 certamente, a lapso.<\/p>\n<p>&nbsp;<\/p>\n<p>Importa, por isso, fazer uma&nbsp;interpreta\u00e7\u00e3o corretiva&nbsp;da dita norma[1], por forma a fazer corresponder a f\u00f3rmula \u201c<em>unidade cadastral<\/em>\u201d a&nbsp;pr\u00e9dio, conceito jur\u00eddico, do direito registral, usado para efeitos de planeamento e de controlo de opera\u00e7\u00f5es urban\u00edsticas, designadamente no Regime Jur\u00eddico da Urbaniza\u00e7\u00e3o e Edifica\u00e7\u00e3o (RJUE) &#8211; aprovado pelo D.L. 555\/99, de 16.12, na reda\u00e7\u00e3o atual &#8211; e legisla\u00e7\u00e3o complementar.<\/p>\n<p>&nbsp;<\/p>\n<p>Com efeito, esta quest\u00e3o deve conjugar-se com as normas que regulam os elementos instrut\u00f3rios que devem acompanhar as pretens\u00f5es de opera\u00e7\u00f5es urban\u00edsticas, nomeadamente o n\u00ba4 do artigo 9\u00ba do Regime Jur\u00eddico da Urbaniza\u00e7\u00e3o e Edifica\u00e7\u00e3o (RJUE), aprovado pelo D.L. 555\/99, de 16.12, na reda\u00e7\u00e3o atual, que prev\u00ea que o&nbsp;requerimento e a comunica\u00e7\u00e3o&nbsp;devem ser acompanhados, e citamos,&nbsp;<em>\u201cdos elementos instrut\u00f3rios previstos em portaria aprovada pelos ministros respons\u00e1veis pelas obras p\u00fablicas e pelo ordenamento do territ\u00f3rio, para al\u00e9m dos documentos especialmente referidos no presente diploma\u201d.<\/em><\/p>\n<p><em>&nbsp;<\/em><\/p>\n<p>O diploma para a qual a norma remete \u00e9, atualmente, a Portaria n.\u00ba 113\/2015, de 22.04, que no seu Anexo I \u2013 \u201c<em>Elementos Instrut\u00f3rios<\/em>\u201d \u2013 I \u2013 \u201c<em>Elementos comuns aos procedimentos de controlo pr\u00e9vio<\/em>\u201d, exige:<\/p>\n<p>\u201c<em>1 \u2013&nbsp;Certid\u00e3o da descri\u00e7\u00e3o e de todas as inscri\u00e7\u00f5es em vigor emitida pela conservat\u00f3ria do registo predial referente ao pr\u00e9dio ou pr\u00e9dios abrangidos, ou indica\u00e7\u00e3o do c\u00f3digo de acesso \u00e0 certid\u00e3o permanente do registo predial, quando omissos, a respetiva certid\u00e3o negativa do registo predial, acompanhada da caderneta predial onde constem os correspondentes artigos matriciais<\/em>\u201d<\/p>\n<p>&nbsp;<\/p>\n<p>\u00c9 este documento instrut\u00f3rio, a&nbsp;certid\u00e3o do registo predial, o elemento que a Lei julga adequado e suficiente para fazer prova da propriedade e para a descri\u00e7\u00e3o do pr\u00e9dio e n\u00e3o a caderneta predial emitida pela AT \u2013 Autoridade Tribut\u00e1ria e Aduaneira.<\/p>\n<p>&nbsp;<\/p>\n<p>Dito isto, \u00e9 inequ\u00edvoco, pela certid\u00e3o do registo predial junta pelo munic\u00edpio, que as duas edifica\u00e7\u00f5es \u2013 moradia e armaz\u00e9m \u2013 se situam numa parcela de terreno que constitui&nbsp;uma \u00fanica unidade predial, sendo esta a unidade que deve ser tomada como refer\u00eancia, nos termos e para os efeitos do atr\u00e1s citado artigo 19\u00ba, n\u00ba3, do Regulamento do Plano Diretor Municipal de Miranda do Corvo.<\/p>\n<p>Sobre o assunto, transcrevemos um coment\u00e1rio ao artigo 2\u00ba do RJUE, das Autoras Fernanda Paula Oliveira, Maria Jos\u00e9 Castanheira Neves e Dulce Lopes[2], que julgamos suficientemente elucidativo:<\/p>\n<p>\u201c<em>Um caso t\u00edpico de divis\u00e3o jur\u00eddica, que corresponde \u00e0 concretiza\u00e7\u00e3o de uma opera\u00e7\u00e3o de loteamento, \u00e9 o que ocorre quando se pretende aprovar, num dado pr\u00e9dio, projetos de obras para v\u00e1rios edif\u00edcios sem liga\u00e7\u00e3o estrutural ou com independ\u00eancia funcional, afetando, assim, partes espec\u00edficas do solo a utiliza\u00e7\u00f5es distintas. Neste sentido, vide Ant\u00f3nio Duarte de ALMEIDA e outros, Legisla\u00e7\u00e3o Fundamental de Direito do Urbanismo, cit., p. 513.&nbsp;Tal \u00e9 assim por, em regra, uma unidade principal apenas permitir a constru\u00e7\u00e3o de um edif\u00edcio principal, pelo que sempre que se pretenda construir v\u00e1rios edif\u00edcios principais numa mesma unidade predial ter\u00e1 de se sujeitar esta, primeiro, a uma divis\u00e3o fundi\u00e1ria por forma a que seja poss\u00edvel cumprir o referido princ\u00edpio<\/em>\u201d<\/p>\n<p>&nbsp;<\/p>\n<p>Temos assim, deste modo, que apenas com uma opera\u00e7\u00e3o de loteamento ou com um destaque, se a ambos houver lugar, se poder\u00e1 satisfazer o pedido do requerente.<\/p>\n<p>&nbsp;<\/p>\n<p>Diferente seria se estiv\u00e9ssemos perante uma constru\u00e7\u00e3o principal e uma outra constru\u00e7\u00e3o com uma depend\u00eancia funcional da primeira, como \u00e9 o caso dos&nbsp;anexos, ou seja, como \u00e9 sabido, de acordo com a defini\u00e7\u00e3o de \u201c<em>edif\u00edcio anexo<\/em>\u201d do Decreto Regulamentar n\u00ba 9\/2009, de 29.5 (ficha 22), um \u201c<em>edif\u00edcio destinado a uso complementar do edif\u00edcio principal<\/em>\u201d, o que, como tudo indica, n\u00e3o ser\u00e1 o caso apresentado.<\/p>\n<p>&nbsp;<\/p>\n<p>De contr\u00e1rio, e conclu\u00edmos, estar-se-\u00e1 n\u00e3o s\u00f3 a violar a norma do PDM citada pelo munic\u00edpio, como, sobretudo, as pr\u00f3prias regras gerais do direito do urbanismo, designadamente as do RJUE.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;Divis\u00e3o de Apoio Jur\u00eddico<\/p>\n<p>&nbsp;<\/p>\n<p>(Ant\u00f3nio Ramos)<\/p>\n<p>&nbsp;<\/p>\n<p>[1]&nbsp;Sobre a admissibilidade da&nbsp;interpreta\u00e7\u00e3o corretiva&nbsp;das normas legais, no sentido assinalado, vide J. Batista Machado, em \u00ab<em>Introdu\u00e7\u00e3o ao Direito e ao Discurso Legitimador<\/em>\u00bb, Almedina, Cimbra, 1991, p.186.<\/p>\n<p>[2]&nbsp;<em>In<\/em>&nbsp;<em>Regime Jur\u00eddico da Urbaniza\u00e7\u00e3o e Edifica\u00e7\u00e3o<\/em>, Anotado, 2016, 4\u00aa edi\u00e7\u00e3o, Almedina, p.83<\/p>\n<\/div>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">A C\u00e2mara Municipal de \u2026, em seu of\u00edcio \u2026, de 20.12.2016, solicita parecer jur\u00eddico que esclare\u00e7a como decidir no caso que se segue.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Um mun\u00edcipe, num seu terreno que constitui <span style=\"text-decoration: underline;\">uma mesma unidade predial<\/span>, onde existe j\u00e1 uma moradia, pretende legalizar uma outra edifica\u00e7\u00e3o, um armaz\u00e9m, sendo que os dois edif\u00edcios est\u00e3o inseridos em diferentes matrizes urbanas, de acordo com as respetivas cadernetas prediais.<\/p>\n<p style=\"text-align: justify;\">Para melhor avalia\u00e7\u00e3o do pretendido, junta o munic\u00edpio uma Certid\u00e3o Permanente, com a descri\u00e7\u00e3o do pr\u00e9dio, retirado do respetivo registo predial, bem como duas cadernetas prediais urbanas: uma referente a \u201c<em>pr\u00e9dio destinado a armaz\u00e9m<\/em>\u201d e outro a \u201c<em>pr\u00e9dio para habita\u00e7\u00e3o<\/em>\u201d.<\/p>\n<p style=\"text-align: justify;\">Pergunta o munic\u00edpio, em suma, se a pretens\u00e3o n\u00e3o violar\u00e1 o disposto no artigo 19\u00ba, n\u00ba3, do Regulamento do seu Plano Diretor Municipal, que tem a seguinte reda\u00e7\u00e3o:<\/p>\n<p style=\"text-align: justify;\">\u201c<em>Os lotes de terreno, resultante de uma opera\u00e7\u00e3o de loteamento, e <span style=\"text-decoration: underline;\">os pr\u00e9dios correspondentes<\/span> a <span style=\"text-decoration: underline;\">uma s\u00f3 unidade cadastral<\/span> apta para a edifica\u00e7\u00e3o, nos termos do n\u00famero anterior, dever\u00e3o contemplar <span style=\"text-decoration: underline;\">um s\u00f3 edif\u00edcio<\/span>, destinado aos usos habitacional, comercial, de servi\u00e7os ou industrial, <span style=\"text-decoration: underline;\">excluindo anexos<\/span> destinados a apoio \u00e0 edifica\u00e7\u00e3o principal e depend\u00eancias agr\u00edcolas<\/em>\u201d.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Quanto a esta norma, devemos come\u00e7ar por lembrar que a <span style=\"text-decoration: underline;\">identifica\u00e7\u00e3o cadastral<\/span> n\u00e3o cobre ainda todo o territ\u00f3rio nacional, o que motivou o Governo \u2013 atrav\u00e9s da RCM n.\u00ba 45\/2006 &#8211; a implementar o <span style=\"text-decoration: underline;\">Sistema Nacional de Explora\u00e7\u00e3o e Gest\u00e3o de Informa\u00e7\u00e3o Cadastral<\/span> (Sinergic), que tem como principal objetivo viabilizar a exist\u00eancia de cadastro predial em Portugal.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Neste \u00e2mbito, por RCM n\u00ba 92\/2009, foi decidido autorizar a realiza\u00e7\u00e3o da despesa com a aquisi\u00e7\u00e3o de servi\u00e7os de execu\u00e7\u00e3o do cadastro predial em alguns munic\u00edpios do pa\u00eds, entre os quais Oliveira do Hospital e Seia, na \u00e1rea desta CCDR-Centro, n\u00e3o se incluindo, no entanto, o munic\u00edpio de Miranda do Corvo.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">\u00a0Face ao exposto, n\u00e3o se poder\u00e1 ainda mencionar a exist\u00eancia de cadastro em Miranda do Corvo, pelo que a refer\u00eancia a \u201c<em>unidade cadastral<\/em>\u201d, no citado artigo do PDM, dever-se-\u00e1 certamente, a lapso.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Importa, por isso, fazer uma <span style=\"text-decoration: underline;\">interpreta\u00e7\u00e3o corretiva<\/span> da dita norma<a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a>, por forma a fazer corresponder a f\u00f3rmula \u201c<em>unidade cadastral<\/em>\u201d a <span style=\"text-decoration: underline;\">pr\u00e9dio<\/span>, conceito jur\u00eddico, do direito registral, usado para efeitos de planeamento e de controlo de opera\u00e7\u00f5es urban\u00edsticas, designadamente no Regime Jur\u00eddico da Urbaniza\u00e7\u00e3o e Edifica\u00e7\u00e3o (RJUE) &#8211; aprovado pelo D.L. 555\/99, de 16.12, na reda\u00e7\u00e3o atual &#8211; e legisla\u00e7\u00e3o complementar.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Com efeito, esta quest\u00e3o deve conjugar-se com as normas que regulam os elementos instrut\u00f3rios que devem acompanhar as pretens\u00f5es de opera\u00e7\u00f5es urban\u00edsticas, nomeadamente o n\u00ba4 do artigo 9\u00ba do Regime Jur\u00eddico da Urbaniza\u00e7\u00e3o e Edifica\u00e7\u00e3o (RJUE), aprovado pelo D.L. 555\/99, de 16.12, na reda\u00e7\u00e3o atual, que prev\u00ea que o <span style=\"text-decoration: underline;\">requerimento e a comunica\u00e7\u00e3o<\/span> devem ser acompanhados, e citamos, <em>\u201cdos elementos instrut\u00f3rios previstos em portaria aprovada pelos ministros respons\u00e1veis pelas obras p\u00fablicas e pelo ordenamento do territ\u00f3rio, para al\u00e9m dos documentos especialmente referidos no presente diploma\u201d.<\/em><\/p>\n<p style=\"text-align: justify;\"><em>\u00a0<\/em><\/p>\n<p style=\"text-align: justify;\">O diploma para a qual a norma remete \u00e9, atualmente, a Portaria n.\u00ba 113\/2015, de 22.04, que no seu Anexo I \u2013 \u201c<em>Elementos Instrut\u00f3rios<\/em>\u201d \u2013 I \u2013 \u201c<em>Elementos comuns aos procedimentos de controlo pr\u00e9vio<\/em>\u201d, exige:<\/p>\n<p style=\"text-align: justify;\">\u201c<em>1 \u2013 <span style=\"text-decoration: underline;\">Certid\u00e3o da descri\u00e7\u00e3o e de todas as inscri\u00e7\u00f5es em vigor emitida pela conservat\u00f3ria do registo predial referente ao pr\u00e9dio ou pr\u00e9dios abrangidos<\/span>, ou indica\u00e7\u00e3o do c\u00f3digo de acesso \u00e0 certid\u00e3o permanente do registo predial, quando omissos, a respetiva certid\u00e3o negativa do registo predial, acompanhada da caderneta predial onde constem os correspondentes artigos matriciais<\/em>\u201d<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">\u00c9 este documento instrut\u00f3rio, a <span style=\"text-decoration: underline;\">certid\u00e3o do registo predial<\/span>, o elemento que a Lei julga adequado e suficiente para fazer prova da propriedade e para a descri\u00e7\u00e3o do pr\u00e9dio e n\u00e3o a caderneta predial emitida pela AT \u2013 Autoridade Tribut\u00e1ria e Aduaneira.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Dito isto, \u00e9 inequ\u00edvoco, pela certid\u00e3o do registo predial junta pelo munic\u00edpio, que as duas edifica\u00e7\u00f5es \u2013 moradia e armaz\u00e9m \u2013 se situam numa parcela de terreno que constitui <span style=\"text-decoration: underline;\">uma \u00fanica unidade predial<\/span>, sendo esta a unidade que deve ser tomada como refer\u00eancia, nos termos e para os efeitos do atr\u00e1s citado artigo 19\u00ba, n\u00ba3, do Regulamento do Plano Diretor Municipal de Miranda do Corvo.<\/p>\n<p style=\"text-align: justify;\">Sobre o assunto, transcrevemos um coment\u00e1rio ao artigo 2\u00ba do RJUE, das Autoras Fernanda Paula Oliveira, Maria Jos\u00e9 Castanheira Neves e Dulce Lopes<a href=\"#_ftn2\" name=\"_ftnref2\">[2]<\/a>, que julgamos suficientemente elucidativo:<\/p>\n<p style=\"text-align: justify;\">\u201c<em>Um caso t\u00edpico de divis\u00e3o jur\u00eddica, que corresponde \u00e0 concretiza\u00e7\u00e3o de uma opera\u00e7\u00e3o de loteamento, \u00e9 o que ocorre quando se pretende aprovar, num dado pr\u00e9dio, projetos de obras para v\u00e1rios edif\u00edcios sem liga\u00e7\u00e3o estrutural ou com independ\u00eancia funcional, afetando, assim, partes espec\u00edficas do solo a utiliza\u00e7\u00f5es distintas. Neste sentido, vide Ant\u00f3nio Duarte de ALMEIDA e outros, Legisla\u00e7\u00e3o Fundamental de Direito do Urbanismo, cit., p. 513. <span style=\"text-decoration: underline;\">Tal \u00e9 assim por, em regra, uma unidade principal apenas permitir a constru\u00e7\u00e3o de um edif\u00edcio principal<\/span>, pelo que sempre que se pretenda construir v\u00e1rios edif\u00edcios principais numa mesma unidade predial ter\u00e1 de se sujeitar esta, primeiro, a uma divis\u00e3o fundi\u00e1ria por forma a que seja poss\u00edvel cumprir o referido princ\u00edpio<\/em>\u201d<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Temos assim, deste modo, que apenas com uma opera\u00e7\u00e3o de loteamento ou com um destaque, se a ambos houver lugar, se poder\u00e1 satisfazer o pedido do requerente.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Diferente seria se estiv\u00e9ssemos perante uma constru\u00e7\u00e3o principal e uma outra constru\u00e7\u00e3o com uma depend\u00eancia funcional da primeira, como \u00e9 o caso dos <span style=\"text-decoration: underline;\">anexos<\/span>, ou seja, como \u00e9 sabido, de acordo com a defini\u00e7\u00e3o de \u201c<em>edif\u00edcio anexo<\/em>\u201d do Decreto Regulamentar n\u00ba 9\/2009, de 29.5 (ficha 22), um \u201c<em>edif\u00edcio destinado a uso complementar do edif\u00edcio principal<\/em>\u201d, o que, como tudo indica, n\u00e3o ser\u00e1 o caso apresentado.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">De contr\u00e1rio, e conclu\u00edmos, estar-se-\u00e1 n\u00e3o s\u00f3 a violar a norma do PDM citada pelo munic\u00edpio, como, sobretudo, as pr\u00f3prias regras gerais do direito do urbanismo, designadamente as do RJUE.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">\u00a0Divis\u00e3o de Apoio Jur\u00eddico<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">(Ant\u00f3nio Ramos)<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> Sobre a admissibilidade da <span style=\"text-decoration: underline;\">interpreta\u00e7\u00e3o corretiva<\/span> das normas legais, no sentido assinalado, vide J. Batista Machado, em \u00ab<em>Introdu\u00e7\u00e3o ao Direito e ao Discurso Legitimador<\/em>\u00bb, Almedina, Cimbra, 1991, p.186.<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref2\" name=\"_ftn2\">[2]<\/a> <em>In<\/em> <em>Regime Jur\u00eddico da Urbaniza\u00e7\u00e3o e Edifica\u00e7\u00e3o<\/em>, Anotado, 2016, 4\u00aa edi\u00e7\u00e3o, Almedina, p.83<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_eb_attr":"","inline_featured_image":false,"iawp_total_views":86,"footnotes":""},"categories":[357],"tags":[187],"class_list":["post-34229","post","type-post","status-publish","format-standard","hentry","category-pareceres-ate-2017","tag-text-layout"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/posts\/34229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/comments?post=34229"}],"version-history":[{"count":3,"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/posts\/34229\/revisions"}],"predecessor-version":[{"id":40886,"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/posts\/34229\/revisions\/40886"}],"wp:attachment":[{"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/media?parent=34229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/categories?post=34229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/tags?post=34229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}