{"id":34226,"date":"2016-12-15T14:03:49","date_gmt":"2016-12-15T14:03:49","guid":{"rendered":""},"modified":"2023-10-23T09:03:45","modified_gmt":"2023-10-23T09:03:45","slug":"34226","status":"publish","type":"post","link":"https:\/\/www.ccdrc.pt\/en\/34226\/","title":{"rendered":"Ren\u00fancia; Cessa\u00e7\u00e3o volunt\u00e1ria do exerc\u00edcio de fun\u00e7\u00f5es de Presidente da Mesa; Assembleia de Freguesia"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1288px;margin-left: calc(-0% \/ 2 );margin-right: calc(-0% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:0%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:0%;--awb-width-medium:100%;--awb-spacing-right-medium:0%;--awb-spacing-left-medium:0%;--awb-width-small:100%;--awb-spacing-right-small:0%;--awb-spacing-left-small:0%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><div class=\"searchbox\">\n<div class=\"value\">Data:&nbsp;&nbsp;<strong>quinta, 15 dezembro 2016<\/strong><\/div>\n<div class=\"value\">N\u00famero:&nbsp;<strong>DSAJAL 203\/16<\/strong><\/div>\n<div class=\"value\">Respons\u00e1veis:&nbsp;&nbsp;<strong>Maria Jos\u00e9 Leal Castanheira Neves (Diretora de Servi\u00e7os de Apoio Jur\u00eddico e \u00e0 Administra\u00e7\u00e3o Local)<\/strong><\/div>\n<div class=\"value\">Diretora de Servi\u00e7os de Apoio Jur\u00eddico e \u00e0 Administra\u00e7\u00e3o Local<\/div>\n<\/div>\n<div class=\"article_content\">\n<div class=\"fulltext\">\n<p>&nbsp;<\/p>\n<p>Em refer\u00eancia ao pedido de parecer solicitado pelo Presidente da Assembleia de Freguesia, por correio eletr\u00f3nico de 7 e 13 de dezembro de 2016, sobre o assunto mencionado em ep\u00edgrafe, julgamos que as quest\u00f5es que em concreto devemos esclarecer, baseados no teor do texto enviado, s\u00e3o as seguintes:<\/p>\n<p>&nbsp;<\/p>\n<ol>\n<li>Poder\u00e1 ocorrer a cessa\u00e7\u00e3o volunt\u00e1ria (erradamente designada pelo Presidente da Assembleia de Freguesia como ren\u00fancia) do exerc\u00edcio de fun\u00e7\u00f5es de Presidente da Mesa, permanecendo o mesmo como membro da mesma Assembleia de Freguesia?<\/li>\n<li>Caso pretenda renunciar ao mandato de membro da Assembleia de Freguesia,<\/li>\n<\/ol>\n<p>para al\u00e9m da cessa\u00e7\u00e3o volunt\u00e1ria como Presidente da Assembleia de Freguesia, como dever\u00e1 proceder?<\/p>\n<p>&nbsp;<\/p>\n<p>I<\/p>\n<p>&nbsp;<\/p>\n<p>No que respeita \u00e0 primeira quest\u00e3o, importa referir que os membros da Mesa podem ser destitu\u00eddos a qualquer momento pela maioria do n\u00famero legal dos membros que comp\u00f5em a Assembleia de Freguesia, contrariamente ao mandato dos mesmos enquanto membros da Assembleia.<\/p>\n<p>De facto, contrariamente ao mandato dos membros da Assembleia de Freguesia que \u00e9 de quatro anos, s\u00f3 deixando de ser eleitos se renunciarem, forem objeto da san\u00e7\u00e3o de perda de mandato ou de dissolu\u00e7\u00e3o do \u00f3rg\u00e3o, nestas duas \u00faltimas hip\u00f3teses por senten\u00e7a de tribunal administrativo, a mesa \u00e9 eleita para o per\u00edodo do mandato mas pode ser destitu\u00edda a qualquer momento pela maioria do n\u00famero legal dos membros que comp\u00f5em a assembleia de freguesia (n \u00ba 2 do artigo 10 \u00ba da lei 169\/99, de 18\/09, na reda\u00e7\u00e3o dada pela lei n \u00ba 5-A\/2002, de 11\/01).<\/p>\n<p>Ocorrendo essa destitui\u00e7\u00e3o os membros da mesa destitu\u00eddos das suas fun\u00e7\u00f5es na mesa continuam, obviamente, a ser membros de pleno direito da Assembleia de Freguesia \u2013 apenas deixam de integrar a mesa.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ora, se os membros da mesa forem destitu\u00eddos continuam a ser membros da Assembleia de Freguesia, n\u00e3o se confundindo esta destitui\u00e7\u00e3o com ren\u00fancia.<\/strong><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p>A ren\u00fancia \u00e9 uma das formas de cessa\u00e7\u00e3o do mandato e consubstancia um direito de que gozam todos os eleitos locais, que depende unicamente da manifesta\u00e7\u00e3o da vontade de renunciar, apresentada pelo eleito quer antes quer depois da instala\u00e7\u00e3o dos \u00f3rg\u00e3os respetivos, estando legalmente consagrada no artigo 76 \u00ba da lei n\u00ba 169\/99, na nova reda\u00e7\u00e3o dada pela lei 5-A\/2002, de 11\/01.<\/p>\n<p>A convoca\u00e7\u00e3o do substituto dever\u00e1 ser realizada no per\u00edodo que medeia entre a comunica\u00e7\u00e3o de ren\u00fancia e a primeira reuni\u00e3o que a seguir se realizar, onde o mesmo ser\u00e1 instalado.<\/p>\n<p><strong>Isto \u00e9, n\u00e3o est\u00e1 legalmente prevista a ren\u00fancia ao cargo de Presidente da Assembleia de Freguesia, as ren\u00fancias respeitam aos mandatos como eleitos locais, sendo o cargo de presidente da Mesa um cargo para que se \u00e9 eleito por se ter previamente adquirido a qualidade de eleito local.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Assim, no que respeita \u00e0 possibilidade de o Presidente da mesa, \u00abcessar\u00bb, por op\u00e7\u00e3o pr\u00f3pria, o exerc\u00edcio desse cargo para que foi eleito, n\u00e3o existe enquadramento legal para tal situa\u00e7\u00e3o, como referimos, limitando-se a lei a prever e a regular apenas a hip\u00f3tese de destitui\u00e7\u00e3o por parte da Assembleia de Freguesia.<\/p>\n<p>Ora, sendo um dos deveres dos eleitos locais participar nas reuni\u00f5es dos \u00f3rg\u00e3os para que foram eleitos, acrescentando n\u00f3s, e nos cargos para que foram eleitos, entendemos, salvo melhor opini\u00e3o, que a Assembleia de Freguesia dever\u00e1 negar a possibilidade desta \u00ab<em>ren\u00fancia<\/em>\u00bb volunt\u00e1ria ao cargo de membro da Mesa da Assembleia, considerando que faz parte dos deveres dos eleitos permanecer nos referidos cargos, a menos que renunciem ou se suspendam os pr\u00f3prios mandatos de eleitos locais.<\/p>\n<p>Ou seja, se a Assembleia de Freguesia considerar que n\u00e3o h\u00e1 enquadramento legal para que o Presidente da Assembleia cesse voluntariamente o exerc\u00edcio do cargo de Presidente da mesa deve comunic\u00e1-lo ao pr\u00f3prio, indeferindo a sua comunica\u00e7\u00e3o de \u00ab<em>ren\u00fancia<\/em>\u00bb, que mais n\u00e3o \u00e9 do que uma comunica\u00e7\u00e3o, como j\u00e1 afirm\u00e1mos, de cessa\u00e7\u00e3o volunt\u00e1ria do cargo.<\/p>\n<p>No entanto, tal n\u00e3o impede nem que a Assembleia o destitua nem que o pr\u00f3prio renuncie ao seu pr\u00f3prio mandato de membro da Assembleia.<\/p>\n<p>Se nenhuma das situa\u00e7\u00f5es ocorrer n\u00e3o se ir\u00e1 verificar qualquer altera\u00e7\u00e3o na Assembleia de Freguesia.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;&nbsp;Temos, no entanto, presente que esta doutrina n\u00e3o colhe unanimidade, pelo que h\u00e1 quem entenda que o Presidente da Mesa pode cessar voluntariamente o exerc\u00edcio deste cargo, continuando como membro da Assembleia.<\/p>\n<p>&nbsp;<\/p>\n<p>Competindo-nos dar apoio t\u00e9cnico \u00e0s autarquias locais devemos inform\u00e1-las dos v\u00e1rios entendimentos sobre as mat\u00e9rias em d\u00favida, muito embora manifestemos a nossa posi\u00e7\u00e3o, dado que o apoio que prestamos n\u00e3o s\u00f3 \u00e9 solicitado voluntariamente pelas autarquias como n\u00e3o as vincula nem as poderia vincular, dado o princ\u00edpio da autonomia do poder local.<\/p>\n<p>&nbsp;<\/p>\n<p>Assim neste outro entendimento, h\u00e1 possibilidade dos membros da mesa cessarem voluntariamente o exerc\u00edcio dos respetivos cargos, pelo que se tal ocorrer a substitui\u00e7\u00e3o do Presidente da Mesa da Assembleia deve operar-se da mesma forma em que se realizou a sua elei\u00e7\u00e3o para a mesa.<\/p>\n<p>&nbsp;<\/p>\n<p>Nestes termos, haver\u00e1 nova elei\u00e7\u00e3o, elei\u00e7\u00e3o realizada por voto secreto pelos membros da Assembleia de Freguesia (vide o artigo 9 \u00ba da Lei n \u00ba 169\/99, de 18\/09, na reda\u00e7\u00e3o dada pela lei n \u00ba 5-A\/2002, de 11 de Janeiro) para eleger um novo Presidente ou uma nova mesa, consoante os termos em que estiver regulamentada a elei\u00e7\u00e3o da mesa no regimento da Assembleia de Freguesia, uninominal ou por listas.<\/p>\n<p>&nbsp;<\/p>\n<p>Se estiver estipulada elei\u00e7\u00e3o uninominal eleger-se-\u00e1 apenas o presidente da Mesa mas se a elei\u00e7\u00e3o prevista em regimento for a elei\u00e7\u00e3o por listas ter\u00e3o que ser apresentadas listas para a elei\u00e7\u00e3o da mesa, ou seja, nesse caso ter\u00e1 que ser eleita uma nova mesa.<\/p>\n<p>&nbsp;<\/p>\n<p>N\u00e3o podemos deixar de referir, no entanto, que &nbsp;no caso que nos foi apresentado houve uma n\u00edtida confus\u00e3o entre o conceito de ren\u00fancia, inerente ao mandato de eleito local e a cessa\u00e7\u00e3o volunt\u00e1ria do cargo de Presidente da mesa.<\/p>\n<p>&nbsp;<\/p>\n<p>Por \u00faltimo refira-se que quer a Assembleia destitua a mesa ( ou qualquer um dos membros da respetiva mesa) ou aceite&nbsp; a&nbsp; cessa\u00e7\u00e3o volunt\u00e1ria do cargo de presidente da Assembleia, haver\u00e1&nbsp; nova elei\u00e7\u00e3o, elei\u00e7\u00e3o realizada por voto secreto pelos membros da assembleia de freguesia ( vide o artigo 9 \u00ba da Lei n \u00ba 169\/99, de 18\/09, na reda\u00e7\u00e3o dada pela lei n \u00ba 5-A\/2002, de 11 de Janeiro) para eleger uma nova mesa ou um novo Presidente, nos termos por n\u00f3s supra referidos.<\/p>\n<p>&nbsp;<\/p>\n<p>II<\/p>\n<p>Se, porventura, o atual Presidente da Assembleia de Freguesia pretender renunciar tamb\u00e9m ao seu mandato como membro da assembleia de Freguesia, para al\u00e9m de querer cessar fun\u00e7\u00f5es como Presidente da mesa, o enquadramento legal da situa\u00e7\u00e3o em causa ser\u00e1 o seguinte:<\/p>\n<p>&nbsp;<\/p>\n<p>A ren\u00fancia, com referimos, est\u00e1 consagrada no artigo 76\u00ba da Lei n\u00ba 169\/99, de 18 de setembro, com as altera\u00e7\u00f5es introduzidas pelo Lei n\u00ba 5-A\/2002, de 11 de janeiro, \u00e9 uma das formas de cessa\u00e7\u00e3o do mandato e consubstancia um direito de que gozam todos os eleitos locais, que depende unicamente da manifesta\u00e7\u00e3o da vontade de renunciar, apresentada pelo eleito quer antes, quer depois da instala\u00e7\u00e3o dos \u00f3rg\u00e3os respetivos,<\/p>\n<p>&nbsp;<\/p>\n<p>Esta manifesta\u00e7\u00e3o de vontade \u00e9 apresentada por escrito e dirigida a quem deve proceder \u00e0 instala\u00e7\u00e3o ou ao presidente do \u00f3rg\u00e3o, consoante o caso, que deve convocar o membro substituto, no per\u00edodo que medeia entre a comunica\u00e7\u00e3o da ren\u00fancia e a primeira reuni\u00e3o que a seguir se realizar, salvo se a entrega do documento de ren\u00fancia coincidir com o ato de instala\u00e7\u00e3o ou reuni\u00e3o do \u00f3rg\u00e3o e estiver presente o respetivo substituto, situa\u00e7\u00e3o em que, ap\u00f3s a verifica\u00e7\u00e3o da sua identidade e legitimidade, a substitui\u00e7\u00e3o se opera de imediato, se o substituto a n\u00e3o recusar por escrito de acordo com o direito que ele pr\u00f3prio tem a renunciar.<\/p>\n<p>&nbsp;<\/p>\n<p>A sua substitui\u00e7\u00e3o far-se-\u00e1 nos termos previstos no artigo 79\u00ba do mesmo diploma, ou seja,&nbsp;<em>\u201cpelo cidad\u00e3o imediatamente a seguir na ordem da respetiva lista ou, tratando-se de coliga\u00e7\u00e3o, pelo cidad\u00e3o imediatamente a seguir do partido pelo qual havia sido proposto o membro que deu origem \u00e0 vaga<\/em>\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>No presente caso, exercendo o eleito renunciante tamb\u00e9m as fun\u00e7\u00f5es de Presidente da mesa da Assembleia de Freguesia, a forma da sua substitui\u00e7\u00e3o enquanto tal \u00e9 a que aludimos&nbsp;<em>supra<\/em>, ou seja, dever-se-\u00e1&nbsp; preencher proceder \u00e0 elei\u00e7\u00e3o do novo Presidente, caso a anterior elei\u00e7\u00e3o tenha sido uninominal, ou de uma nova mesa, caso tenha sido por lista.<\/p>\n<p>&nbsp;<\/p>\n<p>Note-se, por\u00e9m, que enquanto n\u00e3o for feita a referida elei\u00e7\u00e3o, cabe ao 1 \u00ba secret\u00e1rio, nos termos previsto no n\u00ba 3 do citado artigo 10\u00ba, substituir o Presidente nas suas faltas.<\/p>\n<p>&nbsp;<\/p>\n<p>Conclus\u00f5es,<\/p>\n<p>&nbsp;<\/p>\n<ol>\n<li>No caso da Assembleia de Freguesia aceitar a cessa\u00e7\u00e3o volunt\u00e1ria do cargo de presidente da Assembleia, haver\u00e1 nova elei\u00e7\u00e3o, elei\u00e7\u00e3o realizada por voto secreto pelos membros da assembleia de freguesia (&nbsp;<em>vide&nbsp;<\/em>o artigo 9 \u00ba da Lei n \u00ba 169\/99, de 18\/09, na reda\u00e7\u00e3o dada pela lei n \u00ba 5-A\/2002, de 11 de Janeiro) para eleger&nbsp; um novo Presidente ou uma nova mesa, consoante os termos em que estiver regulamentada a elei\u00e7\u00e3o da mesa no regimento da Assembleia de Freguesia, uninominal ou por listas.<\/li>\n<\/ol>\n<p>&nbsp;&nbsp;<\/p>\n<ol start=\"2\">\n<li>No caso do atual Presidente da Assembleia de freguesia renunciar ao mandato de eleito local:<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p>&#8211; Por for\u00e7a da conjuga\u00e7\u00e3o normativa do n\u00ba 4 do artigo 76\u00ba e do n\u00ba 1 do artigo 79\u00ba da Lei n\u00ba 169\/99, dever-se-\u00e1 primeiramente substituir o Presidente da Assembleia enquanto membro da Assembleia de Freguesia, convocando o cidad\u00e3o imediatamente a seguir na ordem da respetiva lista, o que ter\u00e1 lugar no per\u00edodo que medeia entre a comunica\u00e7\u00e3o da ren\u00fancia e a primeira sess\u00e3o que a seguir se realizar, que poder\u00e1 ser ordin\u00e1ria, se o referido per\u00edodo coincidir com a data da sua realiza\u00e7\u00e3o, ou extraordin\u00e1ria, caso isso n\u00e3o aconte\u00e7a.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8211; Por for\u00e7a do disposto no artigo 10\u00ba da mesma lei, a mesa \u00e9 eleita de entre os membros da assembleia de freguesia, pelo que a substitui\u00e7\u00e3o do Presidente da mesa da Assembleia enquanto tal, na sequ\u00eancia da sua ren\u00fancia enquanto membro da assembleia, dever\u00e1 seguir a mesma forma da elei\u00e7\u00e3o da mesa anteriormente realizada, isto \u00e9, uninominal, elegendo um novo Presidente da Assembleia, ou por lista, elegendo uma nova mesa.<\/p>\n<p>&nbsp;&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Diretora de Servi\u00e7os de Apoio Jur\u00eddico e \u00e0 Administra\u00e7\u00e3o Local<\/p>\n<p>&nbsp;&nbsp;<\/p>\n<p>(Maria Jos\u00e9 Leal Castanheira Neves)<\/p>\n<\/div>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Em refer\u00eancia ao pedido de parecer solicitado pelo Presidente da Assembleia de Freguesia, por correio eletr\u00f3nico de 7 e 13 de dezembro de 2016, sobre o assunto mencionado em ep\u00edgrafe, julgamos que as quest\u00f5es que em concreto devemos esclarecer, baseados no teor do texto enviado, s\u00e3o as seguintes:<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<ol style=\"text-align: justify;\">\n<li>Poder\u00e1 ocorrer a cessa\u00e7\u00e3o volunt\u00e1ria (erradamente designada pelo Presidente da Assembleia de Freguesia como ren\u00fancia) do exerc\u00edcio de fun\u00e7\u00f5es de Presidente da Mesa, permanecendo o mesmo como membro da mesma Assembleia de Freguesia?<\/li>\n<li>Caso pretenda renunciar ao mandato de membro da Assembleia de Freguesia,<\/li>\n<\/ol>\n<p style=\"text-align: justify;\">para al\u00e9m da cessa\u00e7\u00e3o volunt\u00e1ria como Presidente da Assembleia de Freguesia, como dever\u00e1 proceder?<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">I<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">No que respeita \u00e0 primeira quest\u00e3o, importa referir que os membros da Mesa podem ser destitu\u00eddos a qualquer momento pela maioria do n\u00famero legal dos membros que comp\u00f5em a Assembleia de Freguesia, contrariamente ao mandato dos mesmos enquanto membros da Assembleia.<\/p>\n<p style=\"text-align: justify;\">De facto, contrariamente ao mandato dos membros da Assembleia de Freguesia que \u00e9 de quatro anos, s\u00f3 deixando de ser eleitos se renunciarem, forem objeto da san\u00e7\u00e3o de perda de mandato ou de dissolu\u00e7\u00e3o do \u00f3rg\u00e3o, nestas duas \u00faltimas hip\u00f3teses por senten\u00e7a de tribunal administrativo, a mesa \u00e9 eleita para o per\u00edodo do mandato mas pode ser destitu\u00edda a qualquer momento pela maioria do n\u00famero legal dos membros que comp\u00f5em a assembleia de freguesia (n \u00ba 2 do artigo 10 \u00ba da lei 169\/99, de 18\/09, na reda\u00e7\u00e3o dada pela lei n \u00ba 5-A\/2002, de 11\/01).<\/p>\n<p style=\"text-align: justify;\">Ocorrendo essa destitui\u00e7\u00e3o os membros da mesa destitu\u00eddos das suas fun\u00e7\u00f5es na mesa continuam, obviamente, a ser membros de pleno direito da Assembleia de Freguesia \u2013 apenas deixam de integrar a mesa.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"text-decoration: underline;\">Ora, se os membros da mesa forem destitu\u00eddos continuam a ser membros da Assembleia de Freguesia, n\u00e3o se confundindo esta destitui\u00e7\u00e3o com ren\u00fancia.<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"text-decoration: underline;\">\u00a0<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\">A ren\u00fancia \u00e9 uma das formas de cessa\u00e7\u00e3o do mandato e consubstancia um direito de que gozam todos os eleitos locais, que depende unicamente da manifesta\u00e7\u00e3o da vontade de renunciar, apresentada pelo eleito quer antes quer depois da instala\u00e7\u00e3o dos \u00f3rg\u00e3os respetivos, estando legalmente consagrada no artigo 76 \u00ba da lei n\u00ba 169\/99, na nova reda\u00e7\u00e3o dada pela lei 5-A\/2002, de 11\/01.<\/p>\n<p style=\"text-align: justify;\">A convoca\u00e7\u00e3o do substituto dever\u00e1 ser realizada no per\u00edodo que medeia entre a comunica\u00e7\u00e3o de ren\u00fancia e a primeira reuni\u00e3o que a seguir se realizar, onde o mesmo ser\u00e1 instalado.<\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"text-decoration: underline;\">Isto \u00e9, n\u00e3o est\u00e1 legalmente prevista a ren\u00fancia ao cargo de Presidente da Assembleia de Freguesia, as ren\u00fancias respeitam aos mandatos como eleitos locais, sendo o cargo de presidente da Mesa um cargo para que se \u00e9 eleito por se ter previamente adquirido a qualidade de eleito local.<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Assim, no que respeita \u00e0 possibilidade de o Presidente da mesa, \u00abcessar\u00bb, por op\u00e7\u00e3o pr\u00f3pria, o exerc\u00edcio desse cargo para que foi eleito, n\u00e3o existe enquadramento legal para tal situa\u00e7\u00e3o, como referimos, limitando-se a lei a prever e a regular apenas a hip\u00f3tese de destitui\u00e7\u00e3o por parte da Assembleia de Freguesia.<\/p>\n<p style=\"text-align: justify;\">Ora, sendo um dos deveres dos eleitos locais participar nas reuni\u00f5es dos \u00f3rg\u00e3os para que foram eleitos, acrescentando n\u00f3s, e nos cargos para que foram eleitos, entendemos, salvo melhor opini\u00e3o, que a Assembleia de Freguesia dever\u00e1 negar a possibilidade desta \u00ab<em>ren\u00fancia<\/em>\u00bb volunt\u00e1ria ao cargo de membro da Mesa da Assembleia, considerando que faz parte dos deveres dos eleitos permanecer nos referidos cargos, a menos que renunciem ou se suspendam os pr\u00f3prios mandatos de eleitos locais.<\/p>\n<p style=\"text-align: justify;\">Ou seja, se a Assembleia de Freguesia considerar que n\u00e3o h\u00e1 enquadramento legal para que o Presidente da Assembleia cesse voluntariamente o exerc\u00edcio do cargo de Presidente da mesa deve comunic\u00e1-lo ao pr\u00f3prio, indeferindo a sua comunica\u00e7\u00e3o de \u00ab<em>ren\u00fancia<\/em>\u00bb, que mais n\u00e3o \u00e9 do que uma comunica\u00e7\u00e3o, como j\u00e1 afirm\u00e1mos, de cessa\u00e7\u00e3o volunt\u00e1ria do cargo.<\/p>\n<p style=\"text-align: justify;\">No entanto, tal n\u00e3o impede nem que a Assembleia o destitua nem que o pr\u00f3prio renuncie ao seu pr\u00f3prio mandato de membro da Assembleia.<\/p>\n<p style=\"text-align: justify;\">Se nenhuma das situa\u00e7\u00f5es ocorrer n\u00e3o se ir\u00e1 verificar qualquer altera\u00e7\u00e3o na Assembleia de Freguesia.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">\u00a0 <span style=\"text-decoration: underline;\">Temos, no entanto, presente que esta doutrina n\u00e3o colhe unanimidade, pelo que h\u00e1 quem entenda que o Presidente da Mesa pode cessar voluntariamente o exerc\u00edcio deste cargo, continuando como membro da Assembleia. <\/span><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Competindo-nos dar apoio t\u00e9cnico \u00e0s autarquias locais devemos inform\u00e1-las dos v\u00e1rios entendimentos sobre as mat\u00e9rias em d\u00favida, muito embora manifestemos a nossa posi\u00e7\u00e3o, dado que o apoio que prestamos n\u00e3o s\u00f3 \u00e9 solicitado voluntariamente pelas autarquias como n\u00e3o as vincula nem as poderia vincular, dado o princ\u00edpio da autonomia do poder local.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Assim neste outro entendimento, h\u00e1 possibilidade dos membros da mesa cessarem voluntariamente o exerc\u00edcio dos respetivos cargos, pelo que se tal ocorrer a substitui\u00e7\u00e3o do Presidente da Mesa da Assembleia deve operar-se da mesma forma em que se realizou a sua elei\u00e7\u00e3o para a mesa.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Nestes termos, haver\u00e1 nova elei\u00e7\u00e3o, elei\u00e7\u00e3o realizada por voto secreto pelos membros da Assembleia de Freguesia (vide o artigo 9 \u00ba da Lei n \u00ba 169\/99, de 18\/09, na reda\u00e7\u00e3o dada pela lei n \u00ba 5-A\/2002, de 11 de Janeiro) para eleger um novo Presidente ou uma nova mesa, consoante os termos em que estiver regulamentada a elei\u00e7\u00e3o da mesa no regimento da Assembleia de Freguesia, uninominal ou por listas.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Se estiver estipulada elei\u00e7\u00e3o uninominal eleger-se-\u00e1 apenas o presidente da Mesa mas se a elei\u00e7\u00e3o prevista em regimento for a elei\u00e7\u00e3o por listas ter\u00e3o que ser apresentadas listas para a elei\u00e7\u00e3o da mesa, ou seja, nesse caso ter\u00e1 que ser eleita uma nova mesa.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">N\u00e3o podemos deixar de referir, no entanto, que \u00a0no caso que nos foi apresentado houve uma n\u00edtida confus\u00e3o entre o conceito de ren\u00fancia, inerente ao mandato de eleito local e a cessa\u00e7\u00e3o volunt\u00e1ria do cargo de Presidente da mesa.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Por \u00faltimo refira-se que quer a Assembleia destitua a mesa ( ou qualquer um dos membros da respetiva mesa) ou aceite\u00a0 a\u00a0 cessa\u00e7\u00e3o volunt\u00e1ria do cargo de presidente da Assembleia, haver\u00e1\u00a0 nova elei\u00e7\u00e3o, elei\u00e7\u00e3o realizada por voto secreto pelos membros da assembleia de freguesia ( vide o artigo 9 \u00ba da Lei n \u00ba 169\/99, de 18\/09, na reda\u00e7\u00e3o dada pela lei n \u00ba 5-A\/2002, de 11 de Janeiro) para eleger uma nova mesa ou um novo Presidente, nos termos por n\u00f3s supra referidos.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">II<\/p>\n<p style=\"text-align: justify;\"><span style=\"text-decoration: underline;\">Se, porventura, o atual Presidente da Assembleia de Freguesia pretender renunciar tamb\u00e9m ao seu mandato como membro da assembleia de Freguesia, para al\u00e9m de querer cessar fun\u00e7\u00f5es como Presidente da mesa, o enquadramento legal da situa\u00e7\u00e3o em causa ser\u00e1 o seguinte<\/span>:<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">A ren\u00fancia, com referimos, est\u00e1 consagrada no artigo 76\u00ba da Lei n\u00ba 169\/99, de 18 de setembro, com as altera\u00e7\u00f5es introduzidas pelo Lei n\u00ba 5-A\/2002, de 11 de janeiro, \u00e9 uma das formas de cessa\u00e7\u00e3o do mandato e consubstancia um direito de que gozam todos os eleitos locais, que depende unicamente da manifesta\u00e7\u00e3o da vontade de renunciar, apresentada pelo eleito quer antes, quer depois da instala\u00e7\u00e3o dos \u00f3rg\u00e3os respetivos,<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Esta manifesta\u00e7\u00e3o de vontade \u00e9 apresentada por escrito e dirigida a quem deve proceder \u00e0 instala\u00e7\u00e3o ou ao presidente do \u00f3rg\u00e3o, consoante o caso, que deve convocar o membro substituto, no per\u00edodo que medeia entre a comunica\u00e7\u00e3o da ren\u00fancia e a primeira reuni\u00e3o que a seguir se realizar, salvo se a entrega do documento de ren\u00fancia coincidir com o ato de instala\u00e7\u00e3o ou reuni\u00e3o do \u00f3rg\u00e3o e estiver presente o respetivo substituto, situa\u00e7\u00e3o em que, ap\u00f3s a verifica\u00e7\u00e3o da sua identidade e legitimidade, a substitui\u00e7\u00e3o se opera de imediato, se o substituto a n\u00e3o recusar por escrito de acordo com o direito que ele pr\u00f3prio tem a renunciar.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">A sua substitui\u00e7\u00e3o far-se-\u00e1 nos termos previstos no artigo 79\u00ba do mesmo diploma, ou seja, <em>\u201cpelo cidad\u00e3o imediatamente a seguir na ordem da respetiva lista ou, tratando-se de coliga\u00e7\u00e3o, pelo cidad\u00e3o imediatamente a seguir do partido pelo qual havia sido proposto o membro que deu origem \u00e0 vaga<\/em>\u201d.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">No presente caso, exercendo o eleito renunciante tamb\u00e9m as fun\u00e7\u00f5es de Presidente da mesa da Assembleia de Freguesia, a forma da sua substitui\u00e7\u00e3o enquanto tal \u00e9 a que aludimos <em>supra<\/em>, ou seja, dever-se-\u00e1\u00a0 preencher proceder \u00e0 elei\u00e7\u00e3o do novo Presidente, caso a anterior elei\u00e7\u00e3o tenha sido uninominal, ou de uma nova mesa, caso tenha sido por lista.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Note-se, por\u00e9m, que enquanto n\u00e3o for feita a referida elei\u00e7\u00e3o, cabe ao 1 \u00ba secret\u00e1rio, nos termos previsto no n\u00ba 3 do citado artigo 10\u00ba, substituir o Presidente nas suas faltas.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Conclus\u00f5es,<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<ol style=\"text-align: justify;\">\n<li>No caso da Assembleia de Freguesia aceitar a cessa\u00e7\u00e3o volunt\u00e1ria do cargo de presidente da Assembleia, haver\u00e1 nova elei\u00e7\u00e3o, elei\u00e7\u00e3o realizada por voto secreto pelos membros da assembleia de freguesia ( <em>vide <\/em>o artigo 9 \u00ba da Lei n \u00ba 169\/99, de 18\/09, na reda\u00e7\u00e3o dada pela lei n \u00ba 5-A\/2002, de 11 de Janeiro) para eleger\u00a0 um novo Presidente ou uma nova mesa, consoante os termos em que estiver regulamentada a elei\u00e7\u00e3o da mesa no regimento da Assembleia de Freguesia, uninominal ou por listas.<\/li>\n<\/ol>\n<p style=\"text-align: justify;\">\u00a0\u00a0<\/p>\n<ol style=\"text-align: justify;\" start=\"2\">\n<li>No caso do atual Presidente da Assembleia de freguesia renunciar ao mandato de eleito local:<\/li>\n<\/ol>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">&#8211; Por for\u00e7a da conjuga\u00e7\u00e3o normativa do n\u00ba 4 do artigo 76\u00ba e do n\u00ba 1 do artigo 79\u00ba da Lei n\u00ba 169\/99, dever-se-\u00e1 primeiramente substituir o Presidente da Assembleia enquanto membro da Assembleia de Freguesia, convocando o cidad\u00e3o imediatamente a seguir na ordem da respetiva lista, o que ter\u00e1 lugar no per\u00edodo que medeia entre a comunica\u00e7\u00e3o da ren\u00fancia e a primeira sess\u00e3o que a seguir se realizar, que poder\u00e1 ser ordin\u00e1ria, se o referido per\u00edodo coincidir com a data da sua realiza\u00e7\u00e3o, ou extraordin\u00e1ria, caso isso n\u00e3o aconte\u00e7a.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">&#8211; Por for\u00e7a do disposto no artigo 10\u00ba da mesma lei, a mesa \u00e9 eleita de entre os membros da assembleia de freguesia, pelo que a substitui\u00e7\u00e3o do Presidente da mesa da Assembleia enquanto tal, na sequ\u00eancia da sua ren\u00fancia enquanto membro da assembleia, dever\u00e1 seguir a mesma forma da elei\u00e7\u00e3o da mesa anteriormente realizada, isto \u00e9, uninominal, elegendo um novo Presidente da Assembleia, ou por lista, elegendo uma nova mesa.<\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Diretora de Servi\u00e7os de Apoio Jur\u00eddico e \u00e0 Administra\u00e7\u00e3o Local<\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0<\/p>\n<p style=\"text-align: justify;\">(Maria Jos\u00e9 Leal Castanheira Neves)<\/p>","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_eb_attr":"","inline_featured_image":false,"iawp_total_views":69,"footnotes":""},"categories":[357],"tags":[187],"class_list":["post-34226","post","type-post","status-publish","format-standard","hentry","category-pareceres-ate-2017","tag-text-layout"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/posts\/34226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/comments?post=34226"}],"version-history":[{"count":3,"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/posts\/34226\/revisions"}],"predecessor-version":[{"id":40868,"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/posts\/34226\/revisions\/40868"}],"wp:attachment":[{"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/media?parent=34226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/categories?post=34226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/tags?post=34226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}