{"id":33242,"date":"2001-04-09T17:05:57","date_gmt":"2001-04-09T17:05:57","guid":{"rendered":""},"modified":"2023-11-15T13:45:06","modified_gmt":"2023-11-15T13:45:06","slug":"33242","status":"publish","type":"post","link":"https:\/\/www.ccdrc.pt\/en\/33242\/","title":{"rendered":"Venda ambulante"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1288px;margin-left: calc(-0% \/ 2 );margin-right: calc(-0% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:0%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:0%;--awb-width-medium:100%;--awb-spacing-right-medium:0%;--awb-spacing-left-medium:0%;--awb-width-small:100%;--awb-spacing-right-small:0%;--awb-spacing-left-small:0%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><div class=\"searchbox\">\n<div class=\"value\">Data:&nbsp;&nbsp;<strong>segunda, 09 abril 2001<\/strong><\/div>\n<div class=\"value\">N\u00famero:&nbsp;<strong>104\/01<\/strong><\/div>\n<div class=\"value\">Respons\u00e1veis:&nbsp;&nbsp;<strong>MMTB<\/strong><\/div>\n<\/div>\n<div class=\"article_content\">\n<div class=\"fulltext\">\n<p>Em resposta ao solicitado por V. Ex\u00aa ao abrigo do of\u00edcio n\u00ba 1035, de 8\/2\/2001, e reportando-nos ao assunto identificado em ep\u00edgrafe temos a informar o seguinte:<\/p>\n<p>Tendo essa c\u00e2mara municipal algumas d\u00favidas sobre o procedimento a adoptar no caso de vendedores ambulantes que possuem mais de uma viatura para venda dos seus produtos (a qual, nestes casos, \u00e9 assegurada por funcion\u00e1rios ao seu servi\u00e7o) pergunta se deve emitir um cart\u00e3o \u00fanico para o empres\u00e1rio ou um cart\u00e3o por viatura? Questiona-se ainda qual o procedimento no caso de viaturas de venda de p\u00e3o? Disp\u00f5e o n\u00ba 1 do artigo 2\u00ba do D.L. 122\/79 de 8 de Maio e o n\u00ba 1 do artigo 4\u00ba do Regulamento Municipal que o exerc\u00edcio da venda ambulante \u00e9 vedado \u00e0s sociedades, aos mandat\u00e1rios e aos que exer\u00e7am outra actividade profissional, n\u00e3o podendo ainda ser praticado por interposta pessoa. Por outro lado o n\u00ba 1 do artigo 19\u00ba do mesmo D.L. determina que o cart\u00e3o de vendedor ambulante \u00e9 pessoal e intransmiss\u00edvel. Das disposi\u00e7\u00f5es transcritas pode concluir-se que actividade de venda ambulante tem que ser exercida pelo pr\u00f3prio, n\u00e3o podendo ser praticada por mandat\u00e1rio ou por interposta pessoa como ser\u00e1 o caso da venda ser efectuada por pessoas em nome do titular do cart\u00e3o de vendedor ambulante ou por seus funcion\u00e1rios.<\/p>\n<p>Conclui-se tamb\u00e9m que sendo o exerc\u00edcio dessa actividade titulada por um cart\u00e3o, que nos termos do artigo 19\u00ba n\u00ba 1 do D.L. 122\/79 \u00e9 pessoal e intransmiss\u00edvel, os cart\u00f5es ter\u00e3o que ser emitidos em nome do vendedor e n\u00e3o por refer\u00eancia \u00e0s viaturas. Quanto \u00e0 venda de p\u00e3o, esta poder\u00e1 enquadrar-se na excep\u00e7\u00e3o prevista no n\u00ba 2 do artigo 2\u00ba do mesmo D.L. que exceptua do \u00e2mbito de aplica\u00e7\u00e3o do diploma a distribui\u00e7\u00e3o domicili\u00e1ria efectuada por conta de comerciantes com estabelecimentos fixo. Assim a mera distribui\u00e7\u00e3o de p\u00e3o por funcion\u00e1rios de uma padaria n\u00e3o se encontra abrangido pelas disposi\u00e7\u00f5es relativas \u00e0 venda ambulante.<\/p>\n<p>A Chefe de Divis\u00e3o de Apoio Jur\u00eddico (Dra. Maria Margarida Teixeira Bento)<\/p>\n<\/div>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Em resposta ao solicitado por V. Ex\u00aa ao abrigo do of\u00edcio n\u00ba 1035, de 8\/2\/2001, e reportando-nos ao assunto identificado em ep\u00edgrafe temos a informar o seguinte: <\/p>","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_eb_attr":"","inline_featured_image":false,"iawp_total_views":39,"footnotes":""},"categories":[357],"tags":[187],"class_list":["post-33242","post","type-post","status-publish","format-standard","hentry","category-pareceres-ate-2017","tag-text-layout"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/posts\/33242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/comments?post=33242"}],"version-history":[{"count":2,"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/posts\/33242\/revisions"}],"predecessor-version":[{"id":42492,"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/posts\/33242\/revisions\/42492"}],"wp:attachment":[{"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/media?parent=33242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/categories?post=33242"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/tags?post=33242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}