{"id":20298,"date":"2023-04-12T13:02:39","date_gmt":"2023-04-12T13:02:39","guid":{"rendered":"http:\/\/www.ccdrc.pt\/regiao-centro-acolhe-evento-nacional-da-missao-solo\/"},"modified":"2023-12-11T15:35:47","modified_gmt":"2023-12-11T15:35:47","slug":"regiao-centro-acolhe-evento-nacional-da-missao-solo","status":"publish","type":"post","link":"https:\/\/www.ccdrc.pt\/en\/regiao-centro-acolhe-evento-nacional-da-missao-solo\/","title":{"rendered":"Regi\u00e3o Centro acolhe Evento Nacional da Miss\u00e3o Solo"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1288px;margin-left: calc(-0% \/ 2 );margin-right: calc(-0% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:0%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:0%;--awb-width-medium:100%;--awb-spacing-right-medium:0%;--awb-spacing-left-medium:0%;--awb-width-small:100%;--awb-spacing-right-small:0%;--awb-spacing-left-small:0%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p><img decoding=\"async\" class=\"size-full wp-image-20297\" style=\"display: block;margin-left: auto;margin-right: auto\" src=\"http:\/\/www.ccdrc.pt\/wp-content\/uploads\/2023\/04\/NOT_12_04_DENTRO-3c3.jpg\" alt=\"\" width=\"650\" height=\"365\" srcset=\"https:\/\/www.ccdrc.pt\/wp-content\/uploads\/2023\/04\/NOT_12_04_DENTRO-3c3-200x112.jpg 200w, https:\/\/www.ccdrc.pt\/wp-content\/uploads\/2023\/04\/NOT_12_04_DENTRO-3c3-400x225.jpg 400w, https:\/\/www.ccdrc.pt\/wp-content\/uploads\/2023\/04\/NOT_12_04_DENTRO-3c3-500x281.jpg 500w, https:\/\/www.ccdrc.pt\/wp-content\/uploads\/2023\/04\/NOT_12_04_DENTRO-3c3-600x337.jpg 600w, https:\/\/www.ccdrc.pt\/wp-content\/uploads\/2023\/04\/NOT_12_04_DENTRO-3c3.jpg 650w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/p>\n<p>A Comiss\u00e3o de Coordena\u00e7\u00e3o e Desenvolvimento Regional do Centro, a Ag\u00eancia Nacional de Inova\u00e7\u00e3o e a Dire\u00e7\u00e3o-Geral de Agricultura e Desenvolvimento Rural, com o enquadramento do projeto <span style=\"color: #0000ff\"><a style=\"color: #0000ff\" href=\"https:\/\/nati00ns.eu\/events\/living-labs-missao-solo-horizonte-europa-portugal\" target=\"_blank\" rel=\"alternate noopener\">NATI00NS<\/a><\/span>\u200b, organizam o evento nacional sobre a implementa\u00e7\u00e3o em Portugal dos Laborat\u00f3rios Vivos da Miss\u00e3o Solo, ao abrigo do programa Horizonte Europa.<\/p>\n<p>Este evento pretende dar a conhecer a Miss\u00e3o Solos e os objetivos relativos \u00e0 constitui\u00e7\u00e3o de Laborat\u00f3rios Vivos; esclarecer o conceito e crit\u00e9rios necess\u00e1rios, para o financiamento ao abrigo do programa Horizonte Europa, a que devem obedecer os Laborat\u00f3rios Vivos, tanto a n\u00edvel regional, como enquanto clusters a n\u00edvel europeu; e discutir diferentes Laborat\u00f3rios Vivos que seria desej\u00e1vel e poss\u00edvel instalar a n\u00edvel nacional.<\/p>\n<p>\u00c9 importante referir que as Miss\u00f5es Europeias s\u00e3o uma novidade do Programa para a investiga\u00e7\u00e3o e inova\u00e7\u00e3o Horizonte Europa, a decorrer de 2021 a 2027. O objetivo da Miss\u00e3o Solos \u00e9 ser um precursor, demonstrador e catalisador da transi\u00e7\u00e3o para solos saud\u00e1veis em 2030, por meio de a\u00e7\u00f5es ambiciosas em 100 laborat\u00f3rios vivos. O financiamento que ser\u00e1 disponibilizado para a implementa\u00e7\u00e3o da Miss\u00e3o Solos ser\u00e1 uma grande oportunidade para as entidades portuguesas comprometidas com a sa\u00fade do solo.<\/p>\n<p>Saiba mais em:<br \/>\n<span style=\"color: #0000ff\"><a style=\"color: #0000ff\" href=\"https:\/\/nati00ns.eu\/events\/living-labs-missao-solo-horizonte-europa-portugal\" target=\"_blank\" rel=\"alternate noopener\">https:\/\/nati00ns.eu\/events\/living-labs-missao-solo-horizonte-europa-portugal<\/a><\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":44537,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_eb_attr":"","inline_featured_image":false,"iawp_total_views":1,"footnotes":""},"categories":[307],"tags":[],"class_list":["post-20298","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informacao"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/posts\/20298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/comments?post=20298"}],"version-history":[{"count":2,"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/posts\/20298\/revisions"}],"predecessor-version":[{"id":44536,"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/posts\/20298\/revisions\/44536"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/media\/44537"}],"wp:attachment":[{"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/media?parent=20298"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/categories?post=20298"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ccdrc.pt\/en\/wp-json\/wp\/v2\/tags?post=20298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}